{"id":371,"count":2,"description":"","link":"https:\/\/blogs.correiobraziliense.com.br\/coletivo-filhas-da-mae\/tag\/pesquisa-estudo-sobre-pessoas-idosas-com-demencias-e-cuidadores-no-distrito-federal\/","name":"Pesquisa \"Estudo Sobre Pessoas Idosas com Dem\u00eancias e Cuidadores no Distrito Federal\"","slug":"pesquisa-estudo-sobre-pessoas-idosas-com-demencias-e-cuidadores-no-distrito-federal","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/coletivo-filhas-da-mae\/wp-json\/wp\/v2\/tags\/371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/coletivo-filhas-da-mae\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/coletivo-filhas-da-mae\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/coletivo-filhas-da-mae\/wp-json\/wp\/v2\/posts?tags=371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}