{"id":1533,"count":1,"description":"","link":"https:\/\/blogs.correiobraziliense.com.br\/coletivo-filhas-da-mae\/tag\/ilary-lourenco\/","name":"\u00cdlary Louren\u00e7o","slug":"ilary-lourenco","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/coletivo-filhas-da-mae\/wp-json\/wp\/v2\/tags\/1533","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/coletivo-filhas-da-mae\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/coletivo-filhas-da-mae\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/coletivo-filhas-da-mae\/wp-json\/wp\/v2\/posts?tags=1533"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}