{"id":1111,"count":1,"description":"","link":"https:\/\/blogs.correiobraziliense.com.br\/coletivo-filhas-da-mae\/tag\/palmeiras\/","name":"Palmeiras","slug":"palmeiras","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/coletivo-filhas-da-mae\/wp-json\/wp\/v2\/tags\/1111","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/coletivo-filhas-da-mae\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/coletivo-filhas-da-mae\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/coletivo-filhas-da-mae\/wp-json\/wp\/v2\/posts?tags=1111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}