{"id":2444,"count":1,"description":"","link":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/tag\/contas-de-2019\/","name":"Contas de 2019","slug":"contas-de-2019","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/tags\/2444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts?tags=2444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}