{"id":2291,"count":5,"description":"","link":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/tag\/mascara\/","name":"M\u00e1scara","slug":"mascara","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/tags\/2291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts?tags=2291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}