{"id":9165,"date":"2017-08-10T17:18:55","date_gmt":"2017-08-10T20:18:55","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/?p=9165"},"modified":"2017-08-10T17:21:19","modified_gmt":"2017-08-10T20:21:19","slug":"camara-gasta-37-mil-para-distritais-participarem-de-eventos","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/camara-gasta-37-mil-para-distritais-participarem-de-eventos\/","title":{"rendered":"C\u00e2mara gasta R$ 37 mil para distritais participarem de eventos em Boston e Nova Iorque"},"content":{"rendered":"<p><strong>Ana Viriato<\/strong><\/p>\n<p>A C\u00e2mara Legislativa gastou R$ 37.219,96, em passagens a\u00e9reas e hospedagens, para garantir a participa\u00e7\u00e3o dos distritais Rodrigo Delmasso (Podemos) e Wasny de Roure (PT) no encontro anual da National Conference of State Legislatures (NCLS), em Boston (EUA). Houve, ainda, custos com as taxas de inscri\u00e7\u00e3o \u2014 a Casa n\u00e3o informou o valor gasto com esse item, mas, conforme o site do evento, as tarifas variam entre R$ 236,70 e R$ 4.339,48. Os parlamentares viajaram na \u00faltima sexta-feira e desembarcar\u00e3o na capital neste s\u00e1bado.<\/p>\n<p>&nbsp;<\/p>\n<p>Os voos em classe econ\u00f4mica, pela American Airlines, custaram, ao todo, R$ 16.870,96. J\u00e1 as despesas com as di\u00e1rias \u2014 sete para cada \u2014 atingiram a cifra de R$ 20.349. Os dois parlamentares viajaram a convite da Uni\u00e3o Nacional dos Legisladores e Legislativos Estaduais (UNALE). Rodrigo Delmasso \u00e9 vice-presidente da entidade e Wasny, um dos integrantes do Conselho Fiscal.<\/p>\n<p>&nbsp;<\/p>\n<p>Iniciado no \u00faltimo domingo e finalizado ontem, o evento reuniu participantes de pa\u00edses de todo o mundo para fomentar a troca de experi\u00eancias e a discuss\u00e3o de assuntos referentes \u00e0 vida parlamentar, economia, sustentabilidade e a projetos sociais. De Boston, os parlamentares seguiram para Nova Iorque, onde embarcar\u00e3o no voo que far\u00e1 uma escala em Guarulhos (SP) e, finalmente, chegar\u00e1 a Bras\u00edlia. O ato da Mesa Diretora que autorizou a viagem oficial foi publicado em 12 de julho de 2017.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Bagagem<\/strong><\/p>\n<p>Em nota, a assessoria de comunica\u00e7\u00e3o de Wasny de Roure afirmou que, na viagem, Wasny participa de uma troca de \u201cinforma\u00e7\u00f5es e conhecimentos sobre as experi\u00eancias vividas por cada Unidade Federativa dos pa\u00edses a fim de aprimorar a cria\u00e7\u00e3o de leis e fiscaliza\u00e7\u00e3o da aplica\u00e7\u00e3o delas\u201d. O texto ainda classifica o evento como \u201cuma oportunidade \u00fanica\u201d, que incrementa a bagagem dos parlamentares.<\/p>\n<p>&nbsp;<\/p>\n<p>A assessoria de Rodrigo Delmasso garantiu que o parlamentar esteve engajado em conversas sobre o programa Stem Education. \u201cEle obteve detalhes sobre esse sistema, cujo enfoque pesa sobre o ensino de ci\u00eancias, tecnologia, engenharia e matem\u00e1tica, para analisar a possibilidade de aplica\u00e7\u00e3o no DF. Tamb\u00e9m discutiu sobre os cen\u00e1rios que viabilizam a venda de Cannabidiol\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ana Viriato A C\u00e2mara Legislativa gastou R$ 37.219,96, em passagens a\u00e9reas e hospedagens, para garantir a participa\u00e7\u00e3o dos distritais Rodrigo Delmasso (Podemos) e Wasny de Roure (PT) no encontro anual da National Conference of State Legislatures (NCLS), em Boston (EUA). Houve, ainda, custos com as taxas de inscri\u00e7\u00e3o \u2014 a Casa n\u00e3o informou o valor gasto com esse item, mas, [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":9166,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[234],"tags":[],"class_list":["post-9165","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cb-poder"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/9165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/comments?post=9165"}],"version-history":[{"count":2,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/9165\/revisions"}],"predecessor-version":[{"id":9168,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/9165\/revisions\/9168"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media\/9166"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media?parent=9165"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/categories?post=9165"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/tags?post=9165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}