{"id":28750,"date":"2026-04-30T13:11:16","date_gmt":"2026-04-30T16:11:16","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/?p=28750"},"modified":"2026-04-30T13:11:16","modified_gmt":"2026-04-30T16:11:16","slug":"tramitacao-do-projeto-que-autorizou-compra-do-master-pelo-brb-entra-no-foco-da-compliance-zero","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/tramitacao-do-projeto-que-autorizou-compra-do-master-pelo-brb-entra-no-foco-da-compliance-zero\/","title":{"rendered":"Tramita\u00e7\u00e3o do projeto que autorizou compra do Master pelo BRB entra no foco da Compliance Zero"},"content":{"rendered":"<h4>ANA MARIA CAMPOS\/EIXO CAPITAL<\/h4>\n<p class=\"p1\"><span class=\"s1\">Como tudo que envolve o Master est\u00e1 atrelado a cifras bilion\u00e1rias, frentes da Opera\u00e7\u00e3o Compliance Zero apuram como\u00a0<\/span>se deu a opera\u00e7\u00e3o pol\u00edtica na C\u00e2mara Legislativa (CLDF) para aprova\u00e7\u00e3o, a toque de caixa, do projeto de lei que autorizou\u00a0<span class=\"s1\">a compra de 58% do banco de Daniel Vorcaro pelo BRB.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\"><span class=\"s1\">A proposta chegou \u00e0 Casa em 14 de agosto do ano passado, para vota\u00e7\u00e3o em regime de urg\u00eancia, e foi aprovada cinco dias depois, com 14 votos favor\u00e1veis e sete contr\u00e1rios. O ent\u00e3o presidente do BRB, Paulo Henrique Costa, acompanhou a tramita\u00e7\u00e3o e se reuniu com os deputados distritais para defender o neg\u00f3cio que, hoje sabe-se, provocaria um preju\u00edzo monumental.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\"><span class=\"s1\">O BRB j\u00e1 havia comprado fundos sem lastro do Master e destinado R$ 21,9 bilh\u00f5es nessas transa\u00e7\u00f5es. Hoje, o Distrito Federal, acionista majorit\u00e1rio do BRB, negocia um empr\u00e9stimo de R$ 6,6 bilh\u00f5es junto ao Fundo Garantidor de Cr\u00e9dito para recuperar a institui\u00e7\u00e3o financeira do DF.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\"><strong><span class=\"s1\">Estrat\u00e9gia de convencimento na dela\u00e7\u00e3o<\/span><\/strong><\/p>\n<p class=\"p1\"><span class=\"s1\">Enquanto tentava convencer deputados distritais, Paulo Henrique Costa negociava com Daniel Vorcaro \u2014 segundo relatou o ministro Andr\u00e9 Mendon\u00e7a, do Supremo Tribunal Federal (STF), na decreta\u00e7\u00e3o da pris\u00e3o do ex-presidente do BRB \u2014 propina\u00a0<\/span>em im\u00f3veis de luxo, localizados em S\u00e3o Paulo e em Bras\u00edlia, no valor de R$ 146 milh\u00f5es.<\/p>\n<p class=\"p1\"><span class=\"s1\"><br \/>\nPara conquistar o apoio da C\u00e2mara Legislativa, Paulo Henrique garantiu que a opera\u00e7\u00e3o seria positiva para a popula\u00e7\u00e3o do DF. \u201cExiste uma expectativa de crescimento do resultado de dividendos, que ser\u00e1 revertido em pol\u00edticas p\u00fablicas. Outro benef\u00edcio \u00e9 que o BRB passa a ter mais produtos, a atuar em outros segmentos, que ficam \u00e0 disposi\u00e7\u00e3o das pessoas que moram no DF. Al\u00e9m disso, o fortalecimento do BRB vai, naturalmente, gerar emprego e renda\u201d, afirmou Paulo Henrique Costa.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\"><span class=\"s1\">A negocia\u00e7\u00e3o poder\u00e1 ser esclarecida na<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">dela\u00e7\u00e3o premiada do ex-presidente.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ANA MARIA CAMPOS\/EIXO CAPITAL Como tudo que envolve o Master est\u00e1 atrelado a cifras bilion\u00e1rias, frentes da Opera\u00e7\u00e3o Compliance Zero apuram como\u00a0se deu a opera\u00e7\u00e3o pol\u00edtica na C\u00e2mara Legislativa (CLDF) para aprova\u00e7\u00e3o, a toque de caixa, do projeto de lei que autorizou\u00a0a compra de 58% do banco de Daniel Vorcaro pelo BRB. &nbsp; A proposta chegou \u00e0 Casa em 14 [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":28751,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[234],"tags":[286,70,639,1254,4079,3817,348],"class_list":["post-28750","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cb-poder","tag-brb","tag-camara-legislativa","tag-delacao-premiada","tag-deputados-distritais","tag-master","tag-paulo-henrique-costa","tag-projeto-de-lei"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/28750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/comments?post=28750"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/28750\/revisions"}],"predecessor-version":[{"id":28752,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/28750\/revisions\/28752"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media\/28751"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media?parent=28750"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/categories?post=28750"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/tags?post=28750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}