{"id":28257,"date":"2026-02-17T12:46:14","date_gmt":"2026-02-17T15:46:14","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/?p=28257"},"modified":"2026-02-17T12:46:14","modified_gmt":"2026-02-17T15:46:14","slug":"ventoinha-de-canudo-ocupa-a-tesourinha-da-207-norte","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/ventoinha-de-canudo-ocupa-a-tesourinha-da-207-norte\/","title":{"rendered":"Ventoinha de Canudo ocupa a tesourinha da 207 Norte"},"content":{"rendered":"<p><em><strong>Coluna Eixo Capital, publicada em 17 de fevereiro de 2026, por Ana Dubeux<\/strong><\/em><\/p>\n<p>O sopro encantador do bloco Ventoinha de Canudo arrastar\u00e1 uma legi\u00e3o de brasilienses, hoje, a partir das 16h20, no gramad\u00e3o da 207 Norte, para a ocupa\u00e7\u00e3o festiva e pac\u00edfica da tesourinha. \u00c9 um dos blocos mais singularmente candangos.<\/p>\n<p>N\u00e3o precisa de trio el\u00e9trico nem de 120 decib\u00e9is para arrebatar. Somente com o sopro das flautas e a marca\u00e7\u00e3o dos tambores, o Ventoinha de Canudo puxa o bloco da inclus\u00e3o, dos adolescentes, dos adultos, dos filhos e dos netos dos adultos. \u00c9 para brincantes de todas as idades. E, neste ano, o grupo ter\u00e1 a participa\u00e7\u00e3o luxuosa do Maracatu Boiadeiro Brilhante, que refor\u00e7ar\u00e1 a percuss\u00e3o dos tambores.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Coluna Eixo Capital, publicada em 17 de fevereiro de 2026, por Ana Dubeux O sopro encantador do bloco Ventoinha de Canudo arrastar\u00e1 uma legi\u00e3o de brasilienses, hoje, a partir das 16h20, no gramad\u00e3o da 207 Norte, para a ocupa\u00e7\u00e3o festiva e pac\u00edfica da tesourinha. \u00c9 um dos blocos mais singularmente candangos. N\u00e3o precisa de trio el\u00e9trico nem de 120 decib\u00e9is [&hellip;]<\/p>\n","protected":false},"author":164,"featured_media":28258,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2089],"tags":[],"class_list":["post-28257","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eixo-capital"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/28257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/users\/164"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/comments?post=28257"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/28257\/revisions"}],"predecessor-version":[{"id":28259,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/28257\/revisions\/28259"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media\/28258"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media?parent=28257"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/categories?post=28257"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/tags?post=28257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}