{"id":27005,"date":"2025-07-29T17:01:27","date_gmt":"2025-07-29T20:01:27","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/?p=27005"},"modified":"2025-07-29T17:10:06","modified_gmt":"2025-07-29T20:10:06","slug":"candidatura-do-pt-ao-buriti-pode-ser-definida-em-previas","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/candidatura-do-pt-ao-buriti-pode-ser-definida-em-previas\/","title":{"rendered":"Candidatura do PT ao Buriti pode ser definida em pr\u00e9vias"},"content":{"rendered":"<h4>ANA MARIA CAMPOS<\/h4>\n<p>O PT-DF saiu h\u00e1 pouco de uma disputa pela presid\u00eancia regional e agora pode entrar em outra: a defini\u00e7\u00e3o do candidato ou candidata ao Pal\u00e1cio do Buriti. O diret\u00f3rio regional do PT ainda vai tomar uma decis\u00e3o sobre ter ou n\u00e3o pr\u00e9vias. Mas j\u00e1 h\u00e1 embate interno.<\/p>\n<p>&nbsp;<\/p>\n<p>O presidente do Iphan, Leandro Grass, que concorreu ao governo do DF na \u00faltima elei\u00e7\u00e3o, anunciou na semana passada que est\u00e1 trocando o PV pelo PT. A filia\u00e7\u00e3o oficial est\u00e1 marcada para 20 de agosto. O movimento sinaliza a inten\u00e7\u00e3o de se candidatar ao GDF.<\/p>\n<p>&nbsp;<\/p>\n<p>Mas Leandro Grass tem advers\u00e1rio interno, o ex-deputado Geraldo Magela. \u201cFui o primeiro a defender candidatura do PT e quero concorrer\u201d, afirma o petista.<\/p>\n<p>&nbsp;<\/p>\n<p>O presidente do PT-DF, Jacy Afonso, afirma que o diret\u00f3rio regional s\u00f3 vai come\u00e7ar as discuss\u00f5es sobre 2026 no encontro do partido marcado para ocorrer em 22,23 e 24 de agosto. No \u00faltimo dia, o presidente eleito, Guilherme Sigmaringa Seixas, tomar\u00e1 posse.<\/p>\n<p>&nbsp;<\/p>\n<p>A decis\u00e3o sobre pr\u00e9vias caber\u00e1 ao diret\u00f3rio. Para evitar a disputa, dois ter\u00e7os do diret\u00f3rio devem ser optar por outra forma de escolha da candidatura.<\/p>\n<p>&nbsp;<\/p>\n<p>O deputado Chico Vigilante (PT) afirma que, al\u00e9m de Leandro Grass e Magela, o partido tem outros nomes, como a ex-reitora da UnB M\u00e1rcia Abrah\u00e3o. \u201cO diret\u00f3rio vai decidir se teremos ou n\u00e3o pr\u00e9vias\u201d, explica Vigilante.<\/p>\n<p>&nbsp;<\/p>\n<p>Para o vice-presidente da C\u00e2mara, Ricardo Vale (PT), as pr\u00e9vias S\u00e3o leg\u00edtimas e devem ocorrer. \u201c\u00c9 estatut\u00e1rio e leg\u00edtimo. Acredito que a maioria do diret\u00f3rio vai aprovar as pr\u00e9vias\u201d, avalia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ANA MARIA CAMPOS O PT-DF saiu h\u00e1 pouco de uma disputa pela presid\u00eancia regional e agora pode entrar em outra: a defini\u00e7\u00e3o do candidato ou candidata ao Pal\u00e1cio do Buriti. O diret\u00f3rio regional do PT ainda vai tomar uma decis\u00e3o sobre ter ou n\u00e3o pr\u00e9vias. Mas j\u00e1 h\u00e1 embate interno. &nbsp; O presidente do Iphan, Leandro Grass, que concorreu ao [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":25758,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[234],"tags":[192,807,620,3806,3916,1557,495,290,363],"class_list":["post-27005","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cb-poder","tag-chico-vigilante","tag-eleicoes-2018","tag-geraldo-magela","tag-guilherme-sigmaringa","tag-jacy-afonso","tag-leandro-grass","tag-previas","tag-pt","tag-ricardo-vale"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/27005","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/comments?post=27005"}],"version-history":[{"count":2,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/27005\/revisions"}],"predecessor-version":[{"id":27007,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/27005\/revisions\/27007"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media\/25758"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media?parent=27005"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/categories?post=27005"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/tags?post=27005"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}