{"id":26974,"date":"2025-07-16T10:28:59","date_gmt":"2025-07-16T13:28:59","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/?p=26974"},"modified":"2025-07-16T10:28:59","modified_gmt":"2025-07-16T13:28:59","slug":"integracao-do-transporte-entre-o-df-e-o-entorno","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/integracao-do-transporte-entre-o-df-e-o-entorno\/","title":{"rendered":"Integra\u00e7\u00e3o do transporte entre o DF e o Entorno"},"content":{"rendered":"<h3>Por Arthur de Souza (interino)<\/h3>\n<p>Em reuni\u00e3o realizada ontem, na Secretaria de Transporte e Mobilidade do Distrito Federal (Semob-DF), representantes dos governos do Distrito Federal e de Goi\u00e1s, al\u00e9m da prefeitura de \u00c1guas Lindas (GO), decidiram que a cidade goiana desenvolver\u00e1 o projeto-piloto para a implanta\u00e7\u00e3o da integra\u00e7\u00e3o do transporte p\u00fablico na Regi\u00e3o Metropolitana do Entorno. A iniciativa servir\u00e1 de base para o futuro cons\u00f3rcio interfederativo com o DF.<\/p>\n<p>A proposta prev\u00ea a cria\u00e7\u00e3o de um terminal de integra\u00e7\u00e3o na entrada de \u00c1guas Lindas, que permitir\u00e1 ganho de efici\u00eancia no deslocamento at\u00e9 o DF, al\u00e9m da redu\u00e7\u00e3o da tarifa para o usu\u00e1rio. O modelo servir\u00e1 de base para futuras amplia\u00e7\u00f5es da integra\u00e7\u00e3o na regi\u00e3o. &#8220;Faremos um grupo pequeno de governan\u00e7a entre os tr\u00eas entes para viabilizar tudo isso em no m\u00e1ximo 90 dias&#8221;, disse \u00e0 coluna o prefeito de \u00c1guas Lindas, Dr. Lucas (Uni\u00e3o Brasil), que tamb\u00e9m participou do encontro.<\/p>\n<p><strong>Sistema unificado<\/strong><\/p>\n<p>Durante a reuni\u00e3o, ficou definido que a a\u00e7\u00e3o ser\u00e1 viabilizada por meio de um modelo de integra\u00e7\u00e3o tarif\u00e1ria indireta, com unifica\u00e7\u00e3o dos sistemas de bilhetagem, sem necessidade de mudan\u00e7as imediatas na pol\u00edtica tarif\u00e1ria e constru\u00e7\u00e3o de um terminal. Com isso, a expectativa \u00e9 de que a passagem entre Bras\u00edlia e \u00c1guas Lindas, atualmente no valor de R$ 10,85, tenha redu\u00e7\u00e3o de 30% na fase inicial do projeto.<\/p>\n<p><strong>Integra\u00e7\u00e3o tarif\u00e1ria<\/strong><\/p>\n<p>O secret\u00e1rio de Mobilidade (Semob-DF), Zeno Gon\u00e7alves, se comprometeu a coordenar a constru\u00e7\u00e3o de um conv\u00eanio entre o GDF, o estado de Goi\u00e1s e a cidade de \u00c1guas Lindas, como forma de viabilizar a opera\u00e7\u00e3o integrada e o modelo de subs\u00eddio ao transporte metropolitano. &#8220;A gente precisa trazer todas as variantes. Fazer a modelagem de integra\u00e7\u00e3o tarif\u00e1ria de forma indireta com a unifica\u00e7\u00e3o do sistema de bilhetagem&#8221;, avaliou \u00e0 coluna.<\/p>\n<p>Al\u00e9m do titular da Semob-DF e do prefeito de \u00c1guas Lindas, participaram da reuni\u00e3o o presidente da Codeal, Andr\u00e9 Oliveira; o secret\u00e1rio municipal de Transportes de \u00c1guas Lindas, Ol\u00edvio Chaves; o secret\u00e1rio de Estado do Entorno do DF, Cristian Viana; e a superintendente Paula Tredicci, representando a Secretaria de Estado do Entorno de Goi\u00e1s.<\/p>\n<h3>Seguran\u00e7a nacional em pauta<\/h3>\n<p>O Comit\u00ea de Seguran\u00e7a do Instituto Rui Barbosa (IRB), presidido pelo conselheiro do Tribunal de Contas do Distrito Federal (TCDF) Renato Rainha, iniciou o planejamento de uma auditoria nacional que promete lan\u00e7ar luz sobre o uso dos recursos do Fundo Nacional de Seguran\u00e7a P\u00fablica, repassados pela Uni\u00e3o aos estados. A iniciativa busca evitar que verbas fundamentais fiquem paradas enquanto a popula\u00e7\u00e3o sofre com a viol\u00eancia, est\u00e1 prevista para o ano que vem e ser\u00e1 executada por tribunais de contas de todo o pa\u00eds.<\/p>\n<h3>Efici\u00eancia e tempestividade<\/h3>\n<p>\u00c0 coluna, o conselheiro do TCDF disse que a ideia \u00e9 avaliar como esses recursos est\u00e3o sendo aplicados e se est\u00e3o sendo usados com efici\u00eancia e tempestividade. &#8220;Alguns estados, infelizmente, n\u00e3o est\u00e3o utilizando os valores disponibilizados pela Uni\u00e3o para investir em seguran\u00e7a p\u00fablica&#8221;, avaliou. &#8220;S\u00f3 vamos vencer o crime organizado se os recursos da seguran\u00e7a forem aplicados com efici\u00eancia e rapidez. Essa \u00e9 uma guerra, e n\u00e3o se vence guerra com desperd\u00edcio e lentid\u00e3o&#8221;, ressaltou Renato Rainha.<\/p>\n<h3>PEC do Fundo Constitucional<\/h3>\n<p>A Comiss\u00e3o de Seguran\u00e7a P\u00fablica (CSP) do Senado Federal recebe, hoje, a segunda audi\u00eancia p\u00fablica para debater a Proposta de Emenda \u00e0 Constitui\u00e7\u00e3o (PEC) 1\/2025, que tem o objetivo de garantir o c\u00e1lculo do Fundo Constitucional do Distrito Federal (FCDF) com base na Receita Corrente L\u00edquida (RCL) da Uni\u00e3o, evitando que o recurso esteja sujeito a outras formas de corre\u00e7\u00e3o que possam ser menos vantajosas para o DF. A reuni\u00e3o contar\u00e1 com a participa\u00e7\u00e3o de representantes da Pol\u00edcia Militar (PMDF).<\/p>\n<h3>Capacita\u00e7\u00e3o que transforma<\/h3>\n<p>Idealizado pela secret\u00e1ria de Justi\u00e7a e Cidadania do DF, Marcela Passamani, o projeto Protagonista da Casa encerrou o primeiro ciclo com um resultado expressivo: mais de 8 mil mulheres capacitadas e certificadas em todas as regi\u00f5es administrativas do DF. O curso gratuito de organiza\u00e7\u00e3o do lar tem transformado a vida de diaristas, empregadas dom\u00e9sticas e donas de casa, promovendo valoriza\u00e7\u00e3o profissional, aumento de renda e at\u00e9 transi\u00e7\u00e3o de carreira para a \u00e1rea de personal organizer. Enquanto muitas profissionais do lar passaram a cobrar por hora e oferecer servi\u00e7os especializados, donas de casa relatam melhorias na rotina e mais tempo de qualidade com a fam\u00edlia. A iniciativa acaba de iniciar seu segundo m\u00f3dulo, focado em educa\u00e7\u00e3o financeira, e um novo ciclo j\u00e1 est\u00e1 em planejamento.<\/p>\n<h3>Plano de compensa\u00e7\u00e3o ambiental<\/h3>\n<p>A vice-governadora do DF, Celina Le\u00e3o (PP), participou de um encontro para assinar um Acordo de Coopera\u00e7\u00e3o T\u00e9cnica entre o Tribunal Superior do Trabalho (TST), o Tribunal Regional do Trabalho da 10\u00aa Regi\u00e3o (TRT-10), MPT-DF\/TO e GDF para o plantio de 70 mil mudas de esp\u00e9cies nativas do Cerrado, ao longo de quatro anos. A parceria foi firmada no \u00e2mbito do Programa Justi\u00e7a Carbono Zero. \u00c0 coluna, Celina afirmou que firmar esta parceria \u00e9 avan\u00e7ar com responsabilidade rumo a um futuro mais sustent\u00e1vel. &#8220;Este acordo representa mais do que o plantio de \u00e1rvores, \u00e9 a semeadura de um compromisso duradouro com o Cerrado, com a justi\u00e7a clim\u00e1tica e com as pr\u00f3ximas gera\u00e7\u00f5es&#8221;, comentou.<\/p>\n<h3>Visita \u00e0 Ucr\u00e2nia<\/h3>\n<p>A convite da Confer\u00eancia Episcopal Ucraniana, o cardeal Paulo Cezar Costa est\u00e1 na Ucr\u00e2nia, acompanhado do chefe do gabinete episcopal, padre Luiz Oct\u00e1vio de Aguiar Faria. O cardeal vai presidir, em 20 de julho, a Santa Missa no Santu\u00e1rio Nacional de Nossa Senhora do Carmo, na cidade de Berdychiv, por ocasi\u00e3o da tradicional peregrina\u00e7\u00e3o anual ao santu\u00e1rio.<\/p>\n<h3>A\u00e7\u00f5es conjuntas<\/h3>\n<p>Um acordo de coopera\u00e7\u00e3o t\u00e9cnica entre o Instituto de Pesquisa e Estat\u00edstica do Distrito Federal (IPEDF) e a C\u00e2mara dos Deputados, publicado ontem no Di\u00e1rio Oficial (DODF), quer promover a colabora\u00e7\u00e3o para a execu\u00e7\u00e3o de a\u00e7\u00f5es conjuntas, visando a dissemina\u00e7\u00e3o de informa\u00e7\u00f5es sobre o aprimoramento de processos de trabalho. Entre os objetivos espec\u00edficos, est\u00e3o a colabora\u00e7\u00e3o em edi\u00e7\u00f5es e coedi\u00e7\u00f5es de produtos bibliogr\u00e1ficos e a distribui\u00e7\u00e3o de exemplares de publica\u00e7\u00f5es editadas conjunta ou individualmente pelos part\u00edcipes do acordo.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Arthur de Souza (interino) Em reuni\u00e3o realizada ontem, na Secretaria de Transporte e Mobilidade do Distrito Federal (Semob-DF), representantes dos governos do Distrito Federal e de Goi\u00e1s, al\u00e9m da prefeitura de \u00c1guas Lindas (GO), decidiram que a cidade goiana desenvolver\u00e1 o projeto-piloto para a implanta\u00e7\u00e3o da integra\u00e7\u00e3o do transporte p\u00fablico na Regi\u00e3o Metropolitana do Entorno. A iniciativa servir\u00e1 de [&hellip;]<\/p>\n","protected":false},"author":159,"featured_media":26975,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[234],"tags":[416,113,1783,3913,229],"class_list":["post-26974","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cb-poder","tag-camara-dos-deputados","tag-celina-leao","tag-fundo-constitucional","tag-justica-e-cidadania","tag-transporte-publico"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/26974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/users\/159"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/comments?post=26974"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/26974\/revisions"}],"predecessor-version":[{"id":26976,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/26974\/revisions\/26976"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media\/26975"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media?parent=26974"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/categories?post=26974"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/tags?post=26974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}