{"id":25991,"date":"2024-11-14T10:52:46","date_gmt":"2024-11-14T13:52:46","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/?p=25991"},"modified":"2024-11-14T10:57:12","modified_gmt":"2024-11-14T13:57:12","slug":"df-lidera-em-elucidacao-de-homicidios","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/df-lidera-em-elucidacao-de-homicidios\/","title":{"rendered":"DF lidera em elucida\u00e7\u00e3o de homic\u00eddios"},"content":{"rendered":"<p><strong>EIXO CAPITAL, publicado quinta-feira (14\/11) &#8211; Por Ana Maria Campos<\/strong><\/p>\n<p>O Distrito Federal \u00e9 a unidade da Federa\u00e7\u00e3o com o maior \u00edndice de esclarecimento de homic\u00eddios dolosos: 90% dos casos registrados no ano de 2022 tiveram o autor identificado e houve den\u00fancia pelo Minist\u00e9rio P\u00fablico. O DF ocupa a primeira posi\u00e7\u00e3o, seguido por Goi\u00e1s e Mato Grosso do Sul. Os dados fazem parte de relat\u00f3rio da pesquisa Onde Mora a Impunidade?, lan\u00e7ado pelo Instituto Sou da Paz. Para a elabora\u00e7\u00e3o do levantamento, foram solicitados dados aos minist\u00e9rios p\u00fablicos e aos tribunais de justi\u00e7a de todas as unidades da Federa\u00e7\u00e3o, por meio da Lei de Acesso \u00e0 Informa\u00e7\u00e3o. A pesquisa considerou 22.880 homic\u00eddios dolosos registrados em 2022, dos quais 8.919 resultaram em den\u00fancias criminais at\u00e9 dezembro de 2023.<\/p>\n<p><strong>Integra\u00e7\u00e3o<\/strong><\/p>\n<p>O secret\u00e1rio de Seguran\u00e7a P\u00fablica do DF e presidente do Conselho Nacional dos Secret\u00e1rios de Seguran\u00e7a P\u00fablica (Consesp), Sandro Avelar, atribui esse desempenho \u00e0 consolida\u00e7\u00e3o de pol\u00edticas de seguran\u00e7a p\u00fablica ao longo dos \u00faltimos 11 anos. &#8220;Iniciamos com o fortalecimento da integra\u00e7\u00e3o das for\u00e7as de seguran\u00e7a, mas fomos al\u00e9m. Hoje, temos uma pol\u00edtica de seguran\u00e7a integral, que envolve n\u00e3o s\u00f3 as for\u00e7as de seguran\u00e7a, mas tamb\u00e9m outros setores do governo e da sociedade&#8221;, afirma.<\/p>\n<p><strong>Ainda est\u00e3o aqui<\/strong><\/p>\n<p>A deputada federal \u00c9rika Kokay (PT-DF) apresentou, nesta semana, projeto de lei para incluir o nome de Eunice Paiva no livro de Her\u00f3is e Hero\u00ednas da P\u00e1tria. Vi\u00fava de Rubens Paiva, deputado cassado pelo golpe de 1964 e morto pela ditadura militar, e m\u00e3e do escritor Marcelo Rubens Paiva, Eunice, al\u00e9m de buscar, incessantemente, not\u00edcias sobre o paradeiro do marido, se formou em direito e se tornou uma grande defensora dos direitos humanos e da busca por verdade. &#8220;Homenagear Rubens e Eunice Paiva \u00e9 dizer que eles &#8216;Ainda Est\u00e3o Aqui'&#8221;, disse Kokay, autora do PL 4320\/2024, em refer\u00eancia ao filme em cartaz assistido por mais de 350 mil pessoas no \u00faltimo fim de semana e que representa o Brasil para disputar uma vaga no Oscar 2025.<\/p>\n<p><strong>Advogados da Uni\u00e3o: solenidade de 28 anos<\/strong><\/p>\n<p>O plen\u00e1rio da C\u00e2mara dos Deputados ser\u00e1 palco, amanh\u00e3, de uma sess\u00e3o solene em homenagem aos 28 anos do Dia do Advogado da Uni\u00e3o e da Associa\u00e7\u00e3o Nacional dos Advogados da Uni\u00e3o (Anauni). O evento, proposto pelo deputado Lafayette de Andrada (Republicanos-MG), comemora o dia 12 de novembro, data em que, em 1996, os primeiros advogados da Uni\u00e3o tomaram posse e que marca tamb\u00e9m a funda\u00e7\u00e3o da Anauni. Ser\u00e1 a partir das 15h.<\/p>\n<p><strong>Homenagem suprapartid\u00e1ria<\/strong><\/p>\n<p>A poucos dias de deixar a reitoria da Universidade de Bras\u00edlia (UnB), M\u00e1rcia Abrah\u00e3o Moura recebeu ontem o t\u00edtulo de Cidad\u00e3 Honor\u00e1ria de Bras\u00edlia, em solenidade emocionante. Al\u00e9m da justa celebra\u00e7\u00e3o ao trabalho da educadora e primeira mulher a ocupar o cargo na UnB, o evento no plen\u00e1rio da C\u00e2mara Legislativa rendeu uma cena rara: a jun\u00e7\u00e3o de deputados das mais diferentes vertentes pol\u00edticas. Autora da homenagem, a deputada distrital Paula Belmonte (Cidadania), que se define como uma parlamentar independente, reuniu \u00e0 mesa de honra os deputados de esquerda, F\u00e1bio F\u00e9lix (PSOL) e Gabriel Magno e a ex-deputada Arlete Sampaio. Tamb\u00e9m fizeram parte da celebra\u00e7\u00e3o o ex-reitor da UnB, Jos\u00e9 Geraldo de Sousa J\u00fanior e a decana de Tecnologia e Inova\u00e7\u00e3o, Maria Em\u00edlia Walter.<\/p>\n<p><strong>Mem\u00f3ria de outros tempos<\/strong><\/p>\n<p>Na solenidade, a ex-deputada e ex-vice-governadora Arlete Sampaio (PT) se emocionou ao se recordar de um tempo em que alunos eram jubilados da UnB por quest\u00f5es pol\u00edticas. Ela se referiu ao mandato do ex-reitor Jos\u00e9 Carlos Azevedo, Capit\u00e3o de mar e guerra que esteve na UnB entre 1976 e 1985, nos anos de chumbo.<\/p>\n<p><strong>Boa gestora<\/strong><\/p>\n<p>Professor em\u00e9rito da UnB e ex-reitor, Jos\u00e9 Geraldo de Sousa J\u00fanior fez muitos elogios a M\u00e1rcia Abrah\u00e3o como boa gestora. Ele afirmou que ela daria uma boa presidente do Banco Central. M\u00e1rcia \u00e9 graduada, mestra e doutora em geologia pela UnB e tem p\u00f3s-doutorado pela Queen&#8217;s University, do Canad\u00e1.<\/p>\n<p><strong>A pergunta que n\u00e3o quer calar&#8230;<\/strong><\/p>\n<p>Ser\u00e1 que agora, com o encerramento do mandato de M\u00e1rcia Abrah\u00e3o na reitoria da UnB e a proximidade das elei\u00e7\u00f5es de 2026, ela est\u00e1 aberta a uma candidatura ao Pal\u00e1cio do Buriti?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>EIXO CAPITAL, publicado quinta-feira (14\/11) &#8211; Por Ana Maria Campos O Distrito Federal \u00e9 a unidade da Federa\u00e7\u00e3o com o maior \u00edndice de esclarecimento de homic\u00eddios dolosos: 90% dos casos registrados no ano de 2022 tiveram o autor identificado e houve den\u00fancia pelo Minist\u00e9rio P\u00fablico. O DF ocupa a primeira posi\u00e7\u00e3o, seguido por Goi\u00e1s e Mato Grosso do Sul. Os [&hellip;]<\/p>\n","protected":false},"author":157,"featured_media":25992,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2089],"tags":[1018,482,1034],"class_list":["post-25991","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eixo-capital","tag-homicidio","tag-seguranca-publica","tag-unb"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/25991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/users\/157"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/comments?post=25991"}],"version-history":[{"count":2,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/25991\/revisions"}],"predecessor-version":[{"id":25994,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/25991\/revisions\/25994"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media\/25992"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media?parent=25991"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/categories?post=25991"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/tags?post=25991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}