{"id":25736,"date":"2024-10-08T07:50:23","date_gmt":"2024-10-08T10:50:23","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/?p=25736"},"modified":"2024-10-08T07:50:23","modified_gmt":"2024-10-08T10:50:23","slug":"os-proximos-planos-do-psd","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/os-proximos-planos-do-psd\/","title":{"rendered":"Os pr\u00f3ximos planos do PSD"},"content":{"rendered":"<p><em><strong>Coluna Eixo Capital publicada em 8 de outubro de 2024, por Ana Maria Campos<\/strong><\/em><\/p>\n<p>Depois de conquistar o maior n\u00famero de prefeituras no primeiro turno das elei\u00e7\u00f5es municipais, o presidente do PSD, Gilberto Kassab, tem duas metas: manter o desempenho no segundo turno e alcan\u00e7ar a presid\u00eancia da C\u00e2mara dos Deputados. O nome para o cargo \u00e9 o do l\u00edder do partido, Ant\u00f4nio Brito (BA). No DF, o presidente regional, Paulo Oct\u00e1vio, comemora a performance da legenda e espera um fortalecimento de seus projetos para 2026, entre os quais eleger o filho ca\u00e7ula, Andr\u00e9 Kubitschek, deputado federal.<\/p>\n<p><strong>Onda da causa animal<\/strong><br \/>\nCom 113.820 votos, o terceiro vereador mais votado da cidade de S\u00e3o Paulo foi Dr. Murillo Lima (PP) elegeu-se com a bandeira da causa animal. Mesmo enfoque da campanha do segundo mais votado em Osasco, Ralfi Silva (Republicanos), defensor da implanta\u00e7\u00e3o de hospitais veterin\u00e1rios gratuitos na cidade.<\/p>\n<p><strong>Mulheres na minoria<\/strong><br \/>\nComo resultado do primeiro turno, por enquanto, apenas 11% das prefeituras ser\u00e3o comandadas por mulheres.<\/p>\n<p><strong>Vice<\/strong><br \/>\nProcurador de Justi\u00e7a aposentado, ex-presidente da Terracap e ex-administrador de Bras\u00edlia, o advogado Ant\u00f4nio Gomes topou ser vice na chapa encabe\u00e7ada por Carolyne Guimar\u00e3es na disputa pela presid\u00eancia da OAB-DF.<\/p>\n<p><strong>Filhos eleitos<\/strong><br \/>\nOs filhos do ex-presidente Jair Bolsonaro tiveram o melhor desempenho poss\u00edvel nas elei\u00e7\u00f5es municipais. Carlos Bolsonaro (PL) teve 130.480 votos, mais do dobro de votos do segundo colocado na disputa pela C\u00e2mara de Vereadores do Rio de Janeiro, M\u00e1rcio Ribeiro (PSD). O filho 04, Jair Renan (PL), tamb\u00e9m foi o mais votado em Balne\u00e1rio Cambori\u00fa e se elegeu vereador.<\/p>\n<p><strong>Devagar<\/strong><br \/>\nO PSDB sumiu do mapa no munic\u00edpio de S\u00e3o Paulo. Em 2020, o partido reelegeu o tucano Bruno Covas. Agora, n\u00e3o tem sequer um vereador. Em Goi\u00e2nia, o partido do presidente nacional da sigla, Marconi Perillo, elegeu apenas dois vereadores.<\/p>\n<blockquote><p>\n<strong>\u00c0 Queima Roupa<\/strong><br \/>\n<strong>Bruno Eduardo, vice-diretor da ONG A Vida no Cerrado<\/strong><\/p>\n<p>Em meio a enchentes no Rio Grande do Sul, seca dos rios na Amaz\u00f4nica, recordes de temperaturas e inc\u00eandios em v\u00e1rios pontos do pa\u00eds, a ONG A Vida no Cerrado, sediada em S\u00e3o Sebasti\u00e3o e com ramifica\u00e7\u00f5es em v\u00e1rios estados, lan\u00e7ou o\u00a0<em>Guia para Candidaturas Ambientalistas<\/em>. O\u00a0material \u00e9 dirigido a candidatos a prefeitos e vereadores, com orienta\u00e7\u00f5es de como integrar a tem\u00e1tica do meio ambiente \u00e0s pol\u00edticas p\u00fablicas municipais em uma era de emerg\u00eancia clim\u00e1tica. E, nesta entrevista, Bruno Eduardo, bi\u00f3logo e mestre em ecologia, vice-diretor da Avinc, fala sobre a cartilha e o engajamento dos jovens nas quest\u00f5es ambientais.<\/p>\n<p><strong>O que voc\u00eas miram ao conceber uma cartilha sobre as a\u00e7\u00f5es para mitigar as mudan\u00e7as clim\u00e1ticas dirigida a candidatos a prefeitos e vereadores?<\/strong><\/p>\n<p>A ideia nasceu de uma an\u00e1lise conjunta de volunt\u00e1rios de todas as redes que atuam com juventudes mobilizadas pela pauta da consci\u00eancia ambiental, com foco no bioma Cerrado. Nunca antes vimos tantas oportunidades de intervir na pauta ambiental quanto neste momento em que estamos vivendo eventos extremos cada vez mais frequentes. O Brasil pegou fogo quase que nacionalmente. Tivemos mais de 190 mil focos de inc\u00eandios. Fa\u00e7o um recorte de que 35% desses alarmes de queimadas ocorreram no Cerrado. Os munic\u00edpios s\u00e3o os lugares onde as pessoas, efetivamente, moram e constroem suas identidades. Ent\u00e3o, ao exercer o direito ao voto, o cidad\u00e3o pode influenciar os candidatos a oferecer pol\u00edticas p\u00fablicas para o meio ambiente.<\/p>\n<p><strong>Qual deve ser a perspectiva dos pol\u00edticos em rela\u00e7\u00e3o ao meio ambiente em um contexto de emerg\u00eancia clim\u00e1tica?<\/strong><\/p>\n<p>N\u00e3o devem olhar o meio ambiente como uma bolha, mas, sim, como um tema transversal. A crise clim\u00e1tica envolve tudo: meio ambiente, sa\u00fade p\u00fablica, educa\u00e7\u00e3o e mobilidade urbana. Tivemos em mira, justamente, criar um material capaz de fornecer aos candidatos as principais ferramentas de como agir para enfrentar as mudan\u00e7as clim\u00e1ticas no \u00e2mbito local. Os prefeitos e vereadores est\u00e3o na linha de frente das cidades assoladas por enchentes, secas e calor extremo. Com pol\u00edticas p\u00fablicas, eles podem promover a resili\u00eancia em seus territ\u00f3rios e a sustentabilidade nas cadeias produtivas.<\/p>\n<p><strong>Uma pesquisa recente mostrou que somente um em cada tr\u00eas pol\u00edticos mencionam as mudan\u00e7as clim\u00e1ticas em seus programas. Como lidar com esse n\u00edvel de consci\u00eancia em uma situa\u00e7\u00e3o t\u00e3o grave?<\/strong><\/p>\n<p>A pesquisa revela uma desconex\u00e3o total entre a realidade e a percep\u00e7\u00e3o da pol\u00edtica, apesar de ser um tema presente no cotidano de milh\u00f5es de brasileiros. Os candidatos n\u00e3o conseguem compreender que isso ter\u00e1 um impacto profundo e precisa ser enfrentado com as pol\u00edticas p\u00fablicas locais. A gente est\u00e1 vivendo em um novo clima. N\u00e3o \u00e9 mais o de 20 anos atr\u00e1s. Hoje, a gente precisa repensar as nossas cidades, temos de falar em estruturas verdes relacionadas, construir solu\u00e7\u00f5es baseadas na natureza. Tem uma frase muita boa do Ailton Krenak: &#8220;A melhor tecnologia para sequestrar carbono a natureza j\u00e1 deu para a gente, que s\u00e3o as \u00e1rvores.&#8221; Temos de transformar essas tecnologias em pol\u00edticas p\u00fablicas municipais, estaduais e federais.<\/p>\n<p><strong>Que solu\u00e7\u00f5es seriam poss\u00edveis para enfrentar as mudan\u00e7as clim\u00e1ticas nas cidades e qual o papel dos prefeitos e vereadores nessas a\u00e7\u00f5es?<\/strong><\/p>\n<p>Adotar solu\u00e7\u00f5es baseadas na natureza. Isso \u00e9 muito importante. \u00c1reas mais verdes podem reduzir a sensa\u00e7\u00e3o t\u00e9rmica. As cidades s\u00e3o verdadeiras ilhas de concreto que absorvem muito calor. E, tamb\u00e9m, tornar as cidades mais perme\u00e1veis. A gente sofre com a falta da chuva, mas quando ela chega, temos dificuldade de drenagem. Os solos s\u00e3o altamente compactados, n\u00e3o conseguem infiltrar a \u00e1gua. Nossas cidades precisam ser perme\u00e1veis. \u00c9 necess\u00e1rio investir em inova\u00e7\u00e3o e pesquisa. E, pensando no papel dos prefeitos e vereadores, \u00e9 fundamental a participa\u00e7\u00e3o deles na aprova\u00e7\u00e3o das leis para direcionar os recursos do or\u00e7amento municipal para lidar com a crise clim\u00e1tica. \u00c9 preciso ter um or\u00e7amento distribu\u00eddo para grupos priorit\u00e1rios, a partir de um recorte . A vida no Cerrado coloca isso em jogo. O Cerrado est\u00e1, em m\u00e9dia, 1,2\u00baC mais quente. Isso significa menos \u00e1gua na caixa d&#8217;\u00e1gua do Brasil, que \u00e9 o bioma Cerrado. A Cartilha veio com essa perspectiva nas elei\u00e7\u00f5es. A ideia \u00e9 plantar a sementinha do ambiente como um tema transversal. A chave \u00e9 integrar a tem\u00e1tica ambiental em todas as esferas das pol\u00edticas p\u00fablicas.<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Coluna Eixo Capital publicada em 8 de outubro de 2024, por Ana Maria Campos Depois de conquistar o maior n\u00famero de prefeituras no primeiro turno das elei\u00e7\u00f5es municipais, o presidente do PSD, Gilberto Kassab, tem duas metas: manter o desempenho no segundo turno e alcan\u00e7ar a presid\u00eancia da C\u00e2mara dos Deputados. O nome para o cargo \u00e9 o do l\u00edder [&hellip;]<\/p>\n","protected":false},"author":157,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2089],"tags":[3661,311,274],"class_list":["post-25736","post","type-post","status-publish","format-standard","hentry","category-eixo-capital","tag-cerrado","tag-eleicoes","tag-oab"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/25736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/users\/157"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/comments?post=25736"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/25736\/revisions"}],"predecessor-version":[{"id":25738,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/25736\/revisions\/25738"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media?parent=25736"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/categories?post=25736"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/tags?post=25736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}