{"id":22763,"date":"2022-11-10T16:07:56","date_gmt":"2022-11-10T19:07:56","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/?p=22763"},"modified":"2022-11-10T16:12:58","modified_gmt":"2022-11-10T19:12:58","slug":"orcamento-do-df-de-2023-tera-aumento-de-188-e-chega-a-r-574-bilhoes","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/orcamento-do-df-de-2023-tera-aumento-de-188-e-chega-a-r-574-bilhoes\/","title":{"rendered":"Or\u00e7amento do DF de 2023 ter\u00e1 aumento de 18,8% e chega a R$ 57,4 bilh\u00f5es"},"content":{"rendered":"<h4>ANA MARIA CAMPOS<\/h4>\n<p>O or\u00e7amento do Distrito Federal para 2023 ser\u00e1 de R$ 57,4 bilh\u00f5es. Esse montante representa um aumento de 18,8% em compara\u00e7\u00e3o a 2022.<\/p>\n<p>&nbsp;<\/p>\n<p>Os n\u00fameros foram apresentados pela equipe da Secretaria de Planejamento, Or\u00e7amento e Administra\u00e7\u00e3o do GDF, em audi\u00eancia p\u00fablica da Comiss\u00e3o de Economia, Or\u00e7amento e Finan\u00e7as (CEOF) da C\u00e2mara Legislativa, realizada nesta quarta-feira (09), por videoconfer\u00eancia.<\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\"><span class=\"s1\">O Projeto de Lei Or\u00e7ament\u00e1ria Anual &#8211; PLOA (PL 2992\/2022) prev\u00ea aumento de 6,61% do Tesouro do DF, saindo de R$ 32,3 bilh\u00f5es para R$ 34,4 bilh\u00f5es, enquanto o Fundo Constitucional do DF (FCDF) ter\u00e1 um crescimento de 41,09% (de R$ 16,2 para R$ 23 bilh\u00f5es).<br \/>\n<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\">A distribui\u00e7\u00e3o do FCDF compreende aumento de 17,8% para seguran\u00e7a p\u00fablica (R$ 10,2 bilh\u00f5es); de 64,05% para sa\u00fade (R$ 7,1 bilh\u00f5es); e de 72,18% para educa\u00e7\u00e3o (R$ 5,6 bilh\u00f5es). A previs\u00e3o \u00e9 de que as receitas correntes cres\u00e7am 7,41% (de R$ 29,1 bilh\u00f5es para R$ 31,3 bilh\u00f5es), com incremento de 5,92% em impostos, taxas e contribui\u00e7\u00f5es de melhoria.<\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\"><span class=\"s1\"> A receita de capital ter\u00e1 aumento de 17,52% (de R$ 1,3 a bilh\u00e3o para R$ 1,5 bilh\u00e3o) e as receitas totais, 6,3%.<br \/>\n<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\"><span class=\"s1\">A arrecada\u00e7\u00e3o com impostos somar\u00e1 R$ 19,8 bilh\u00f5es, com destaque para o ICMS, que representa 46% do total, seguido por Imposto de Renda (20%) e ISS (13%).<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\"><span class=\"s1\">Segundo o chefe da Unidade de Processo e Monitoramento Or\u00e7ament\u00e1rios, Luiz Paulo de Carvalho, a diminui\u00e7\u00e3o de 6,41% (de R$ 17,5 para R$ 16,4 bilh\u00f5es) com a despesa do tesouro do DF com pessoal deve-se ao aumento do FCDF.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\"><span class=\"s1\">No total, o gasto soma R$ 27,5 bilh\u00f5es, sem considerar os valores de seguran\u00e7a p\u00fablica do FCDF. O mesmo ocorre em rela\u00e7\u00e3o a Seguridade, que registrar\u00e1 queda de 7,23% referente ao tesouro, mas ter\u00e1 um incremento real de 13,8%, quando considerado tamb\u00e9m o FCDF.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\"><span class=\"s1\"> O gasto com pessoal, de acordo com o PLOA, representar\u00e1 49,64% das despesas do DF.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\"><span class=\"s1\">O projeto est\u00e1 na fase de apresenta\u00e7\u00e3o de emendas. Esse prazo termina nesta sexta-feira (11). \u00a0<\/span>As emendas dos deputados distritais, que representam 2% da receita corrente l\u00edquida, somam R$ 600 milh\u00f5es, sendo que cada parlamentar poder\u00e1 indicar R$ 25 milh\u00f5es.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p class=\"p1\">A vota\u00e7\u00e3o dos pareceres preliminares da CEOF est\u00e1 prevista para 22 de novembro e, a partir de 12 de dezembro, o projeto estar\u00e1 pronto para ser votado em plen\u00e1rio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ANA MARIA CAMPOS O or\u00e7amento do Distrito Federal para 2023 ser\u00e1 de R$ 57,4 bilh\u00f5es. Esse montante representa um aumento de 18,8% em compara\u00e7\u00e3o a 2022. &nbsp; Os n\u00fameros foram apresentados pela equipe da Secretaria de Planejamento, Or\u00e7amento e Administra\u00e7\u00e3o do GDF, em audi\u00eancia p\u00fablica da Comiss\u00e3o de Economia, Or\u00e7amento e Finan\u00e7as (CEOF) da C\u00e2mara Legislativa, realizada nesta quarta-feira (09), [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":22765,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[234],"tags":[70,2021,1778,3164],"class_list":["post-22763","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cb-poder","tag-camara-legislativa","tag-emendas","tag-fundo-constitucional-do-df","tag-orcamento-2023"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/22763","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/comments?post=22763"}],"version-history":[{"count":5,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/22763\/revisions"}],"predecessor-version":[{"id":22769,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/22763\/revisions\/22769"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media\/22765"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media?parent=22763"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/categories?post=22763"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/tags?post=22763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}