{"id":21911,"date":"2021-08-05T07:10:04","date_gmt":"2021-08-05T10:10:04","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/?p=21911"},"modified":"2021-08-05T07:10:04","modified_gmt":"2021-08-05T10:10:04","slug":"saida-de-leila-barros-e-perda-importante-para-o-psb-no-df","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/saida-de-leila-barros-e-perda-importante-para-o-psb-no-df\/","title":{"rendered":"Sa\u00edda de Leila Barros \u00e9 perda importante para o PSB no DF"},"content":{"rendered":"<p><strong>Coluna Eixo Capital, por Ana Maria Campos<\/strong><\/p>\n<p>Agora \u00e9 para valer: <a href=\"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/leila-barros-formaliza-adeus-ao-psb-e-fecha-com-o-cidadania\/\"><strong>a senadora Leila Barros (DF) formalizou a desfilia\u00e7\u00e3o ao PSB<\/strong><\/a>, ontem (4\/8), com uma mensagem \u00e0 imprensa, assinada por sua assessoria de comunica\u00e7\u00e3o. Foi elegante com o partido que n\u00e3o perdoou a sua decis\u00e3o e prepara uma s\u00e9rie de retalia\u00e7\u00f5es. \u201cEmbora reconhe\u00e7a a hist\u00f3ria e postura da sigla pela qual se elegeu em 2018, a parlamentar do Distrito Federal seguir\u00e1 sua vida pol\u00edtica no Cidadania\u201d, diz a nota. E continua: \u201cLeila agradece a acolhida dada pelo PSB, tanto a n\u00edvel nacional quanto distrital, e ressalta que mal-entendidos e poss\u00edveis m\u00e1goas diante da sua decis\u00e3o n\u00e3o a impedir\u00e3o de continuar ao lado dos colegas da legenda nas lutas comuns\u201d.<\/p>\n<p><strong>Partido perde<\/strong><\/p>\n<p>A sa\u00edda de Leila \u00e9 uma perda importante para o PSB. O partido fica sem nenhuma representa\u00e7\u00e3o no Senado e sem um nome para lan\u00e7ar ao Pal\u00e1cio do Buriti, j\u00e1 que o principal integrante da legenda no DF, o ex-governador Rodrigo Rollemberg, anunciou que pretende concorrer a um mandato de deputado federal.<\/p>\n<p><strong>Mist\u00e9rio<\/strong><\/p>\n<p>No momento pol\u00edtico fundamental para a defini\u00e7\u00e3o de seus rumos para 2022, Leila Barros preferiu n\u00e3o se posicionar politicamente. Ela n\u00e3o esconde que jamais apoiaria a candidatura do ex-presidente Lula, mas tamb\u00e9m n\u00e3o fez qualquer cr\u00edtica ao presidente Jair Bolsonaro. Tampouco defendeu uma terceira via. No caso da pol\u00edtica do DF, Leila manteve-se neutra em rela\u00e7\u00e3o \u00e0 reelei\u00e7\u00e3o do governador Ibaneis Rocha (MDB).<\/p>\n<h3>A pergunta que n\u00e3o quer calar\u2026.<\/h3>\n<p>Se, como Bolsonaro disse ontem, governo federal e do DF s\u00e3o um s\u00f3, Ibaneis Rocha vai apoiar a reelei\u00e7\u00e3o do presidente?<\/p>\n<p><strong>Pai pelo filho<\/strong><\/p>\n<p>O ex-deputado federal V\u00edtor Paulo deixou a Secretaria de Rela\u00e7\u00f5es Institucionais do DF e abriu espa\u00e7o para o filho, V\u00edtor Paulo J\u00fanior, nomeado em seu lugar pelo governador Ibaneis Rocha (MDB). V\u00edtor Paulo vai trabalhar e morar em S\u00e3o Paulo, onde n\u00e3o disputa a base eleitoral, da Igreja Universal, com o deputado federal J\u00falio C\u00e9sar (Republicanos-DF). V\u00edtor Paulo exerceu mandato de deputado federal no Rio de Janeiro e no Distrito Federal.<\/p>\n<p><strong>Nas m\u00e3os da Universal<\/strong><\/p>\n<p>A mudan\u00e7a de V\u00edtor Paulo para S\u00e3o Paulo faz parte dos remanejamentos pol\u00edticos da Igreja Universal, que define seus candidatos. Foi assim, por exemplo, com o ex-deputado Evandro Garla, que n\u00e3o p\u00f4de disputar a reelei\u00e7\u00e3o em 2018. Em seu lugar, entrou em campo o deputado distrital Martins Machado (Republicanos).<\/p>\n<p><strong>Novos caminhos<\/strong><\/p>\n<p>Articulador da alian\u00e7a que levou a vice-governadoria na chapa de Ibaneis Rocha em 2018, o advogado Lucas Kontoyanis deixou a vice-presid\u00eancia do Avante-DF. Ele e o vice-governador Paco Britto, presidente regional do partido, v\u00e3o trilhar caminhos distintos na pol\u00edtica. Lucas \u00e9 um estrategista na montagem de nominatas para a elei\u00e7\u00e3o de deputados distritais. Foi assim que o Avante emplacou dois representantes na C\u00e2mara Legislativa: Jo\u00e3o Cardoso e Reginaldo Sardinha. Agora, ele trabalha de olho em 2022, ainda sem definir a legenda.<\/p>\n<p><strong>Celebra\u00e7\u00e3o pelos 85 anos<\/strong><\/p>\n<p>No anivers\u00e1rio de 85 anos do nascimento do ex-governador Joaquim Roriz, a fam\u00edlia, como de costume, mandou celebrar uma missa. Neste ano, foi na Igreja Comunidade Mel de Deus, em Luzi\u00e2nia (GO). Dona Weslian Roriz, a vi\u00fava do pol\u00edtico, vive, atualmente, na fazenda Palma, da fam\u00edlia, na cidade goiana. Roriz morreu em 2018, quando tinha 82 anos.<\/p>\n<p><strong>Disputa pelo Na Hora<\/strong><\/p>\n<p>Um decreto do governador Ibaneis Rocha \u00e9 a base da transfer\u00eancia do contrato para a gest\u00e3o das ag\u00eancias de atendimento do Na Hora. Ibaneis autorizou a Secretaria de Justi\u00e7a e Cidadania a contratar para essa finalidade o Conglomerado BRB. Assim, em junho, o governo rescindiu o contrato com a ATP Tecnologia e Produtos e repassou para o BRB e para a BRB Servi\u00e7os, empresa de capital privado. A ATP, no entanto, n\u00e3o vai se conformar facilmente. A empresa, que h\u00e1 anos presta servi\u00e7o de automa\u00e7\u00e3o banc\u00e1ria para o BRB, briga na Justi\u00e7a para anular o decreto de Ibaneis e o contrato atual. O governo, por enquanto, est\u00e1 ganhando essa parada. Uma decis\u00e3o do desembargador Roberto Freitas Filho, do Tribunal de Justi\u00e7a do Distrito Federal e Territ\u00f3rios (TJDFT), garantiu, ontem, o in\u00edcio do atendimento ao p\u00fablico nos postos do Na Hora sob nova dire\u00e7\u00e3o.<\/p>\n<p><strong>S\u00f3 papos<\/strong><\/p>\n<p>\u201cQuanto mais pobre o estado, mais gordo \u00e9 o governador\u201d<br \/>\n<em>Presidente Jair Bolsonaro, em novo ataque ao advers\u00e1rio<\/em><\/p>\n<p>\u201cAcho que ele est\u00e1 se oferecendo para ser meu personal trainer. N\u00e3o, obrigado. Que estranha obsess\u00e3o. Vai trabalhar, presidente\u201d<br \/>\n<em>Governador do Maranh\u00e3o, Fl\u00e1vio Dino (PSB)<\/em><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A senadora Leila Barros (DF) formalizou a desfilia\u00e7\u00e3o ao PSB, ontem, com uma mensagem \u00e0 imprensa, assinada por sua assessoria de comunica\u00e7\u00e3o<\/p>\n","protected":false},"author":9,"featured_media":21912,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[234],"tags":[2715,1407,2963,52,2968],"class_list":["post-21911","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cb-poder","tag-eleicoes-2022","tag-leila-barros","tag-na-hora","tag-psb","tag-secretaria-de-relacoes-institucionais-do-df"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/21911","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/comments?post=21911"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/21911\/revisions"}],"predecessor-version":[{"id":21913,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/21911\/revisions\/21913"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media\/21912"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media?parent=21911"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/categories?post=21911"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/tags?post=21911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}