{"id":21813,"date":"2021-07-28T07:06:25","date_gmt":"2021-07-28T10:06:25","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/?p=21813"},"modified":"2021-07-28T07:06:25","modified_gmt":"2021-07-28T10:06:25","slug":"brasilia-tera-dois-complexos-desportivos-com-padroes-olimpicos-para-a-pratica-de-skate","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/brasilia-tera-dois-complexos-desportivos-com-padroes-olimpicos-para-a-pratica-de-skate\/","title":{"rendered":"Bras\u00edlia ter\u00e1 dois complexos desportivos com padr\u00f5es ol\u00edmpicos para a pr\u00e1tica de skate"},"content":{"rendered":"<p><strong>\u00c0 Queima-roupa \/\/\u00a0Giselle Ferreira, secret\u00e1ria de Esporte e Lazer do DF<\/strong><\/p>\n<p><strong>por Ana Maria Campos<\/strong><\/p>\n<p><strong>Quando chegam os Jogos Ol\u00edmpicos, todo mundo pensa: ser\u00e1 que o governo est\u00e1 contribuindo para formar bons atletas? O que o GDF tem feito para isso?<\/strong><br \/>\nO Governo do Distrito Federal tem criado e desenvolvido diversos programas e projetos com o objetivo de incentivar e democratizar a pr\u00e1tica esportiva e a forma\u00e7\u00e3o de atletas no DF. Em 2021, o nosso Programa Bolsa Atleta atende a 130 atletas ol\u00edmpicos e 107 atletas paral\u00edmpicos por m\u00eas, com a previs\u00e3o de cerca de R$ 1,7 milh\u00e3o para modalidades ol\u00edmpicas e R$ 1 milh\u00e3o para modalidades paral\u00edmpicas, o que totalizar\u00e1 cerca de R$ 2,7 milh\u00f5es investidos no esporte do Distrito Federal. O programa Compete Bras\u00edlia, que concede passagens para atletas competirem no Brasil e no mundo, continua atendendo a comunidade esportiva da capital. Desde o ano passado, mesmo com o per\u00edodo da pandemia, foram quase 1.500 contemplados. Os nossos 12 Centros Ol\u00edmpicos e Paral\u00edmpicos foram informatizados e duplicamos os atendimentos de 29 mil para 62 mil vagas. Vale destacar que o atleta de saltos ornamentais Kawan Pereira descobriu a modalidade no nosso COP do Gama, e hoje representa o Brasil nas Olimp\u00edadas de T\u00f3quio. E Taguatinga que n\u00e3o possu\u00eda um COP, agora contar\u00e1 com o Centro de Excel\u00eancia em Esporte que receber\u00e1 1,5 mil pessoas, em uma parceria in\u00e9dita com o SESI. As constru\u00e7\u00f5es, melhorias e reformas tamb\u00e9m n\u00e3o param. Nove campos sint\u00e9ticos e 20 campos de areia ser\u00e3o inaugurados por todo o DF, reformamos a Pra\u00e7a da Capoeira, banheiros, cal\u00e7adas e trocamos a ilumina\u00e7\u00e3o das quadras de areia do Parque da Cidade.<\/p>\n<p><strong>O or\u00e7amento da bolsa atleta \u00e9 baixo em rela\u00e7\u00e3o a um or\u00e7amento de R$ 42 bilh\u00f5es?<\/strong><br \/>\nA Secretaria de Esporte e Lazer atendeu a uma antiga reivindica\u00e7\u00e3o dos esportistas da cidade e aumentou, em 2020, os valores do Programa Bolsa Atleta em at\u00e9 93%. Todos os valores foram reajustados de R$ 183 a R$ 3.315 para R$ 354 a R$ 6.400. Al\u00e9m de pagar maiores valores em rela\u00e7\u00e3o as mesmas categorias do programa Bolsa Atleta Nacional.<\/p>\n<p><strong>Temos uma atleta de Ceil\u00e2ndia competindo, Ketleyn Quadros, judoca que foi porta-bandeira do Brasil e sambou na cerim\u00f4nia de abertura. O GDF deu algum apoio?<\/strong><br \/>\nAs artes marciais est\u00e3o presentes de forma cont\u00ednua em nossa pasta. Seguindo os protocolos de seguran\u00e7a, as competi\u00e7\u00f5es de jiu-j\u00edtsu e jud\u00f4 foram as primeiras a retornarem \u00e0s atividades competitivas. Quanto ao apoio a Ketleyn, h\u00e1 na lei que rege o Bolsa Atleta algumas regras espec\u00edficas, entre elas de que o esportista resida e tenha morado nos \u00faltimos 3 anos no DF, e, hoje, para representar o pa\u00eds em sua modalidade, Ketleyn n\u00e3o reside mais no DF.<\/p>\n<p><strong>Vimos uma menina de 13 anos brilhar com a medalha de prata no skate. Existe espa\u00e7o para crian\u00e7as e adolescentes receberem incentivo no skate como a fadinha Rayssa Leal?<\/strong><br \/>\nSim, sabemos que cerca de 300 mil pessoas praticam o esporte no DF, e pensando nisso, a Secretaria de Esporte e Lazer, com o apoio do governador Ibaneis, vai construir dois complexos desportivos \u2014 com padr\u00f5es ol\u00edmpicos \u2014 para a pr\u00e1tica de skate, nos dois maiores parques urbanos do DF, o Parque da Cidade Dona Sarah Kubitschek e no Taguaparque. Os projetos contam com duas pistas e vesti\u00e1rios. A \u00e1rea de conv\u00edvio vai contemplar pelo menos tr\u00eas estilos de skate: street, park e downhill.<\/p>\n<p><strong>Bras\u00edlia \u00e9 uma cidade prop\u00edcia para a atividade f\u00edsica. O que tem sido feito para incentivar essa voca\u00e7\u00e3o durante a pandemia?<\/strong><br \/>\nBras\u00edlia \u00e9 uma academia a c\u00e9u aberto. Sabemos que a pr\u00e1tica esportiva faz parte da vida dos brasilienses e com a chegada do novo normal, ap\u00f3s a pandemia da covid-19, ser\u00e1 ainda mais importante \u00e0s fam\u00edlias utilizarem os espa\u00e7os abertos da cidade. Pensando nisso, estamos abrindo novas avenidas aos domingos, al\u00e9m do Eix\u00e3o do Lazer, temos, agora, o Viva W3 e a Rua do lazer no Parano\u00e1. A deputada Celina Le\u00e3o, na sua gest\u00e3o na SEL, conseguiu reabrir as academias e os parques para que a popula\u00e7\u00e3o pudesse continuar a praticar esportes. E tamb\u00e9m conseguimos elevar a categoria dos profissionais de educa\u00e7\u00e3o f\u00edsica para representantes da sa\u00fade, o que garantiu a essencialidade do trabalho e posteriormente a prioridade na vacina\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em entrevista, a secret\u00e1ria de esportes e lazer Giselle Ferreira fala sobre o incentivo \u00e0 pr\u00e1tica esportiva, como aux\u00edlios financeiros<\/p>\n","protected":false},"author":9,"featured_media":21814,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[184],"tags":[2942,2482],"class_list":["post-21813","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entrevistas","tag-giselle-ferreira","tag-secretaria-de-esportes"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/21813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/comments?post=21813"}],"version-history":[{"count":2,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/21813\/revisions"}],"predecessor-version":[{"id":21816,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/21813\/revisions\/21816"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media\/21814"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media?parent=21813"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/categories?post=21813"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/tags?post=21813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}