{"id":21287,"date":"2021-05-02T09:19:35","date_gmt":"2021-05-02T12:19:35","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/?p=21287"},"modified":"2021-05-02T09:35:45","modified_gmt":"2021-05-02T12:35:45","slug":"mais-distante-bolsonaro-ibaneis-quer-candidato-proprio","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/mais-distante-bolsonaro-ibaneis-quer-candidato-proprio\/","title":{"rendered":"Mais distante de Bolsonaro, Ibaneis quer que MDB lance candidato pr\u00f3prio"},"content":{"rendered":"<h5>Coluna Eixo Capital, por Alexandre de Paula<\/h5>\n<p>Mesmo com os desentendimentos no \u00faltimo fechamento do com\u00e9rcio no DF, a rela\u00e7\u00e3o do governador Ibaneis Rocha (MDB) e do presidente Jair Bolsonaro (sem partido) est\u00e1 apaziguada. Segundo fontes pr\u00f3ximas ao emebista, Ibaneis gosta de Bolsonaro, mas quer manter-se independente nas decis\u00f5es locais. Apesar da paz, o governador lan\u00e7ou a proposta, em reuni\u00e3o do MDB nesta semana, de que o partido tenha candidato pr\u00f3prio \u00e0 presid\u00eancia em 2022, uma forma tamb\u00e9m de n\u00e3o se aliar a Lula, como planeja um grupo liderado pelo senador Renan Calheiros (MDB-AL). Os aliados do governador dizem que a ideia n\u00e3o tem nada a ver com Bolsonaro, mas Ibaneis defendia publicamente, at\u00e9 pouco tempo, que o presidente merecia ser reeleito.<\/p>\n<h3>Pacote de gera\u00e7\u00e3o de empregos<\/h3>\n<p>O governador Ibaneis Rocha (MDB) anunciou, ontem, que vai <a href=\"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/ibaneis-diz-que-lancara-pacote-para-geracao-de-empregos\/\">lan\u00e7ar um pacote para ajudar na gera\u00e7\u00e3o de empregos no DF nesta semana<\/a>. O emedebista, no entanto, ainda n\u00e3o divulgou as informa\u00e7\u00f5es sobre o projeto. \u201cSei que \u00e9 um momento muito delicado por conta da crise gerada pela pandemia. Mas, neste dia do trabalhador, a mensagem que quero deixar \u00e9 a de esperan\u00e7a porque estamos trabalhando muito para reacelerar a economia e gerar empregos\u201d, disse.<\/p>\n<p><strong>Mulheres jovens s\u00e3o alvo<\/strong><br \/>\nDe 94 inqu\u00e9ritos avaliados pela CPI do Feminic\u00eddio da C\u00e2mara Legislativa, 53% das v\u00edtimas tinham entre 30 e 49 anos e 38%, entre 18 e 29, mostra o relat\u00f3rio, que ser\u00e1 divulgado amanh\u00e3 na \u00edntegra, feito pelo distrital F\u00e1bio Felix (PSol). O trabalho tentou identificar padr\u00f5es e buscar solu\u00e7\u00f5es para o problema no DF. Chama a aten\u00e7\u00e3o, por exemplo, que em 21,4% dos casos o agressor usou frase similiar a \u201cse voc\u00ea n\u00e3o for minha, n\u00e3o ser\u00e1 de mais ningu\u00e9m\u201d. A CPI concluiu que medidas de protetivas de urg\u00eancia, se monitoradas pelo Poder p\u00fablico, podem salvar vidas e destacou que \u00e9 preciso refor\u00e7ar o sistema de apoio local.<\/p>\n<p><strong>Continuidade<\/strong><br \/>\nA diretoria do Sindireta, maior sindicato de servidores p\u00fablicos do DF, foi reconduzida por mais cinco anos. Apenas uma chapa disputou as elei\u00e7\u00f5es e Ibrahim Yusef segue na presid\u00eancia da entidade. Ele afirma que a pandemia deixou clara a necessidade de refor\u00e7ar o servi\u00e7o p\u00fablico. \u201cIsso s\u00f3 \u00e9 poss\u00edvel com servidores qualificados, reconhecidos, valorizados e com estabilidade\u201d, disse.<\/p>\n<p><strong>100% digital<\/strong><br \/>\nProcessos em primeira inst\u00e2ncia no Tribunal de Justi\u00e7a do Distrito Federal e Territ\u00f3rios (TJDFT) poder\u00e3o ser feitos de maneira 100% digital. A partir de amanh\u00e3, ser\u00e1 poss\u00edvel aderir ao formato no sistema da Corte. Nesse caso, n\u00e3o ser\u00e1 necess\u00e1rio comparecer aos f\u00f3runs e tudo ser\u00e1 feito on-line, at\u00e9 as audi\u00eancias.<\/p>\n<p><strong>Otimismo<\/strong><br \/>\nOs resultados de fevereiro do \u00cdndice de Velocidade de Vendas (IVV) do Mercado Imobili\u00e1rio deixaram o setor otimistas para a manuten\u00e7\u00e3o de bons n\u00fameros neste ano. Neste ano, o IVV ficou em 10,5% em fevereiro contra 6,7%. \u00c1guas Claras liderou a venda de im\u00f3veis, segundo a pesquisa feita em parceria pelo Sinduscon-DF e pela Ademi-DF.<\/p>\n<p><strong>Chumbo trocado<\/strong><br \/>\nDe um lado, os governistas dizem que a tentativa de instalar uma CPI para investigar atos do Iges-DF \u00e9 pura a\u00e7\u00e3o pol\u00edtica com foco em 2022; defendem que a ideia \u00e9 encontrar material para usar contra Ibaneis nas pr\u00f3ximas elei\u00e7\u00f5es. De outro lado, a oposi\u00e7\u00e3o diz que o governo quer esconder poss\u00edveis ilicitudes e tem medo de uma investiga\u00e7\u00e3o mais profunda numa \u00e1rea em que j\u00e1 houve suspeita de irregularidades pelo Minist\u00e9rio P\u00fablico.<\/p>\n<p><strong>Tudo explicadinho<\/strong><br \/>\nA Secretaria de Comunica\u00e7\u00e3o lan\u00e7ou uma ferramenta para auxiliar a popula\u00e7\u00e3o a ter acesso a uma s\u00e9rie de servi\u00e7os oferecidos pelo governo. Chamada de Tudo explicadinho, a plataforma on-line d\u00e1 passo a passo para v\u00e1rias fun\u00e7\u00f5es oferecidas pelo poder p\u00fablico e \u00e0s quais o cidad\u00e3o pode ter dificuldade para usar, como registrar boletins de ocorr\u00eancia, fazer pedidos de medicamentos da farm\u00e1cia de alto custo e a obten\u00e7\u00e3o de alvar\u00e1s.<\/p>\n<blockquote><p><strong>S\u00d3 PAPOS<\/strong><br \/>\n\u201cBolsonaro continua sua escalada golpista na Esplanada. Alguma manifesta\u00e7\u00e3o de empatia por mais de 400 mil mortos? Bolsonaro \u00e9 o maior aliado do v\u00edrus.\u201d<br \/>\n<em>Leandro Grass (Rede), deputado distrital<\/em><\/p>\n<p>\u201cO povo foi em peso pras ruas (&#8230;) Carreata bombando!\u00c9 pelas liberdades ,pelo voto audit\u00e1vel e apoio ao presidente Jair Bolsonaro.\u201d<br \/>\n<em>Bia Kicis (PSL-DF), deputada federal<\/em><\/p><\/blockquote>\n<p><strong>ENQUANTO ISSO NA SALA DE JUSTI\u00c7A<\/strong><br \/>\nForam definidos os seis mais votados para disputar a vaga pelo Minist\u00e9rio P\u00fablico do Distrito Federal e Territ\u00f3rios no TJDFT. O procurador de Justi\u00e7a Leonardo Bessa ficou em primeiro lugar seguido do promotor Lib\u00e2nio Rodrigues; e dos procuradores Maur\u00edcio Miranda; Jos\u00e9 Firmo Soub; Vitor Gon\u00e7alves; e Eduardo Albuquerque. Os nomes seguir\u00e3o para o TJDFT, que definir\u00e1 lista tr\u00edplice. Por fim, o presidente Jair Bolsonaro escolher\u00e1 um deles.<\/p>\n<p><strong>MANDOU MAL<\/strong><br \/>\nO ministro da Economia Paulo Guedes, sem saber que estava sendo gravado, deu uma s\u00e9rie de declara\u00e7\u00f5es catastr\u00f3ficas. A repercuss\u00e3o foi p\u00e9ssima e abriu mais uma pol\u00eamica no governo.<\/p>\n<p><strong>MANDOU BEM<\/strong><br \/>\nO ministro Marco Aur\u00e9lio Mello, do Supremo Tribunal Federal, mandou que o governo realize o Censo neste ano. As informa\u00e7\u00f5es s\u00e3o important\u00edssimas para a an\u00e1lise do quadro social brasileiro e para a formula\u00e7\u00e3o de pol\u00edtica p\u00fablicas<\/p>\n<p><strong>A PERGUNTA QUE N\u00c3O QUER CALAR<\/strong><br \/>\nO Brasil conseguir\u00e1 barrar as fraudes e irregularidades nos cadastros para a vacina\u00e7\u00e3o de pessoas com comorbidades?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Coluna Eixo Capital, por Alexandre de Paula Mesmo com os desentendimentos no \u00faltimo fechamento do com\u00e9rcio no DF, a rela\u00e7\u00e3o do governador Ibaneis Rocha (MDB) e do presidente Jair Bolsonaro (sem partido) est\u00e1 apaziguada. Segundo fontes pr\u00f3ximas ao emebista, Ibaneis gosta de Bolsonaro, mas quer manter-se independente nas decis\u00f5es locais. Apesar da paz, o governador lan\u00e7ou a proposta, em reuni\u00e3o [&hellip;]<\/p>\n","protected":false},"author":75,"featured_media":18436,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2089,6],"tags":[1143,16,966,1415],"class_list":["post-21287","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eixo-capital","category-noticias","tag-bolsonaro","tag-gdf","tag-ibaneis","tag-mdb"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/21287","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/users\/75"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/comments?post=21287"}],"version-history":[{"count":2,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/21287\/revisions"}],"predecessor-version":[{"id":21291,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/21287\/revisions\/21291"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media\/18436"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media?parent=21287"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/categories?post=21287"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/tags?post=21287"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}