{"id":21265,"date":"2021-04-26T07:11:33","date_gmt":"2021-04-26T10:11:33","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/?p=21265"},"modified":"2021-04-26T07:11:33","modified_gmt":"2021-04-26T10:11:33","slug":"partidos-buscam-via-alternativa-a-ibaneis-e-a-ao-pt-para-as-eleicoes-do-df","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/partidos-buscam-via-alternativa-a-ibaneis-e-a-ao-pt-para-as-eleicoes-do-df\/","title":{"rendered":"Partidos buscam via alternativa a Ibaneis e a ao PT para as elei\u00e7\u00f5es do DF"},"content":{"rendered":"<p><strong>Coluna Eixo capital por Ana Dubeux<\/strong><\/p>\n<p>Primeiro foi Jos\u00e9 Roberto Arruda. Em 1998, o ent\u00e3o senador criou a Terceira Via na disputa pelo Buriti. Acabou fora do segundo turno, disputado por Cristovam Buarque e Joaquim Roriz, vencedor do pleito. Hoje, setores que n\u00e3o se alinham nem com o atual governador, Ibaneis Rocha, nem com o PT e seus partidos sat\u00e9lites tamb\u00e9m buscam um caminho alternativo. O movimento, ainda sem nome, quer mostrar por que \u00e9 diferente das for\u00e7as que dominam a pol\u00edtica local nas \u00faltimas d\u00e9cadas.<\/p>\n<p><strong>Olhos de cobi\u00e7a<\/strong><br \/>\nCeil\u00e2ndia, sempre bom lembrar, \u00e9 ber\u00e7o pol\u00edtico de tradi\u00e7\u00e3o no DF. Basta dizer que \u00e9 a base eleitoral de Maria de Lourdes Abadia, cuja trajet\u00f3ria se confunde com a da cidade. Ceil\u00e2ndia tamb\u00e9m foi uma importante etapa na trajet\u00f3ria de Rog\u00e9rio Rosso, ex-administrador da cidade e governador do DF. O maior col\u00e9gio eleitoral do DF, com nada menos que 290 mil votos, \u00e9 caminho incontorn\u00e1vel para quem busca peso pol\u00edtico no quadrado federal e distrital. N\u00e3o \u00e0 toa, o presidente Jair Bolsonaro \u2014 que ainda ignora a import\u00e2ncia do uso da m\u00e1scara, passeou por l\u00e1 neste s\u00e1bado. Ser\u00e1 ali um dos seus redutos.<\/p>\n<h3>Bras\u00edlia no Oscar nacional<\/h3>\n<p>A s\u00e9rie <em>Em nome dos pais<\/em>, da HBO, \u00e9 finalista na categoria \u201cdocument\u00e1rio de TV\u201d do Grande Pr\u00eamio do Cinema Brasileiro, o \u201cOscar\u201d nacional. Ele \u00e9 baseado no livro do jornalista brasiliense Matheus Leit\u00e3o, que narra como localizou a pessoa que entregou seus pais, Miriam Leit\u00e3o e Marcelo Netto, para a tortura na ditadura militar.<\/p>\n<p><strong>Jerusalema pra relaxar<\/strong><br \/>\nOs profissionais do posto de sa\u00fade da 23 do Lago Sul est\u00e3o treinando a Jerusalema, depois do expediente, para relaxar da covid. O Jerusalema Challenge \u00e9 um desafio de dan\u00e7a que surgiu em Angola, viralizou nas redes sociais e ganhou a ades\u00e3o de diversas equipes de trabalho de diferentes partes do mundo.<\/p>\n<p><strong>Stock Car em alta<\/strong><br \/>\nO BRB vai manter o Aut\u00f3dromo de Bras\u00edlia como neg\u00f3cio e n\u00e3o apenas atuar como patrocinador. O sucesso da parceria com o Flamengo \u2014 que se refletiu na abertura de mais de 300 mil novas contas \u2014 \u00e9 o espelho da nova frente de investimento. O BRB vai receber o aut\u00f3dromo da Terracap esta semana e iniciar as reformas para que, ainda este ano, seja reinaugurado em 12 de dezembro, na etapa final do campeonato do Stock Car. O planejamento \u00e9 se associar a uma empresa com expertise em corridas e j\u00e1, a partir do ano que vem, sediar v\u00e1rias provas. E \u00e9 claro que j\u00e1 se pensa na cria\u00e7\u00e3o de um cart\u00e3o espec\u00edfico para os f\u00e3s do automobilismo.<\/p>\n<p><strong>Bloco na rua<\/strong><br \/>\nThais Riedel, mestre em direito previdenci\u00e1rio, \u00e9 candidata \u00e0 presid\u00eancia da OAB-DF. \u201c\u00c9 hora de sermos propositivos. Os advogados est\u00e3o descuidados, desamparados. A situa\u00e7\u00e3o de muitos profissionais ante a pandemia de coronav\u00edrus \u00e9 muito grave\u201d, queixa-se a advogada.<\/p>\n<p><strong>Roriz vive<\/strong><br \/>\nCom a entrega do \u00faltimo dos 23 viadutos que comp\u00f5em a nova sa\u00edda norte do DF, marcada para a pr\u00f3xima quinta-feira, o GDF vai homenagear o ex-governador Joaquim Roriz. O local passa a se chamar Complexo Vi\u00e1rio Governador Roriz. A fam\u00edlia do pol\u00edtico foi convidada para a solenidade de entrega \u2014 uma cerim\u00f4nia simples como conv\u00e9m aos tempos atuais. Dona Weslian e as filhas Wesliane e Jacqueline confirmaram presen\u00e7a.<\/p>\n<p><strong>O que eles disseram<\/strong><\/p>\n<p>Em meio \u00e0 pandemia, o brasiliense vem se adaptando \u00e0s restri\u00e7\u00f5es e buscando solu\u00e7\u00f5es para enfrentar esse momento.<\/p>\n<p>\u201cDepois de um ano, o novo coronav\u00edrus ainda assusta o mundo todo. Momento dif\u00edcil, em que a popula\u00e7\u00e3o carente fica ainda mais vulner\u00e1vel. Por isso, temos nos esfor\u00e7ado para pagar em dia os benef\u00edcios sociais, como o Prato Cheio e o DF Sem Mis\u00e9ria, para que possam amenizar os efeitos econ\u00f4micos potencializados por essa pandemia\u201d.<br \/>\n<em>Mayara Noronha Rocha, secret\u00e1ria de Desenvolvimento Social e primeira-dama<\/em><\/p>\n<p>\u201cAs doen\u00e7as desconhecidas s\u00e3o a maior amea\u00e7a ao futuro da humanidade. O homo sapiens, em termos c\u00f3smicos, \u00e9 uma esp\u00e9cie recente: 70 mil anos. Dizem os dem\u00f3grafos que as pandemias dizimaram milh\u00f5es de esp\u00e9cies e seres ao longo da hist\u00f3ria da Terra. Mas a pandemia do coronav\u00edrus \u00e9 a maior e mais letal trag\u00e9dia, que mexeu no corpo e na alma da sociedade, transformando o homem e seus sentimentos de amor de \u00f3dio, de alegria e de medo. Mas estamos vendo despertar uma sociedade de solidariedade, mais humana. Todos os cientistas do mundo se uniram e nos salvaram com a ci\u00eancia e o esfor\u00e7o para vencer essa trag\u00e9dia, que amea\u00e7ava extinguir a sociedade. Vamos sobreviver. \u00c9 hora de uni\u00e3o, caridade e esperan\u00e7a\u201d.<br \/>\n<em>Jos\u00e9 Sarney, ex-presidente da Rep\u00fablica<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Setores que n\u00e3o se alinham nem com o atual governador, Ibaneis Rocha, nem com o PT e seus partidos sat\u00e9lites tamb\u00e9m buscam um caminho alternativo<\/p>\n","protected":false},"author":118,"featured_media":21266,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2089],"tags":[2810,286,311,2809,966,468],"class_list":["post-21265","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eixo-capital","tag-autodramo","tag-brb","tag-eleicoes","tag-em-nome-dos-pais","tag-ibaneis","tag-joaquim-roriz"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/21265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/users\/118"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/comments?post=21265"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/21265\/revisions"}],"predecessor-version":[{"id":21267,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/21265\/revisions\/21267"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media\/21266"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media?parent=21265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/categories?post=21265"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/tags?post=21265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}