{"id":20751,"date":"2021-02-25T22:11:30","date_gmt":"2021-02-26T01:11:30","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/?p=20751"},"modified":"2021-02-25T22:17:50","modified_gmt":"2021-02-26T01:17:50","slug":"ibaneis-decreta-lockdown-no-df-entre-20h-e-5h","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/ibaneis-decreta-lockdown-no-df-entre-20h-e-5h\/","title":{"rendered":"Ibaneis decreta lockdown no DF entre 20h e 5h"},"content":{"rendered":"<h4>ANA MARIA CAMPOS<\/h4>\n<p>O governador Ibaneis Rocha (MDB) decidiu agora \u00e0 noite (25\/02) adotar medidas restritivas para evitar a amplia\u00e7\u00e3o da prolifera\u00e7\u00e3o da covid-19 no DF. A partir de segunda-feira (01\/03), toda a atividade econ\u00f4mica na cidade ficar\u00e1 fechada de 20h \u00e0s 5h, com exce\u00e7\u00e3o de servi\u00e7os essenciais.<\/p>\n<p>&nbsp;<\/p>\n<p>A medida atinge principalmente lojas, restaurantes e bares. Ibaneis foi informado de que a ocupa\u00e7\u00e3o dos leitos em UTI chegou a um n\u00edvel preocupante, pr\u00f3ximo do colapso, superior a 90%.<\/p>\n<p>&nbsp;<\/p>\n<p>Por isso, ele tomou essa decis\u00e3o, depois de passar os \u00faltimos dias tentando evitar o lockdown que atinge fortemente a atividade econ\u00f4mica no DF.<\/p>\n<p>&nbsp;<\/p>\n<p>O decreto com os detalhes das regras de restri\u00e7\u00f5es deve ser publicado na edi\u00e7\u00e3o desta sexta-feira (26\/02) do Di\u00e1rio Oficial do DF.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ANA MARIA CAMPOS O governador Ibaneis Rocha (MDB) decidiu agora \u00e0 noite (25\/02) adotar medidas restritivas para evitar a amplia\u00e7\u00e3o da prolifera\u00e7\u00e3o da covid-19 no DF. A partir de segunda-feira (01\/03), toda a atividade econ\u00f4mica na cidade ficar\u00e1 fechada de 20h \u00e0s 5h, com exce\u00e7\u00e3o de servi\u00e7os essenciais. &nbsp; A medida atinge principalmente lojas, restaurantes e bares. Ibaneis foi informado [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":20491,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[234],"tags":[2151,2424,966,2376],"class_list":["post-20751","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cb-poder","tag-covid-19","tag-fechamento","tag-ibaneis","tag-lockdown"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/20751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/comments?post=20751"}],"version-history":[{"count":2,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/20751\/revisions"}],"predecessor-version":[{"id":20753,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/20751\/revisions\/20753"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media\/20491"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media?parent=20751"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/categories?post=20751"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/tags?post=20751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}