{"id":20122,"date":"2020-11-16T11:59:53","date_gmt":"2020-11-16T14:59:53","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/?p=20122"},"modified":"2020-11-16T11:59:54","modified_gmt":"2020-11-16T14:59:54","slug":"pirenopolis-eleicao-terminara-tribunais","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/pirenopolis-eleicao-terminara-tribunais\/","title":{"rendered":"Em Pirenop\u00f3lis, disputa pela prefeitura terminar\u00e1 nos tribunais"},"content":{"rendered":"<h5>Coluna Eixo Capital por Ana Maria Campos<\/h5>\n<div>Em Piren\u00f3polis, a elei\u00e7\u00e3o vai terminar nos tribunais. O candidato mais votado, Nivaldo Melo (PP), com 64,33% dos votos, est\u00e1 sub-judice. Ao examinar as contas de Nivaldo, na prefeitura de Piren\u00f3polis, o TCU constatou que ele aplicou mal dinheiro do governo federal.<br \/>\n<strong><br \/>\nMoro X PSol<\/strong><\/div>\n<div><\/div>\n<div>An\u00e1lise do ex-ministro da Justi\u00e7a e Seguran\u00e7a P\u00fablica e ex-juiz S\u00e9rgio Moro sobre as elei\u00e7\u00f5es municipais de ontem: \u201cO resultado das elei\u00e7\u00f5es municipais foi fragmentado, sem um claro vencedor nacional, o que sinaliza a preval\u00eancia do interesse local. H\u00e1 alguns resultados interessantes: os candidatos apoiados pela Presid\u00eancia fracassaram e o Psol tornou-se o partido de esquerda mais relevante\u201d. Em outras palavras, a polariza\u00e7\u00e3o Bolsonaro X Lula ficou enfraquecida na vis\u00e3o de Moro, que sonha em se tornar uma alternativa de direita ou centro-direita para o Planalto em 2022. Contra o Psol.<\/p>\n<div><strong>Apoio de dois governadores<\/strong><\/div>\n<div><\/div>\n<div>Em Luzi\u00e2nia, terra do rorizismo, venceu o candidato apoiado pelos governadores Ibaneis Rocha (MDB) e Ronaldo Caiado (DEM): o deputado estadual Diego Sorgatto (DEM).<\/p>\n<p><strong><br \/>\n<\/strong><\/p>\n<div><strong>Ibaneis vence no Piau\u00ed<\/strong><\/div>\n<div><\/div>\n<div>Aliado do governador Ibaneis Rocha, o prefeito de Corrente, Murilo (PP), se reelegeu com mais de 45% dos votos. No munic\u00edpio, Ibaneis tem fazenda e ajudou com doa\u00e7\u00f5es do GDF de 22,5 mil equipamentos de prote\u00e7\u00e3o individual (EPIs). Foi na cidade que o governador passou a inf\u00e2ncia.<\/p>\n<p><strong><br \/>\n<\/strong><\/p>\n<div><strong>Derrota nas urnas<\/strong><\/div>\n<div><\/div>\n<div>N\u00e3o foi desta vez que o deputado Agaciel Maia (PL) se tornou \u201cprimeiro-marido\u201d de Jardim de Piranhas (RN).<\/div>\n<div>A mulher do distrital, S\u00e2nzia Maia (PL), teve apenas 1.082 votos, correspondentes a 12,75% dos votos no munic\u00edpio, e perdeu para Rog\u00e9rio Couro Fino (MDB). O emedebista teve 6.808 votos, mais de 80%, e levou a prefeitura do pequeno munic\u00edpio do<\/div>\n<div>Rio Grande do Norte.<\/p>\n<div><\/div>\n<div><strong>Bolsonaro X Marielle<\/strong><\/div>\n<div><strong>\u00a0<\/strong><\/div>\n<div>Independentemente de qualquer crise, o Rio de Janeiro \u00e9 territ\u00f3rio de Jair Bolsonaro. O filho 02, Carlos Bolsonaro, foi o segundo vereador mais votado na capital, embora esteja muito mais focado no mandato do pai. Marcelo Crivella (Republicanos) foi para o segundo turno na disputa \u00e0 reelei\u00e7\u00e3o. Mas o candidato do PSol \u00e0 C\u00e2mara Municipal, Tarc\u00edsio Mota, foi eleito o vereador o mais votado, uma homenagem a Marielle Franco (PSol).<\/p>\n<div><strong>Voto \u00fatil<\/strong><\/div>\n<div><\/div>\n<div>Dif\u00edcil acreditar que o ex-presidente Luiz In\u00e1cio Lula da Silva, no sigilo da urna, tenha optado pelo voto no candidato de seu partido, Jilmar Tatto (PT), quando Boulos \u00e9 quem tinha condi\u00e7\u00f5es de chegar no segundo turno na disputa pela Prefeitura de S\u00e3o Paulo.<\/p>\n<p><strong><br \/>\n<\/strong><\/p>\n<div><strong>PT perde protagonismo<\/strong><\/div>\n<div><\/div>\n<div>O desempenho de Boulos (PSol) em S\u00e3o Paulo e de Manuela D\u2019\u00c1vila (PCdoB) tira do PT o protagonismo da esquerda no pa\u00eds. Nos \u00faltimos 35 anos, essa \u00e9 a primeira vez que os petistas n\u00e3o est\u00e3o no segundo turno das elei\u00e7\u00f5es na principal capital do pa\u00eds. Em Porto Alegre, tamb\u00e9m sempre foram fortes. Manuela e Boulos est\u00e3o no segundo turno.<\/p>\n<div><\/div>\n<div><strong>Heran\u00e7a baiana<\/strong><\/div>\n<div><\/div>\n<div>A fam\u00edlia de ACM continua forte em Salvador. O prefeito ACM Neto (DEM) fez o sucessor no primeiro turno: o atual vice-prefeito, Bruno Reis (DEM), com 63,61% dos votos.<\/p>\n<p><strong><br \/>\n<\/strong><\/p>\n<div><strong>Tiros na\u00a0<\/strong><strong>Justi\u00e7a Eleitoral<\/strong><\/div>\n<div><\/div>\n<div>Os bolsonaristas v\u00e3o deitar e rolar com as dificuldades de ontem na apura\u00e7\u00e3o das elei\u00e7\u00f5es. Refor\u00e7a a tese de vulnerabilidade das urnas. A deputada Bia Kicis (PSL-DF) atirou: \u201cA Justi\u00e7a Eleitoral existe s\u00f3 para cuidar das elei\u00e7\u00f5es. Faz dois anos da \u00faltima elei\u00e7\u00e3o e na hora H ela falha. Mas est\u00e1 tudo normal&#8230;\u201d<\/p>\n<div><strong>Disputa em fam\u00edlia\u00a0<\/strong><\/div>\n<div><\/div>\n<div>Dois descendentes de Miguel Arraes, um dos mais importantes l\u00edderes pol\u00edticos de Pernambuco, disputam a prefeitura de Recife. Aos 26 anos, o deputado federal Jo\u00e3o Campos (PSE-PE), filho e herdeiro pol\u00edtico de Eduardo Campos, disputar\u00e1 o segundo turno com a prima, Mar\u00edlia Arraes (PT). A deputada federal de 36 anos \u00e9 neta de Arraes. A diferen\u00e7a entre os dois foi de apenas 9.780 votos, correspondente a 1,22% dos votos v\u00e1lidos.<\/p>\n<p><strong><br \/>\n<\/strong><\/p>\n<div><strong>Polariza\u00e7\u00e3o de esquerda<\/strong><\/div>\n<div><\/div>\n<div>Aliado e amigo de Eduardo Campos, que morreu na campanha presidencial de 2014, o ex-governador Rodrigo Rollemberg (PSB) acredita na vit\u00f3ria de Jo\u00e3o Campos. Para Rollemberg, a elei\u00e7\u00e3o em Recife tem um significado importante: \u201cMinha avalia\u00e7\u00e3o \u00e9 de que, salvo engano, Recife \u00e9 a \u00fanica cidade que vai ter o segundo turno entre dois candidatos de esquerda, PSB e PT\u201d, disse. \u201cVai ser um grande desafio a forma como vai se dar esse segundo turno porque, dependendo da forma como ocorrer, pode afastar ainda mais o PSB e o PT. Temos que aguardar, mas acredito muito na vit\u00f3ria do Jo\u00e3o Campos em Recife\u201d.<br \/>\n<strong><\/p>\n<p><\/strong><\/p>\n<div><strong>Namoro apartid\u00e1rio<\/strong><\/div>\n<div><\/div>\n<div>Se Jo\u00e3o Campos vencer em Recife, a capital de Pernambuco ter\u00e1 um prefeito do PSB e uma \u201cprimeira-dama\u201d do DEM. A namorada do candidato \u00e9 a deputada federal T\u00e1bata Amaral (DEM-SP).<\/div>\n<div>\n<div><strong>Mandou bem\u00a0<\/strong><\/div>\n<div><\/div>\n<div>Guilherme Boulos (Psol) foi uma surpresa nas elei\u00e7\u00f5es municipais. Cresceu e derrotou o candidato apoiado pelo presidente Jair Bolsonaro em S\u00e3o Paulo, Celso Russomanno, considerado um dos favoritos na largada. Vai para o segundo turno com Bruno Covas (PSDB) e, mesmo se perder, torna-se uma estrela da esquerda.<\/p>\n<p><strong><br \/>\n<\/strong><\/p>\n<div><strong>Mandou mal\u00a0<\/strong><\/div>\n<div><\/div>\n<div>Fac\u00e7\u00f5es criminosas come\u00e7am a eleger seus candidatos, de acordo com o presidente do TSE, Roberto Barroso. Uma aposta estrat\u00e9gica para que os pol\u00edticos aprovem leis que os beneficiam e facilitem a vida de bandidos para que escapem de puni\u00e7\u00f5es. \u00c9 o crime organizado nas estruturas de poder.<\/p>\n<div>\n<strong>S\u00f3\u00a0papos<\/strong><\/p>\n<div>\u201cNoticiam que TSE foi atacado por hackers. TSE nega. Ent\u00e3o, \u00e9 exposto banco de dados do TSE. Isso traz um clima de inseguran\u00e7a, que faz as pessoas desconfiarem que o atraso na divulga\u00e7\u00e3o possa ser um novo ataque hacker ou manipula\u00e7\u00e3o j\u00e1 que n\u00e3o h\u00e1 transpar\u00eancia\u201d<\/div>\n<div><strong>\u00a0<\/strong><\/div>\n<div><strong>Deputado federal\u00a0<\/strong><\/div>\n<div>Eduardo Bolsonaro (PSL-SP)<\/p>\n<div><\/div>\n<div>\u201cHouve uma tentativa de ataque, hoje, com grande volume de tentativas de acessos simult\u00e2neos. Foi totalmente neutralizado pelo TSE e pelas operadoras de telefonia e, portanto, tamb\u00e9m sem qualquer repercuss\u00e3o sobre o processo de vota\u00e7\u00e3o\u201d<\/div>\n<div><\/div>\n<div><strong>Presidente do TSE,\u00a0<\/strong><\/div>\n<div>ministro Roberto Barroso<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Coluna Eixo Capital por Ana Maria Campos Em Piren\u00f3polis, a elei\u00e7\u00e3o vai terminar nos tribunais. O candidato mais votado, Nivaldo Melo (PP), com 64,33% dos votos, est\u00e1 sub-judice. Ao examinar as contas de Nivaldo, na prefeitura de Piren\u00f3polis, o TCU constatou que ele aplicou mal dinheiro do governo federal. Moro X PSol An\u00e1lise do ex-ministro da Justi\u00e7a e Seguran\u00e7a P\u00fablica [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":20123,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2089,6],"tags":[311,2615,22,2614],"class_list":["post-20122","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eixo-capital","category-noticias","tag-eleicoes","tag-eleicoes-2020","tag-entorno","tag-pirenopolis"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/20122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/comments?post=20122"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/20122\/revisions"}],"predecessor-version":[{"id":20124,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/20122\/revisions\/20124"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media\/20123"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media?parent=20122"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/categories?post=20122"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/tags?post=20122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}