{"id":19947,"date":"2020-10-21T07:31:58","date_gmt":"2020-10-21T10:31:58","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/?p=19947"},"modified":"2020-10-21T07:31:58","modified_gmt":"2020-10-21T10:31:58","slug":"disputa-pelo-comando-da-policia-civil-do-df","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/disputa-pelo-comando-da-policia-civil-do-df\/","title":{"rendered":"Disputa pelo comando da Pol\u00edcia Civil do DF"},"content":{"rendered":"<h6><strong>Coluna Eixo Capital\/Por Ana Maria Campos<\/strong><\/h6>\n<p>A c\u00fapula da Pol\u00edcia Civil do DF ficou incomodada com um movimento pol\u00edtico voltado para substituir o atual diretor-geral, Robson C\u00e2ndido (foto). Ent\u00e3o corregedor-geral, Anderson Espindola era cotado para assumir a chefia. Os nomes j\u00e1 estavam na Casa Civil. Mas o governador Ibaneis Rocha (MDB) decidiu manter Robson na fun\u00e7\u00e3o.<\/p>\n<p>Espindola acabou sendo transferido para a 4\u00aa DP. Ele j\u00e1 foi cotado para o cargo de diretor-geral outras vezes, principalmente no governo Rollemberg, quando foi 02 de Eric Seba. Robson, no entanto, continua forte.<\/p>\n<h3>\n<strong>Luzia fortalece bloco independente<\/strong><\/h3>\n<p>A deputada Luzia de Paula (PSB) aderiu ao bloco independente na C\u00e2mara Legislativa. O grupo agora conta com seis integrantes: Daniel Donizet (PL), Eduardo Pedrosa (PTC), Roosevelt Vilela (PSB), Reginaldo Sardinha (Avante) e Jo\u00e3o Cardoso (Avante). Se votarem sempre unidos, os integrantes do bloco ter\u00e3o for\u00e7a para influenciar qualquer vota\u00e7\u00e3o na Casa.<\/p>\n<h3>\n<strong>Crime com a educa\u00e7\u00e3o<\/strong><\/h3>\n<p>O presidente Jair Bolsonaro quer acabar com um benef\u00edcio dos professores previsto em lei de autoria do ex-senador Cristovam Buarque (Cidadania-DF). A ideia \u00e9 alterar a lei do piso salarial dos professores da educa\u00e7\u00e3o b\u00e1sica, vinculando o reajuste \u00e0 infla\u00e7\u00e3o, com base no pelo INPC (\u00cdndice Nacional de Pre\u00e7os ao Consumidor).<\/p>\n<p>Sancionada em 2008 pelo ent\u00e3o presidente Luiz In\u00e1cio Lula da Silva, a Lei do Piso vincula reajuste anual \u00e0 varia\u00e7\u00e3o do valor por aluno do Fundeb, o que reflete em aumentos acima da infla\u00e7\u00e3o. \u201cO Bolsonaro est\u00e1 cometendo um crime contra a educa\u00e7\u00e3o e os professores\u201d, reclama Cristovam.<\/p>\n<h3>\n<strong>Privatiza\u00e7\u00e3o \u00e9 pol\u00eamica tamb\u00e9m no TCDF<\/strong><\/h3>\n<p>Vai a plen\u00e1rio no TCDF o julgamento sobre a privatiza\u00e7\u00e3o da CEB Distribuidora. Sindicato e organiza\u00e7\u00f5es defendem a obrigatoriedade do tema ser levado para decis\u00e3o da C\u00e2mara Legislativa, enquanto o Governo diz n\u00e3o ser preciso.<\/p>\n<p>A deputada federal Erika Kokay (PT-DF) reuniu-se com a presidente do TCDF, Anilceia Machado, e ouviu que o assunto tamb\u00e9m causa diverg\u00eancias internas no tribunal. A expectativa \u00e9 que o resultado n\u00e3o saia hoje, uma vez que ainda ser\u00e3o feitas as sustenta\u00e7\u00f5es orais antes do relator produzir seu voto.<\/p>\n<h3>\n<strong>Petistas contra a privatiza\u00e7\u00e3o<\/strong><\/h3>\n<p>O PT transformou a privatiza\u00e7\u00e3o da CEB numa bandeira pol\u00edtica de oposi\u00e7\u00e3o. Ontem houve at\u00e9 ato virtual contra a venda da empresa. O evento foi aberto pelo ex-governador Agnelo Queiroz (PT).<\/p>\n<h3>\n<strong>Siga o dinheiro<\/strong><\/h3>\n<p>R$ 23.729.999,96<\/p>\n<p>Valor destinado pelo SLU para contrata\u00e7\u00e3o de empresa Hydros Solu\u00e7\u00f5es Ambientais Ltda para tratamento de chorume gerado no Aterro Sanit\u00e1rio de Bras\u00edlia-ASB, Usina de Tratamento Mec\u00e2nico e Biol\u00f3gico da Ceil\u00e2ndia.<\/p>\n<h3>\n<strong>Melhoras<\/strong><\/h3>\n<p>O l\u00edder do governo na C\u00e2mara Legislativa, Cl\u00e1udio Abrantes (PDT), que recupera-se de covid-19, apresentou melhoras no quadro inflamat\u00f3rio e segue sem febre, internado no Hospital DF Star. A perspectiva de alta \u00e9 para o final desta semana.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Coluna Eixo Capital\/Por Ana Maria Campos A c\u00fapula da Pol\u00edcia Civil do DF ficou incomodada com um movimento pol\u00edtico voltado para substituir o atual diretor-geral, Robson C\u00e2ndido (foto). Ent\u00e3o corregedor-geral, Anderson Espindola era cotado para assumir a chefia. Os nomes j\u00e1 estavam na Casa Civil. Mas o governador Ibaneis Rocha (MDB) decidiu manter Robson na fun\u00e7\u00e3o. Espindola acabou sendo transferido [&hellip;]<\/p>\n","protected":false},"author":90,"featured_media":13388,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2089],"tags":[407,1556],"class_list":["post-19947","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eixo-capital","tag-policia-civil-do-df","tag-robson-candido"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/19947","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/users\/90"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/comments?post=19947"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/19947\/revisions"}],"predecessor-version":[{"id":19948,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/19947\/revisions\/19948"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media\/13388"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media?parent=19947"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/categories?post=19947"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/tags?post=19947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}