{"id":19714,"date":"2020-09-20T10:04:01","date_gmt":"2020-09-20T13:04:01","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/?p=19714"},"modified":"2020-09-20T10:04:25","modified_gmt":"2020-09-20T13:04:25","slug":"df-pessoas-inelegiveis-contas-rejeitadas","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/df-pessoas-inelegiveis-contas-rejeitadas\/","title":{"rendered":"No DF, 318 pessoas est\u00e3o ineleg\u00edveis por causa de contas rejeitadas"},"content":{"rendered":"<h5>Coluna Eixo Capital \/ Por Ana Maria Campos<\/h5>\n<p>O TCU enviou ao TSE a lista de pessoas com as contas rejeitadas que est\u00e3o ineleg\u00edveis. No DF, s\u00e3o 318. Entre os listados, nomes conhecidos em casos de ind\u00edcios de irregularidades, como o ex-reitor da UnB Timothy Mulhohand, o ex-secret\u00e1rio de Trabalho Wigberto Tartuce (foto), o ex-PM Jo\u00e3o Dias, e o empres\u00e1rio Mauro Dutra. No pa\u00eds inteiro, s\u00e3o 7.351 ineleg\u00edveis.<\/p>\n<h3>Secret\u00e1rio de Sa\u00fade vai prestar esclarecimentos na C\u00e2mara<\/h3>\n<p>Em meio a um debate sobre a cria\u00e7\u00e3o da CPI da Pandemia, Osnei Okumoto, confirmado na semana passada como secret\u00e1rio de Sa\u00fade, topou participar de uma audi\u00eancia com os deputados distritais. Ser\u00e1 por teleconfer\u00eancia, nesta quarta-feira. A C\u00e2mara aprovou um requerimento para a ida de Osnei, de autoria do deputado F\u00e1bio F\u00e9lix (PSol). O presidente da Casa, Rafael Prudente (MDB), pediu aos parlamentares que encaminhem os questionamentos que desejam fazer durante o encontro para que Okumoto possa prestar os esclarecimentos. Ele reassumiu o cargo depois que o antecessor, Francisco Ara\u00fajo Filho, foi preso preventivamente e denunciado por peculato, no \u00e2mbito da Opera\u00e7\u00e3o Falso Negativo.<\/p>\n<h3>Nem com 13 assinaturas<\/h3>\n<p>Mesmo que o PSB consiga convencer o deputado Jos\u00e9 Gomes a assinar o requerimento para cria\u00e7\u00e3o da CPI da Pandemia, dificilmente a investiga\u00e7\u00e3o ser\u00e1 iniciada. Os 13 votos n\u00e3o ser\u00e3o suficientes para furar a fila das CPIs e a articula\u00e7\u00e3o dos governistas.<\/p>\n<h3>Cota para trans<\/h3>\n<p>Tramita na C\u00e2mara Legislativa um projeto de iniciativa do deputado F\u00e1bio F\u00e9lix (PSol) que garante reserva de vagas de emprego para pessoas autodeclaradas trans, travestis, transexuais e transg\u00eaneros. Empresas que recebem incentivos fiscais ou que mantenham contrato ou conv\u00eanio com o Poder P\u00fablico do Distrito Federal dever\u00e3o contratar pessoas trans na propor\u00e7\u00e3o de no m\u00ednimo 5% do total de seus empregados.<\/p>\n<blockquote>\n<h3>S\u00f3 papos<\/h3>\n<p>\u201cVoc\u00eas n\u00e3o pararam durante a pandemia. Voc\u00eas n\u00e3o entraram naquela conversinha mole de \u2018fique em casa, que a economia a gente v\u00ea depois\u2019. Isso \u00e9 para os fracos\u201d<\/p>\n<p>Presidente Jair Bolsonaro,<br \/>\nem discurso para produtores rurais no Mato Grosso<\/p>\n<p>\u201cBolsonaro, \u2018fraco\u2019 \u00e9 presidente que se elege fugindo de debates. Fraco e covarde\u201d<\/p>\n<p>Deputada federal \u00c9rika Kokay (PT), pelo Twitter<\/p><\/blockquote>\n<h3>Mandou bem<\/h3>\n<p>A 10\u00aa edi\u00e7\u00e3o do boletim produzido pelo Observat\u00f3rio de predi\u00e7\u00e3o e acompanhamento da epidemia Covid-19 (PrEpidemia), da Universidade de Bras\u00edlia (UnB), divulgada na semana passada, apontou uma desacelera\u00e7\u00e3o na transmiss\u00e3o da doen\u00e7a no Distrito Federal.<\/p>\n<h3>Mandou mal<\/h3>\n<p>Chegou a segunda onda na Europa: mais da metade dos pa\u00edses do bloco registrou aumento de casos de covid-19 e m\u00e9dia semanal ultrapassou 300 mil novos infectados, maior do que no 1\u00b0 pico da pandemia em mar\u00e7o. OMS alerta para risco de aumento de mortes em outubro e novembro.<\/p>\n<h3>Enquanto isso&#8230;<br \/>\nNa sala de Justi\u00e7a<\/h3>\n<p>A composi\u00e7\u00e3o do Conselho Nacional do Minist\u00e9rio P\u00fablico (CNMP) foi atingida pela pandemia do novo coronav\u00edrus. Tr\u00eas conselheiros j\u00e1 sabatinados pela CCJ do Senado esperam h\u00e1 meses pela delibera\u00e7\u00e3o do plen\u00e1rio. Um deles \u00e9 o promotor de Justi\u00e7a Moacyr Rey Filho, chefe de gabinete da procuradora-geral de Justi\u00e7a do DF, Fabiana Costa, indicado para o assento do Minist\u00e9rio P\u00fablico do DF no CNMP em novembro do ano passado. Outros dois integrantes est\u00e3o na mesma situa\u00e7\u00e3o: Ediene Lousado, para vaga do Minist\u00e9rio P\u00fablico Estadual e o juiz Paulo Marcos de Farias, indicado pelo STF. A Associa\u00e7\u00e3o Nacional dos Procuradores da Rep\u00fablica (ANPR) entrou com uma a\u00e7\u00e3o de descumprimento de preceito constitucional no STF, questionando a demora do Senado, apontada como um \u201cbloqueio deliberado\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Coluna Eixo Capital \/ Por Ana Maria Campos O TCU enviou ao TSE a lista de pessoas com as contas rejeitadas que est\u00e3o ineleg\u00edveis. No DF, s\u00e3o 318. Entre os listados, nomes conhecidos em casos de ind\u00edcios de irregularidades, como o ex-reitor da UnB Timothy Mulhohand, o ex-secret\u00e1rio de Trabalho Wigberto Tartuce (foto), o ex-PM Jo\u00e3o Dias, e o empres\u00e1rio [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":6740,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2089,6],"tags":[2263,1346,867],"class_list":["post-19714","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eixo-capital","category-noticias","tag-distrito-federal","tag-eixo-capital","tag-tcu"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/19714","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/comments?post=19714"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/19714\/revisions"}],"predecessor-version":[{"id":19715,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/19714\/revisions\/19715"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media\/6740"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media?parent=19714"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/categories?post=19714"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/tags?post=19714"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}