{"id":17790,"date":"2020-03-16T07:32:39","date_gmt":"2020-03-16T10:32:39","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/?p=17790"},"modified":"2020-03-16T07:35:50","modified_gmt":"2020-03-16T10:35:50","slug":"na-pandemia-do-coronavirus-a-importancia-do-sistema-de-saude","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/na-pandemia-do-coronavirus-a-importancia-do-sistema-de-saude\/","title":{"rendered":"Na pandemia do coronav\u00edrus, a import\u00e2ncia do sistema de sa\u00fade"},"content":{"rendered":"<h6><strong>Coluna Eixo Capital\/Por Ana Maria Campos<\/strong><\/h6>\n<p>Ao adotar medidas como suspender aulas, eventos, aglomera\u00e7\u00f5es e separar mesas em bares e restaurantes, o governador Ibaneis Rocha (MDB) levou em conta um aspecto importante que pode ser fundamental para salvar vidas: \u00e9 preciso preparar o sistema de sa\u00fade para receber os pacientes. Sem isso, o que \u00e9 simples pode se tornar letal. Os hospitais, superlotados com doentes de coronav\u00edrus, ficar\u00e3o sem condi\u00e7\u00f5es de receber um infartado, um acidentado, um paciente com AVC ou mesmo de internar quem est\u00e1 com Covid-19.<\/p>\n<p>Ao anunciar as primeiras medidas, Ibaneis disse que n\u00e3o tinha sequer kits suficientes para exames de coronav\u00edrus e a rede p\u00fablica do DF, ele admitiu, n\u00e3o est\u00e1 preparada para uma pandemia. Nenhuma est\u00e1. Por isso, a import\u00e2ncia de retardar o pico do surto, preparar a Casa e tratar os doentes. Assim, ser\u00e1 menos traum\u00e1tico passar por esse furac\u00e3o.<\/p>\n<h2><strong>Livre do corona<\/strong><\/h2>\n<p>A senadora Leila Barros (PSB-DF) fez o teste para coronav\u00edrus e deu negativo. Depois que o exame do senador Nelsinho Trad deu positivo, o presidente do Senado, Davi Alcolumbre, pediu que os colegas procurassem um laborat\u00f3rio rapidamente.<\/p>\n<h2><strong>Manuten\u00e7\u00e3o<\/strong><\/h2>\n<p>Entre as medidas anunciadas pelo governador Ibaneis Rocha (MDB) para melhorar o atendimento \u00e0 popula\u00e7\u00e3o no surto de coronav\u00edrus est\u00e1 a manuten\u00e7\u00e3o predial dos hospitais. S\u00e3o pequenas obras. Esse servi\u00e7o n\u00e3o era feito. Precisava esperar grandes reformas.<\/p>\n<h2><strong>Focado<\/strong><\/h2>\n<p>Ibaneis Rocha est\u00e1 trabalhando em ritmo fren\u00e9tico nesse epis\u00f3dio do surto de coronav\u00edrus. A equipe est\u00e1 at\u00e9 com dificuldades para acompanh\u00e1-lo. Foi assim que o Distrito Federal tomou a decis\u00e3o de suspender aulas e aglomera\u00e7\u00f5es. Em seguida, v\u00e1rios estados seguiram a receita.<\/p>\n<h2><strong>Na TV<\/strong><\/h2>\n<p>O jornalista politico Jair de Farias volta \u00e0 telinha depois de anos de aus\u00eancia. Estreou ontem na TV Brasilia, \u00e0s 13h, o programa Brasilia em Debates, com a pauta permanente de discuss\u00e3o do futuro da cidade. Seus convidados foram Cristovam Buarque e Paulo Oct\u00e1vio, a deputada federal Paula Belmonte (Cidadania-DF), a distrital Julia Lucy (Novo) e a presidente do Sabin, Lidia Abdalla.<\/p>\n<blockquote><p>\u201cAt\u00e9 que ponto chegar\u00e3o? \u00c9 inacredit\u00e1vel. Soltar criminosos e dane-se a popula\u00e7\u00e3o\u201d<\/p><\/blockquote>\n<p style=\"text-align: right\"><strong>Vereador Carlos Bolsonaro<\/strong>, sobre pedido da Pastoral Carcer\u00e1ria para que presos sejam liberados como forma de evitar epidemia de coronav\u00edrus nas pris\u00f5es<\/p>\n<blockquote><p>\u201cSe voc\u00eas realmente n\u00e3o gostassem de criminosos n\u00e3o teriam tantos amigos e c\u00famplices milicianos\u201d<\/p><\/blockquote>\n<p style=\"text-align: right\"><strong>Marivaldo Pereira<\/strong>, ex-secret\u00e1rio-executivo do Minist\u00e9rio da Justi\u00e7a no governo Dilma e candidato ao Senado pelo PSOL em 2018<\/p>\n<h2><strong>Mandou bem<\/strong><\/h2>\n<p>O governador Ibaneis Rocha saiu na frente de gestores de outros estados e tomou diversas medidas para conter a dissemina\u00e7\u00e3o do coronav\u00edrus no DF.<\/p>\n<h2><strong>Mandou mal<\/strong><\/h2>\n<p>O presidente Jair Bolsonaro foi desrespeitoso com quem est\u00e1 doente ao dar uma banana p\u00fablica depois de testar negativo para o coronav\u00edrus.<\/p>\n<h2><strong>A pergunta que n\u00e3o quer calar\u2026.<\/strong><\/h2>\n<p>Imaginem um surto de coronav\u00edrus h\u00e1 um m\u00eas, durante o carnaval?<\/p>\n<h2><strong>Enquanto isso&#8230;Na sala de Justi\u00e7a<\/strong><\/h2>\n<p>O ministro da Justi\u00e7a e Seguran\u00e7a P\u00fablica, Sergio Moro, estuda adotar a coleta e a interna\u00e7\u00e3o compuls\u00f3rias em caso de resist\u00eancia aos exames para testar coronav\u00edrus. A iniciativa j\u00e1 foi adotada por decreto do governador Ibaneis Rocha, depois que a Justi\u00e7a deferiu liminar em a\u00e7\u00e3o da Procuradoria-geral do Distrito Federal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Coluna Eixo Capital\/Por Ana Maria Campos Ao adotar medidas como suspender aulas, eventos, aglomera\u00e7\u00f5es e separar mesas em bares e restaurantes, o governador Ibaneis Rocha (MDB) levou em conta um aspecto importante que pode ser fundamental para salvar vidas: \u00e9 preciso preparar o sistema de sa\u00fade para receber os pacientes. Sem isso, o que \u00e9 simples pode se tornar letal. [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":17791,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2089],"tags":[2085,917],"class_list":["post-17790","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eixo-capital","tag-coronavirus","tag-ibaneis-rocha"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/17790","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/comments?post=17790"}],"version-history":[{"count":2,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/17790\/revisions"}],"predecessor-version":[{"id":17794,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/17790\/revisions\/17794"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media\/17791"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media?parent=17790"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/categories?post=17790"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/tags?post=17790"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}