{"id":17783,"date":"2020-03-15T21:16:20","date_gmt":"2020-03-16T00:16:20","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/?p=17783"},"modified":"2020-03-15T21:16:20","modified_gmt":"2020-03-16T00:16:20","slug":"ibaneis-quer-reduzir-imposto-para-alcool-em-gel-luvas-e-mascaras","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/ibaneis-quer-reduzir-imposto-para-alcool-em-gel-luvas-e-mascaras\/","title":{"rendered":"Ibaneis quer reduzir imposto para \u00e1lcool em gel, luvas e m\u00e1scaras"},"content":{"rendered":"<h5>ANA MARIA CAMPOS<\/h5>\n<h5>AGATHA GONZAGA<\/h5>\n<p>Projeto de lei do governador Ibaneis Rocha (MDB) estabelece al\u00edquota de 7% para produtos essenciais no combate \u00e0 dissemina\u00e7\u00e3o do coronav\u00edrus. A proposta ser\u00e1 encaminhada nesta segunda-feira (16\/03) \u00e0 C\u00e2mara Legislativa.<\/p>\n<p>&nbsp;<\/p>\n<p>S\u00e3o eles: \u00e1lcool em gel, insumos para fabricar \u00e1lcool em gel (exceto energia el\u00e9trica), luvas m\u00e9dicas, m\u00e1scaras m\u00e9dicas, hipoclorito de s\u00f3dio 5%, \u00e1lcool 70%. Hoje a al\u00edquota do ICMS para esses produtos \u00e9 de 18%.<\/p>\n<p>&nbsp;<\/p>\n<p>Pelo projeto, a redu\u00e7\u00e3o valer\u00e1 durante o tempo em que estiver em vigor a recomenda\u00e7\u00e3o da Organiza\u00e7\u00e3o Mundial de Sa\u00fade (OMS) para que os pa\u00edses tomem cuidados com o novo coronav\u00edrus como uma pandemia. \u201cEstamos fazendo a nossa parte para reduzir o pre\u00e7o desses produtos essenciais num momento como esse. Esperamos que esse esfor\u00e7o seja percebido no pre\u00e7o nas prateleiras\u201d, afirmou o secret\u00e1rio de Economia do DF, Andr\u00e9 Clemente.<\/p>\n<p><strong>Linha de cr\u00e9dito<\/strong><\/p>\n<p>Ibaneis Rocha informou em v\u00eddeo gravado do Pal\u00e1cio do Buriti, na noite deste domingo (15\/03), as medidas tomadas. \u201cEstamos encaminhando na manh\u00e3 de amanh\u00e3 um projeto de lei |\u00e0 C\u00e2mara Legislativa reduzindo a tributa\u00e7\u00e3o sobre os produtos que ajudam na preven\u00e7\u00e3o. \u00c1lcool, luvas, m\u00e1scaras\u2026 Estamos todos trabalhando\u201d, definiu.<\/p>\n<p>&nbsp;<\/p>\n<p>Al\u00e9m desta medida o governador comentou sobre a suspens\u00e3o do passe livre estudantil para complementar a suspens\u00e3o de aulas nos pr\u00f3ximos 15 dias. Segundo Ibaneis o benef\u00edcio s\u00f3 ser\u00e1 revisto para casos de est\u00e1gio remunerado.<\/p>\n<p>Sobre os impactos na economia, e os preju\u00edzos sofridos por comerciantes diante das consequ\u00eancias dos tr\u00eas decretos at\u00e9 agora publicados, o governador informou a disposi\u00e7\u00e3o do BRB de liberar R$ 1 bilh\u00e3o em linha de cr\u00e9dito para o setor produtivo. \u201c Esse dinheiro ser\u00e1 colocado em favor do com\u00e9rcio, de todos aqueles empreendedores para que possamos superar essa crise, com taxas reduzidas e com prazo de car\u00eancia de at\u00e9 6 meses nas opera\u00e7\u00f5es\u201d, destacou.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ANA MARIA CAMPOS AGATHA GONZAGA Projeto de lei do governador Ibaneis Rocha (MDB) estabelece al\u00edquota de 7% para produtos essenciais no combate \u00e0 dissemina\u00e7\u00e3o do coronav\u00edrus. A proposta ser\u00e1 encaminhada nesta segunda-feira (16\/03) \u00e0 C\u00e2mara Legislativa. &nbsp; S\u00e3o eles: \u00e1lcool em gel, insumos para fabricar \u00e1lcool em gel (exceto energia el\u00e9trica), luvas m\u00e9dicas, m\u00e1scaras m\u00e9dicas, hipoclorito de s\u00f3dio 5%, \u00e1lcool [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":17695,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[234],"tags":[2161,2165,2085,91,2162,2163,2164],"class_list":["post-17783","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cb-poder","tag-alcool-em-gel","tag-aliquota","tag-coronavirus","tag-icms","tag-luvas","tag-mascaras","tag-reducao"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/17783","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/comments?post=17783"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/17783\/revisions"}],"predecessor-version":[{"id":17784,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/17783\/revisions\/17784"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media\/17695"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media?parent=17783"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/categories?post=17783"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/tags?post=17783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}