{"id":12875,"date":"2018-09-09T15:18:46","date_gmt":"2018-09-09T18:18:46","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/?p=12875"},"modified":"2018-09-09T15:19:13","modified_gmt":"2018-09-09T18:19:13","slug":"futuro-do-transporte-publico-em-julgamento-no-tjdf","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/futuro-do-transporte-publico-em-julgamento-no-tjdf\/","title":{"rendered":"Justi\u00e7a vai avaliar licita\u00e7\u00e3o dos \u00f4nibus e pode anular concorr\u00eancia p\u00fablica"},"content":{"rendered":"<p>A Justi\u00e7a vai analisar no pr\u00f3ximo dia 19 um processo que pode se transformar no maior abacaxi do pr\u00f3ximo governador do Distrito Federal. A 3\u00aa Turma C\u00edvel julgar\u00e1 a apela\u00e7\u00e3o do Governo do Distrito Federal e de empresas de transporte p\u00fablico contra a decis\u00e3o que suspendeu a licita\u00e7\u00e3o dos \u00f4nibus.<\/p>\n<p>&nbsp;<\/p>\n<p>Em primeira inst\u00e2ncia, a Justi\u00e7a anulou a concorr\u00eancia p\u00fablica realizada em 2011. \u201cSe pudesse conferir um r\u00f3tulo a essa licita\u00e7\u00e3o, seria de engodo\u201d, afirmou o juiz Lizandro Garcia, em senten\u00e7a proferida em 2016. O magistrado deu prazo de 180 dias para o governo realizar uma nova licita\u00e7\u00e3o para todo o sistema de \u00f4nibus mas o recurso apresentado teve efeito suspensivo.<\/p>\n<p>&nbsp;<br \/>\n<strong>Maioria j\u00e1 votou pela suspens\u00e3o de pelo menos tr\u00eas contratos<\/strong><br \/>\nO julgamento da apela\u00e7\u00e3o come\u00e7ou mas foi interrompido por um pedido de vista. At\u00e9 agora, dois desembargadores j\u00e1 votaram pela rejei\u00e7\u00e3o dos recursos e um magistrado acatou parcialmente a apela\u00e7\u00e3o para manter a licita\u00e7\u00e3o de apenas duas das cinco bacias de transporte, cancelando as outras tr\u00eas. Faltam os votos de dois desembargadores para o desfecho da apela\u00e7\u00e3o.<\/p>\n<p>&nbsp;<br \/>\n<strong>Grupo econ\u00f4mico<\/strong><\/p>\n<p>O processo \u00e9 uma a\u00e7\u00e3o popular iniciada em 2013. Os autores alegam a exist\u00eancia de um grupo econ\u00f4mico entre as empresas Via\u00e7\u00e3o Pioneira e Via\u00e7\u00e3o Piracicabana, vencedoras de diferentes lotes da concorr\u00eancia. Afirmam ainda que haveria uma liga\u00e7\u00e3o entre as empresas Via\u00e7\u00e3o Marechal e Via\u00e7\u00e3o Piracicabana com o advogado Sacha Reck. O profissional trabalhou na elabora\u00e7\u00e3o do processo licitat\u00f3rio, como consultor contratado pelo GDF. Em contesta\u00e7\u00e3o, os r\u00e9us negaram as irregularidades.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Justi\u00e7a vai analisar no pr\u00f3ximo dia 19 um processo que pode se transformar no maior abacaxi do pr\u00f3ximo governador do Distrito Federal. A 3\u00aa Turma C\u00edvel julgar\u00e1 a apela\u00e7\u00e3o do Governo do Distrito Federal e de empresas de transporte p\u00fablico contra a decis\u00e3o que suspendeu a licita\u00e7\u00e3o dos \u00f4nibus. &nbsp; Em primeira inst\u00e2ncia, a Justi\u00e7a anulou a concorr\u00eancia p\u00fablica [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":7162,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[234],"tags":[],"class_list":["post-12875","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cb-poder"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/12875","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/comments?post=12875"}],"version-history":[{"count":3,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/12875\/revisions"}],"predecessor-version":[{"id":12878,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/12875\/revisions\/12878"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media\/7162"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media?parent=12875"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/categories?post=12875"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/tags?post=12875"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}