{"id":10010,"date":"2017-11-14T19:39:47","date_gmt":"2017-11-14T21:39:47","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/?p=10010"},"modified":"2017-11-14T19:39:47","modified_gmt":"2017-11-14T21:39:47","slug":"coronel-responsavel-por-contratos-na-pmdf-e-exonerado","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/coronel-responsavel-por-contratos-na-pmdf-e-exonerado\/","title":{"rendered":"Rollemberg exonera coronel da PM investigado por extorquir empres\u00e1rios"},"content":{"rendered":"<p>ANA MARIA CAMPOS<\/p>\n<p>O governador Rodrigo Rollemberg exonerou nesta tarde (14\/11) o coronel Francisco Eronildo Feitosa do cargo de diretor de Log\u00edstica e Financas (DLF) da Pol\u00edcia Militar do DF.<\/p>\n<p>O oficial foi preso nesta manh\u00e3 na Opera\u00e7\u00e3o Mamon, deflagrada pelo Minist\u00e9rio P\u00fablico do Distrito Federal e Territ\u00f3rios (MPDFT), em parceria com a Corregedoria da PMDF.<\/p>\n<p>Segundo a investiga\u00e7\u00e3o, a cargo das Promotorias Militares e do Grupo de Atua\u00e7\u00e3o Especial de Combate ao Crime Organizado (Gaeco), Feitosa participava de um esquema de extors\u00e3o a empres\u00e1rios para libera\u00e7\u00e3o de pagamentos de contratos.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ANA MARIA CAMPOS O governador Rodrigo Rollemberg exonerou nesta tarde (14\/11) o coronel Francisco Eronildo Feitosa do cargo de diretor de Log\u00edstica e Financas (DLF) da Pol\u00edcia Militar do DF. O oficial foi preso nesta manh\u00e3 na Opera\u00e7\u00e3o Mamon, deflagrada pelo Minist\u00e9rio P\u00fablico do Distrito Federal e Territ\u00f3rios (MPDFT), em parceria com a Corregedoria da PMDF. Segundo a investiga\u00e7\u00e3o, a [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":10011,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[234],"tags":[974,975,49],"class_list":["post-10010","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cb-poder","tag-coronel-feitosa","tag-operacao-mamon","tag-rollemberg"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/10010","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/comments?post=10010"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/10010\/revisions"}],"predecessor-version":[{"id":10012,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/posts\/10010\/revisions\/10012"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media\/10011"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/media?parent=10010"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/categories?post=10010"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/cbpoder\/wp-json\/wp\/v2\/tags?post=10010"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}