{"id":2592,"count":7,"description":"","link":"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/tag\/policiamilitar\/","name":"#policiamilitar","slug":"policiamilitar","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-json\/wp\/v2\/tags\/2592","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-json\/wp\/v2\/posts?tags=2592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}