{"id":2041,"count":1,"description":"","link":"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/tag\/ocyan\/","name":"#Ocyan","slug":"ocyan","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-json\/wp\/v2\/tags\/2041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-json\/wp\/v2\/posts?tags=2041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}