{"id":1093,"count":1,"description":"","link":"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/tag\/coquetel\/","name":"coquetel","slug":"coquetel","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-json\/wp\/v2\/tags\/1093","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-json\/wp\/v2\/posts?tags=1093"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}