{"id":5297,"date":"2021-10-01T02:45:49","date_gmt":"2021-10-01T05:45:49","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/?p=5297"},"modified":"2021-10-01T02:48:23","modified_gmt":"2021-10-01T05:48:23","slug":"feijoada-do-senac-de-volta-no-downtown","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/2021\/10\/01\/feijoada-do-senac-de-volta-no-downtown\/","title":{"rendered":"Feijoada do Senac de volta no DownTown"},"content":{"rendered":"<p><b>Por Samanta Sallum<br \/>\n<\/b><br \/>\nHoje \u00e9 dia de dica de gastronomia. Para quem estava com saudade de saborear a feijoada do restaurante escola Senac, o DownTown, a boa not\u00edcia \u00e9 que voltar\u00e1 a ser servida a partir de hoje. Estava suspensa por causa da pandemia. Agora, em vez de buf\u00ea, ser\u00e1 oferecida no prato com tudo que tem direito. De entrada: caldinho de feij\u00e3o, linguicinha frita e pastel. O prato principal vem com arroz, farofa, couve refogada e laranja.<\/p>\n<p><b>Com sobremesa<\/b><\/p>\n<p>De segunda a quinta, custar\u00e1 R$ 55,90. E nas sextas, pela grande demanda, R$59,40, incluindo sobremesa \u2014 pudim ou salada de fruta. Tudo preparado pelo chef Diego Jacob (foto) e equipe, que conta com o\u00a0maitre Carlos Ant\u00f4nio Barbosa, das 12h \u00e0s 15h. O DownTown fica no t\u00e9rreo do pr\u00e9dio da CNC, no Setor Banc\u00e1rio Norte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Samanta Sallum Hoje \u00e9 dia de dica de gastronomia. Para quem estava com saudade de saborear a feijoada do restaurante escola Senac, o DownTown, a boa not\u00edcia \u00e9 que voltar\u00e1 a ser servida a partir de hoje. Estava suspensa por causa da pandemia. Agora, em vez de buf\u00ea, ser\u00e1 oferecida no prato com tudo que tem direito. De entrada: [&hellip;]<\/p>\n","protected":false},"author":125,"featured_media":5302,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-5297","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coluna-capital-s-a"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-json\/wp\/v2\/posts\/5297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-json\/wp\/v2\/users\/125"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-json\/wp\/v2\/comments?post=5297"}],"version-history":[{"count":3,"href":"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-json\/wp\/v2\/posts\/5297\/revisions"}],"predecessor-version":[{"id":5303,"href":"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-json\/wp\/v2\/posts\/5297\/revisions\/5303"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-json\/wp\/v2\/media\/5302"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-json\/wp\/v2\/media?parent=5297"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-json\/wp\/v2\/categories?post=5297"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-json\/wp\/v2\/tags?post=5297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}