{"id":21439,"date":"2025-12-22T14:36:51","date_gmt":"2025-12-22T17:36:51","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/?p=21439"},"modified":"2025-12-22T23:54:56","modified_gmt":"2025-12-23T02:54:56","slug":"veja-como-sera-o-funcionamento-do-comercio-no-natal-e-no-ano-novo-no-df","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/2025\/12\/22\/veja-como-sera-o-funcionamento-do-comercio-no-natal-e-no-ano-novo-no-df\/","title":{"rendered":"Veja como ser\u00e1 o funcionamento do com\u00e9rcio no Natal e no Ano Novo no DF"},"content":{"rendered":"<p class=\"p1\">Com base nos acordos firmados nas Conven\u00e7\u00f5es Coletivas de Trabalho (CCTs) entre Fecom\u00e9rcio-DF, sindicatos empresariais e entidades laborais, confira a seguir como ser\u00e1 o funcionamento do com\u00e9rcio neste fim de ano.<\/p>\n<p class=\"p1\"><span class=\"s1\"><strong>Natal<\/strong><br \/>\n&#8211; <\/span><span class=\"s2\">Na v\u00e9spera de Natal (24\/12), o funcionamento do com\u00e9rcio varejista em geral ser\u00e1 permitido at\u00e9 as 18h. Os supermercado, da base do Sindsuper-DF, podem funcionar at\u00e9 as 20h.<\/span><\/p>\n<ul class=\"ul1\">\n<li class=\"li1\"><span class=\"s2\">No dia 25 de dezembro, feriado de Natal, os comerci\u00e1rios das empresas vinculadas \u00e0 base da Fecom\u00e9rcio-DF e aos sindicatos Sindipel-DF, Sindig\u00eaneros-DF, Siese-DF, Sindivarejista-DF, Sindsuper-DF, Sincope\u00e7as-DF e Sindi\u00f3ptica-DF n\u00e3o trabalhar\u00e3o<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">Bares e restaurantes est\u00e3o autorizados a funcionar nos dois dias para a realiza\u00e7\u00e3o das ceias natalinas, desde que sejam respeitadas as regras de folga compensat\u00f3ria ou pagamento em dobro aos funcion\u00e1rios, conforme previsto em CCT.<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">As farm\u00e1cias t\u00eam autoriza\u00e7\u00e3o para operar em hor\u00e1rio livre ao longo do ano, com 10% em regime de plant\u00e3o 24 horas. Nos dias 24 e 25 de dezembro, a maioria funciona at\u00e9 as 18h, permanecendo abertas apenas as unidades escaladas para plant\u00e3o.<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">As feiras podem funcionar normalmente na v\u00e9spera de Natal e permanecem fechadas no dia 25\/12.<\/span><\/li>\n<\/ul>\n<p class=\"p1\"><span class=\"s1\"><strong>Ano Novo<\/strong><br \/>\n&#8211; <\/span><span class=\"s2\">Na v\u00e9spera de Ano Novo (31\/12), as empresas inorganizadas ou vinculadas aos sindicatos Sindipel-DF, Sindig\u00eaneros-DF, Sindivarejista-DF, Sincope\u00e7as-DF e Sindi\u00f3ptica-DF poder\u00e3o funcionar at\u00e9 as 18h. J\u00e1 os supermercados ligados ao Sindsuper-DF devem encerrar as atividades at\u00e9 20h. No dia 1\u00ba de janeiro, feriado de Ano Novo, todas essas empresas estar\u00e3o fechadas, conforme determina a CCT.<\/span><\/p>\n<ul class=\"ul1\">\n<li class=\"li1\"><span class=\"s2\">Bares e restaurantes podem funcionar para atender \u00e0s comemora\u00e7\u00f5es da virada do ano. No dia 1\u00ba de janeiro, h\u00e1 permiss\u00e3o para funcionamento, embora alguns estabelecimentos optem por permanecerem fechados. \u00c9 fundamental que os empres\u00e1rios observem os direitos dos trabalhadores que atuarem no feriado.<\/span><\/li>\n<\/ul>\n<ul class=\"ul1\">\n<li class=\"li1\"><span class=\"s2\">As farm\u00e1cias seguem autorizadas a funcionar em hor\u00e1rio livre, com plant\u00f5es mantidos. Nos dias 31\/12 e 1\u00ba\/1, a maioria das unidades atende at\u00e9 as 18h, permanecendo abertas aquelas em regime de plant\u00e3o.<\/span><\/li>\n<li class=\"li1\"><span class=\"s2\">As feiras do Distrito Federal funcionar\u00e3o normalmente no dia 31 de dezembro e estar\u00e3o fechadas no dia 1\u00ba de janeiro.<\/span><\/li>\n<\/ul>\n<p><strong><em>Acompanhe a Capital S\/A na TV Bras\u00edlia todas as ter\u00e7as e quintas-feiras, 18h,\u00a0<\/em><\/strong><strong><em>no JL ao vivo<\/em><\/strong><\/p>\n<p><iframe loading=\"lazy\" title=\"PARCERIA DO EX\u00c9RCITO COM EMPRESAS  EST\u00c1 FORMANDO JOVENS PARA O MERCADO DE TRABALHO | CAPITAL S\/A\" width=\"1440\" height=\"810\" src=\"https:\/\/www.youtube.com\/embed\/df-I6wH_J04?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p class=\"p1\">\n","protected":false},"excerpt":{"rendered":"<p>Com base nos acordos firmados nas Conven\u00e7\u00f5es Coletivas de Trabalho (CCTs) entre Fecom\u00e9rcio-DF, sindicatos empresariais e entidades laborais, confira a seguir como ser\u00e1 o funcionamento do com\u00e9rcio neste fim de ano. Natal &#8211; Na v\u00e9spera de Natal (24\/12), o funcionamento do com\u00e9rcio varejista em geral ser\u00e1 permitido at\u00e9 as 18h. Os supermercado, da base do Sindsuper-DF, podem funcionar at\u00e9 as [&hellip;]<\/p>\n","protected":false},"author":125,"featured_media":21442,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-21439","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coluna-capital-s-a"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-json\/wp\/v2\/posts\/21439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-json\/wp\/v2\/users\/125"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-json\/wp\/v2\/comments?post=21439"}],"version-history":[{"count":4,"href":"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-json\/wp\/v2\/posts\/21439\/revisions"}],"predecessor-version":[{"id":21449,"href":"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-json\/wp\/v2\/posts\/21439\/revisions\/21449"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-json\/wp\/v2\/media\/21442"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-json\/wp\/v2\/media?parent=21439"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-json\/wp\/v2\/categories?post=21439"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-json\/wp\/v2\/tags?post=21439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}