{"id":21215,"date":"2025-11-28T14:15:17","date_gmt":"2025-11-28T17:15:17","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/?p=21215"},"modified":"2025-12-01T23:21:02","modified_gmt":"2025-12-02T02:21:02","slug":"aprovacao-do-pdot-da-sinal-verde-para-regularizacao-de-28-regioes","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/2025\/11\/28\/aprovacao-do-pdot-da-sinal-verde-para-regularizacao-de-28-regioes\/","title":{"rendered":"Aprova\u00e7\u00e3o do PDOT d\u00e1 sinal verde para regulariza\u00e7\u00e3o de 28 regi\u00f5es"},"content":{"rendered":"<p><strong>Coluna Capital S\/A de 28 de novembro\u00a0<\/strong><\/p>\n<p><strong><em>Por SAMANTA SALLUM<\/em><\/strong><\/p>\n<p>A aprova\u00e7\u00e3o do Plano Diretor de Ordenamento Territorial (PDOT) pela C\u00e2mara Legislativa confirma o in\u00edcio do processo de regulariza\u00e7\u00e3o de 28 regi\u00f5es ocupadas por moradias no Distrito Federal, incluindo a que foi a Col\u00f4nia Agr\u00edcola 26 de Setembro. Essa \u00e9 uma \u00e1rea, antes rural, que passa a ser urbana depois da descaracteriza\u00e7\u00e3o pela ocupa\u00e7\u00e3o. Uma bandeira defendida pela vice-governadora Celina Le\u00e3o desde que era deputada federal e foi autora da lei que redefiniu limites da floresta nacional. O PDOT n\u00e3o regulariza automaticamente as \u00e1reas, mas autoriza que a Terracap e a Codhab iniciem os processos com planos urban\u00edsticos (veja lista abaixo).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-21220\" src=\"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-content\/uploads\/sites\/59\/2025\/11\/b3d77b61-e5eb-416a-a8cc-cd3963437c0a-1-205x300.jpeg\" alt=\"\" width=\"205\" height=\"300\" srcset=\"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-content\/uploads\/sites\/59\/2025\/11\/b3d77b61-e5eb-416a-a8cc-cd3963437c0a-1-205x300.jpeg 205w, https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-content\/uploads\/sites\/59\/2025\/11\/b3d77b61-e5eb-416a-a8cc-cd3963437c0a-1-768x1124.jpeg 768w, https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-content\/uploads\/sites\/59\/2025\/11\/b3d77b61-e5eb-416a-a8cc-cd3963437c0a-1-700x1024.jpeg 700w, https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-content\/uploads\/sites\/59\/2025\/11\/b3d77b61-e5eb-416a-a8cc-cd3963437c0a-1-800x1171.jpeg 800w, https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-content\/uploads\/sites\/59\/2025\/11\/b3d77b61-e5eb-416a-a8cc-cd3963437c0a-1-550x805.jpeg 550w, https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-content\/uploads\/sites\/59\/2025\/11\/b3d77b61-e5eb-416a-a8cc-cd3963437c0a-1-230x337.jpeg 230w, https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-content\/uploads\/sites\/59\/2025\/11\/b3d77b61-e5eb-416a-a8cc-cd3963437c0a-1.jpeg 1093w\" sizes=\"auto, (max-width: 205px) 100vw, 205px\" \/><\/p>\n<p><strong>Nova etapa urban\u00edstica<\/strong><\/p>\n<p>O secret\u00e1rio de Desenvolvimento Urbano e Habita\u00e7\u00e3o (Seduh), Marcelo Vaz, avalia que o percentual de 5% de \u00e1reas rurais que passam a ser urbanas \u00e9 de baixo impacto. \u201cNesses \u00faltimos 16 anos, a ocupa\u00e7\u00e3o do territ\u00f3rio no DF sofreu muitas mudan\u00e7as, e era preciso atualizar o PDOT. Vencida essa etapa, agora come\u00e7amos uma nova fase: a de impedir o surgimento de ocupa\u00e7\u00f5es irregulares; e de passar a ofertar moradias devidamente legalizadas e tamb\u00e9m de interesse social\u201d, disse \u00e0 coluna.<\/p>\n<p><strong>Votos da oposi\u00e7\u00e3o<\/strong><\/p>\n<p>O projeto de lei conseguiu dois votos favor\u00e1veis da oposi\u00e7\u00e3o: dos deputados petistas Chico Vigilante e Ricardo Vale, que \u00e9 vice-presidente da C\u00e2mara Legislativa.<\/p>\n<p><strong>An\u00e1lise de emendas<\/strong><\/p>\n<p>A Seduh aguarda o envio da reda\u00e7\u00e3o final do projeto de lei aprovado na C\u00e2mara Legislativa para emitir um parecer t\u00e9cnico ao governador Ibaneis Rocha. Ele vai avaliar se ser\u00e1 necess\u00e1rio vetar alguma emenda. Foram 200 anexadas pelo distritais ao projeto original.<\/p>\n<p>O setor produtivo apoiou a aprova\u00e7\u00e3o do PDOT, pois o projeto prev\u00ea eixos de desenvolvimento e atividades econ\u00f4micas ligadas ao com\u00e9rcio e \u00e0 ind\u00fastria.<\/p>\n<p><strong>Bares e restaurantes reconquistam otimismo com mais opera\u00e7\u00f5es em lucro<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-21223\" src=\"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-content\/uploads\/sites\/59\/2025\/11\/IMG_2191-300x200.png\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-content\/uploads\/sites\/59\/2025\/11\/IMG_2191-300x200.png 300w, https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-content\/uploads\/sites\/59\/2025\/11\/IMG_2191-550x367.png 550w, https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-content\/uploads\/sites\/59\/2025\/11\/IMG_2191-230x153.png 230w, https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-content\/uploads\/sites\/59\/2025\/11\/IMG_2191.png 750w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>O setor da economia criativa com bares e restaurantes do Distrito Federal voltou a mostrar resili\u00eancia. \u00c9 o que aponta a nova pesquisa da Abrasel, realizada entre 10 e 19 de novembro, com empres\u00e1rios do segmento de Alimenta\u00e7\u00e3o Fora do Lar. O levantamento indica um momento de virada: 47% dos estabelecimentos operaram com lucro em outubro, enquanto 40% registraram estabilidade, e apenas 13% tiveram preju\u00edzo.<\/p>\n<p><em>Mais faturamento<\/em><br \/>\nO desempenho ganha ainda mais for\u00e7a quando comparado ao m\u00eas anterior. Mais da metade dos neg\u00f3cios (56%) registrou aumento no faturamento, demonstrando que a retomada do consumo segue firme \u2014 mesmo diante dos desafios econ\u00f4micos que ainda pressionam o setor. Para 24% dos entrevistados, o cen\u00e1rio permaneceu est\u00e1vel, e apenas 19% relataram queda nas receitas.<\/p>\n<p><em>Endividamento ainda preocupa<\/em><br \/>\nNo entanto, o endividamento ainda \u00e9 um ponto sens\u00edvel. Trinta e sete por cento das empresas t\u00eam d\u00edvidas em atraso, principalmente relacionadas a impostos federais (72%), tributos estaduais (59%) e empr\u00e9stimos banc\u00e1rios (31%). Apesar disso, o setor demonstra capacidade de rea\u00e7\u00e3o e planejamento para avan\u00e7ar, mesmo com restri\u00e7\u00f5es financeiras.<\/p>\n<p><em>Nova diretoria<\/em><br \/>\nA Associa\u00e7\u00e3o dos Bares e Restaurantes do Distrito Federal empossou neste m\u00eas a nova diretoria para o tri\u00eanio 2025\/2028. Quem assume a lideran\u00e7a da Abrasel-DF \u00e9 Thales Furtado, do Restaurante Gordeixos. Depois de dois mandatos \u00e0 frente da Abrasel-DF, o empres\u00e1rio Beto Pinheiro encerrou a gest\u00e3o sendo homenageado pelos associados. Lembrou que assumiu a entidade h\u00e1 seis anos, com 199 associados. Hoje ela tem 905.<\/p>\n<p><strong>Grupo Almer\u00eda investe alto em novo espa\u00e7o<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-21221\" src=\"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-content\/uploads\/sites\/59\/2025\/11\/IMG_2185-260x300.jpeg\" alt=\"\" width=\"260\" height=\"300\" srcset=\"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-content\/uploads\/sites\/59\/2025\/11\/IMG_2185-260x300.jpeg 260w, https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-content\/uploads\/sites\/59\/2025\/11\/IMG_2185-768x886.jpeg 768w, https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-content\/uploads\/sites\/59\/2025\/11\/IMG_2185-887x1024.jpeg 887w, https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-content\/uploads\/sites\/59\/2025\/11\/IMG_2185-800x923.jpeg 800w, https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-content\/uploads\/sites\/59\/2025\/11\/IMG_2185-550x635.jpeg 550w, https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-content\/uploads\/sites\/59\/2025\/11\/IMG_2185-230x265.jpeg 230w, https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-content\/uploads\/sites\/59\/2025\/11\/IMG_2185.jpeg 1170w\" sizes=\"auto, (max-width: 260px) 100vw, 260px\" \/><\/p>\n<p>O empres\u00e1rio Guto Jabour, \u00e0 frente do Grupo Almer\u00eda, prepara a inaugura\u00e7\u00e3o do Almer\u00eda Beira Lago. Quer que o espa\u00e7o se torne \u00edcone na gastronomia e na hospitalidade de alto padr\u00e3o em Bras\u00edlia. O projeto, assinado pelos arquitetos Cuka Lima, Gustavo G\u00f3es e Bianca Greg\u00f3rio Jabour, une design mediterr\u00e2neo e experi\u00eancias sensoriais \u00e0 beira do Lago Parano\u00e1. O investimento foi de R$ 8 milh\u00f5es. O grupo, que administra cinco unidades de neg\u00f3cio, encerra 2025 com 310 colaboradores diretos. E projeta um faturamento pr\u00f3ximo de R$ 100 milh\u00f5es em 2026 \u2014 quase o dobro do deste ano. Muito otimismo.<\/p>\n<p><iframe loading=\"lazy\" title=\"COM\u00c9RCIO NO DF VAI ABRIR 3,8 MIL VAGAS TEMPOR\u00c1RIAS E CONTRATA\u00c7\u00d5ES J\u00c1 COME\u00c7ARAM | CAPITAL S\/A\" width=\"1440\" height=\"810\" src=\"https:\/\/www.youtube.com\/embed\/CSgn1G8gx0I?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Coluna Capital S\/A de 28 de novembro\u00a0 Por SAMANTA SALLUM A aprova\u00e7\u00e3o do Plano Diretor de Ordenamento Territorial (PDOT) pela C\u00e2mara Legislativa confirma o in\u00edcio do processo de regulariza\u00e7\u00e3o de 28 regi\u00f5es ocupadas por moradias no Distrito Federal, incluindo a que foi a Col\u00f4nia Agr\u00edcola 26 de Setembro. Essa \u00e9 uma \u00e1rea, antes rural, que passa a ser urbana depois [&hellip;]<\/p>\n","protected":false},"author":125,"featured_media":21218,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-21215","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coluna-capital-s-a"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-json\/wp\/v2\/posts\/21215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-json\/wp\/v2\/users\/125"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-json\/wp\/v2\/comments?post=21215"}],"version-history":[{"count":6,"href":"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-json\/wp\/v2\/posts\/21215\/revisions"}],"predecessor-version":[{"id":21244,"href":"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-json\/wp\/v2\/posts\/21215\/revisions\/21244"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-json\/wp\/v2\/media\/21218"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-json\/wp\/v2\/media?parent=21215"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-json\/wp\/v2\/categories?post=21215"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/capital-sa\/wp-json\/wp\/v2\/tags?post=21215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}