{"id":3,"count":17,"description":"","link":"https:\/\/blogs.correiobraziliense.com.br\/brasiliatododia\/category\/todo-dia\/","name":"Todo dia","slug":"todo-dia","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/brasiliatododia\/wp-json\/wp\/v2\/categories\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/brasiliatododia\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/brasiliatododia\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/brasiliatododia\/wp-json\/wp\/v2\/posts?categories=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}