{"id":2053,"date":"2017-04-03T13:07:36","date_gmt":"2017-04-03T16:07:36","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/blogaodoze\/?p=2053"},"modified":"2017-04-03T13:07:36","modified_gmt":"2017-04-03T16:07:36","slug":"e-a-crise-3","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/blogaodoze\/e-a-crise-3\/","title":{"rendered":"\u00c9 a crise!!!!"},"content":{"rendered":"<p><span style=\"font-size: xx-large\">A coisa t\u00e1 t\u00e3o feia, que at\u00e9 o implante de cabelo do Renan est\u00e1 caindo<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-2054\" src=\"https:\/\/blogs.correiobraziliense.com.br\/blogaodoze\/wp-content\/uploads\/sites\/9\/2017\/04\/implas-300x249.jpg\" alt=\"implas\" width=\"300\" height=\"249\" srcset=\"https:\/\/blogs.correiobraziliense.com.br\/blogaodoze\/wp-content\/uploads\/sites\/9\/2017\/04\/implas-300x249.jpg 300w, https:\/\/blogs.correiobraziliense.com.br\/blogaodoze\/wp-content\/uploads\/sites\/9\/2017\/04\/implas-350x291.jpg 350w, https:\/\/blogs.correiobraziliense.com.br\/blogaodoze\/wp-content\/uploads\/sites\/9\/2017\/04\/implas-230x191.jpg 230w, https:\/\/blogs.correiobraziliense.com.br\/blogaodoze\/wp-content\/uploads\/sites\/9\/2017\/04\/implas.jpg 520w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A coisa t\u00e1 t\u00e3o feia, que at\u00e9 o implante de cabelo do Renan est\u00e1 caindo &nbsp;<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-2053","post","type-post","status-publish","format-standard","hentry","category-humor"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/blogaodoze\/wp-json\/wp\/v2\/posts\/2053","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/blogaodoze\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/blogaodoze\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/blogaodoze\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/blogaodoze\/wp-json\/wp\/v2\/comments?post=2053"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/blogaodoze\/wp-json\/wp\/v2\/posts\/2053\/revisions"}],"predecessor-version":[{"id":2055,"href":"https:\/\/blogs.correiobraziliense.com.br\/blogaodoze\/wp-json\/wp\/v2\/posts\/2053\/revisions\/2055"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/blogaodoze\/wp-json\/wp\/v2\/media?parent=2053"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/blogaodoze\/wp-json\/wp\/v2\/categories?post=2053"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/blogaodoze\/wp-json\/wp\/v2\/tags?post=2053"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}