{"id":1381,"date":"2016-07-13T14:31:24","date_gmt":"2016-07-13T17:31:24","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/blogaodoze\/?p=1381"},"modified":"2016-07-13T14:31:24","modified_gmt":"2016-07-13T17:31:24","slug":"mudanca-de-ramo","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/blogaodoze\/mudanca-de-ramo\/","title":{"rendered":"Mudan\u00e7a de ramo"},"content":{"rendered":"<p align=\"left\"><span style=\"color: #0000ff\"><span style=\"font-family: Arial;font-size: xx-large\"><b>Confirmado:\u00a0Cerver\u00f3 \u00e9 o novo olheiro da CBF! <\/b><\/span><\/span><\/p>\n<figure id=\"attachment_1382\" aria-describedby=\"caption-attachment-1382\" style=\"width: 300px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/blogs.correiobraziliense.com.br\/blogaodoze\/wp-content\/uploads\/sites\/9\/2016\/07\/cervvv.jpg\" rel=\"attachment wp-att-1382\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1382\" src=\"https:\/\/blogs.correiobraziliense.com.br\/blogaodoze\/wp-content\/uploads\/sites\/9\/2016\/07\/cervvv-300x194.jpg\" alt=\"Cr\u00e9dito: Wilson Dias\/Ag\u00eancia Brasil. Nestor Cerver\u00f3 durante depoimento na Comiss\u00e3o Parlamentar Mista de Inqu\u00e9rito - CPMI da Petrobras.\" width=\"300\" height=\"194\" srcset=\"https:\/\/blogs.correiobraziliense.com.br\/blogaodoze\/wp-content\/uploads\/sites\/9\/2016\/07\/cervvv-300x194.jpg 300w, https:\/\/blogs.correiobraziliense.com.br\/blogaodoze\/wp-content\/uploads\/sites\/9\/2016\/07\/cervvv-768x496.jpg 768w, https:\/\/blogs.correiobraziliense.com.br\/blogaodoze\/wp-content\/uploads\/sites\/9\/2016\/07\/cervvv-350x226.jpg 350w, https:\/\/blogs.correiobraziliense.com.br\/blogaodoze\/wp-content\/uploads\/sites\/9\/2016\/07\/cervvv-550x355.jpg 550w, https:\/\/blogs.correiobraziliense.com.br\/blogaodoze\/wp-content\/uploads\/sites\/9\/2016\/07\/cervvv-230x149.jpg 230w, https:\/\/blogs.correiobraziliense.com.br\/blogaodoze\/wp-content\/uploads\/sites\/9\/2016\/07\/cervvv.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-1382\" class=\"wp-caption-text\">Cr\u00e9dito: Wilson Dias<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Confirmado:\u00a0Cerver\u00f3 \u00e9 o novo olheiro da CBF!<\/p>\n","protected":false},"author":26,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-1381","post","type-post","status-publish","format-standard","hentry","category-humor"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/blogaodoze\/wp-json\/wp\/v2\/posts\/1381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/blogaodoze\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/blogaodoze\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/blogaodoze\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/blogaodoze\/wp-json\/wp\/v2\/comments?post=1381"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/blogaodoze\/wp-json\/wp\/v2\/posts\/1381\/revisions"}],"predecessor-version":[{"id":1383,"href":"https:\/\/blogs.correiobraziliense.com.br\/blogaodoze\/wp-json\/wp\/v2\/posts\/1381\/revisions\/1383"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/blogaodoze\/wp-json\/wp\/v2\/media?parent=1381"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/blogaodoze\/wp-json\/wp\/v2\/categories?post=1381"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/blogaodoze\/wp-json\/wp\/v2\/tags?post=1381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}