{"id":34,"count":1,"description":"","link":"https:\/\/blogs.correiobraziliense.com.br\/blog-tecnologia-tony-ventura\/tag\/veneza\/","name":"veneza","slug":"veneza","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/blog-tecnologia-tony-ventura\/wp-json\/wp\/v2\/tags\/34","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/blog-tecnologia-tony-ventura\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/blog-tecnologia-tony-ventura\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/blog-tecnologia-tony-ventura\/wp-json\/wp\/v2\/posts?tags=34"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}