{"id":78,"date":"2019-01-18T14:12:44","date_gmt":"2019-01-18T16:12:44","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/blog-tecnologia-tony-ventura\/?p=78"},"modified":"2019-01-18T16:50:19","modified_gmt":"2019-01-18T18:50:19","slug":"planeta-terra-na-palma-da-sua-mao","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/blog-tecnologia-tony-ventura\/planeta-terra-na-palma-da-sua-mao\/","title":{"rendered":"Planeta Terra na Palma da Sua M\u00e3o"},"content":{"rendered":"<p><iframe loading=\"lazy\" width=\"1440\" height=\"810\" src=\"https:\/\/www.youtube.com\/embed\/4rj92kua35U?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>Voc\u00ea gostaria de ter o Planeta Terra na sua m\u00e3o? Neste v\u00eddeo, mostro o Astro Reality, um aplicativo que te permite estudar por completo todo nosso planeta Terra usando um modelo 3D da pr\u00f3pria Terra.<\/p>\n<p>J\u00e1 desejou poder visitar outros planetas em nosso sistema solar sem se lan\u00e7ar em uma miss\u00e3o no espa\u00e7o profundo? Com o Astro Reality voc\u00ea pode embarcar em uma aventura diretamente da palma da sua m\u00e3o, gra\u00e7as aos bel\u00edssimos modelos de planeta com impress\u00e3o 3D em um aplicativo de realidade aumentada.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-79\" src=\"https:\/\/blogs.correiobraziliense.com.br\/blog-tecnologia-tony-ventura\/wp-content\/uploads\/sites\/50\/2019\/01\/AstroReality.jpg\" alt=\"\" width=\"608\" height=\"308\" \/><\/p>\n<p>O Astro Reality \u00e9 da mesma empresa que criou o modelo &#8220;Lunar&#8221; e sua nova cria\u00e7\u00e3o \u00e9 sobre a Terra. Este aplicativo inclui modelos em miniatura de todos os oito planetas e um modelo do planeta an\u00e3o Plut\u00e3o. Cada modelo mede 1,2 polegadas de di\u00e2metro e \u00e9 impresso em cores com uma resolu\u00e7\u00e3o de 0,1 mil\u00edmetro por pixel.<\/p>\n<p>A verdadeira aventura extraterrestre come\u00e7a quando voc\u00ea abre o aplicativo Astro Reality (dispon\u00edvel para iOS e Android) em seu dispositivo m\u00f3vel e aponta a c\u00e2mera para qualquer um dos nove modelos. O Astro Reality est\u00e1 dispon\u00edvel para compra no site da marca. O custo \u00e9 de 200 US$ (aproximadamente 750 reais).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voc\u00ea gostaria de ter o Planeta Terra na sua m\u00e3o? Neste v\u00eddeo, mostro o Astro Reality, um aplicativo que te permite estudar por completo todo nosso planeta Terra usando um modelo 3D da pr\u00f3pria Terra. J\u00e1 desejou poder visitar outros planetas em nosso sistema solar sem se lan\u00e7ar em uma miss\u00e3o no espa\u00e7o profundo? Com o Astro Reality voc\u00ea pode [&hellip;]<\/p>\n","protected":false},"author":109,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[5,7,15,3],"class_list":["post-78","post","type-post","status-publish","format-standard","hentry","category-sem-categoria","tag-blog-tony-ventura","tag-novas-tecnologias","tag-tecnologias","tag-tony-ventura"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/blog-tecnologia-tony-ventura\/wp-json\/wp\/v2\/posts\/78","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/blog-tecnologia-tony-ventura\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/blog-tecnologia-tony-ventura\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/blog-tecnologia-tony-ventura\/wp-json\/wp\/v2\/users\/109"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/blog-tecnologia-tony-ventura\/wp-json\/wp\/v2\/comments?post=78"}],"version-history":[{"count":16,"href":"https:\/\/blogs.correiobraziliense.com.br\/blog-tecnologia-tony-ventura\/wp-json\/wp\/v2\/posts\/78\/revisions"}],"predecessor-version":[{"id":98,"href":"https:\/\/blogs.correiobraziliense.com.br\/blog-tecnologia-tony-ventura\/wp-json\/wp\/v2\/posts\/78\/revisions\/98"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/blog-tecnologia-tony-ventura\/wp-json\/wp\/v2\/media?parent=78"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/blog-tecnologia-tony-ventura\/wp-json\/wp\/v2\/categories?post=78"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/blog-tecnologia-tony-ventura\/wp-json\/wp\/v2\/tags?post=78"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}