{"id":9625,"date":"2024-10-30T08:05:59","date_gmt":"2024-10-30T11:05:59","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/?p=9625"},"modified":"2024-10-30T09:23:17","modified_gmt":"2024-10-30T12:23:17","slug":"nas-entrelinhas-dirceu-volta-a-cena-com-anulacao-de-penas","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/nas-entrelinhas-dirceu-volta-a-cena-com-anulacao-de-penas\/","title":{"rendered":"Nas entrelinhas: Dirceu volta \u00e0 cena com anula\u00e7\u00e3o de penas"},"content":{"rendered":"<p style=\"text-align: left\"><em><strong>Gilmar Mendes anulou todos os atos processuais produzidos pelo ex-juiz Sergio Moro em duas a\u00e7\u00f5es penais contra o ex-ministro petista, por parcialidade<\/strong><\/em><\/p>\n<p>A anula\u00e7\u00e3o das condena\u00e7\u00f5es do ex-deputado federal Jos\u00e9 Dirceu, pelo ministro Gilmar Mendes, do Supremo Tribunal Federal (STF), trouxe o petista hist\u00f3rico de volta \u00e0 cena pol\u00edtica do pa\u00eds, com plenos direitos pol\u00edticos. Dirceu havia sido condenado a 23 anos e tr\u00eas meses de pris\u00e3o pelo ent\u00e3o juiz e atual senador Sergio Moro (Uni\u00e3o-PR), que apontou o ex-chefe da Casa Civil do primeiro governo Lula como suposto benefici\u00e1rio de R$ 15 milh\u00f5es em propinas pagas pela empreiteira Engevix, por cinco contratos de obras da Petrobras.<\/p>\n<p>Dirceu vinha mantendo discreta atua\u00e7\u00e3o pol\u00edtica, sempre nos bastidores, mas circulava com desenvoltura e, toda vez que aparecia em p\u00fablico, em algum evento social que reunisse pol\u00edticos, era reverenciado pelos interlocutores. J\u00e1 havia retomado tamb\u00e9m a milit\u00e2ncia no PT, participando de reuni\u00f5es e conversas informais, com a mesma discri\u00e7\u00e3o. Agora, livre das condena\u00e7\u00f5es, deve intensificar sua atua\u00e7\u00e3o, mas n\u00e3o decidiu ainda se pretende voltar \u00e0 c\u00fapula do PT e\/ou disputar elei\u00e7\u00f5es. Or\u00e1culo dos principais dirigentes petistas nunca deixou de ser.<\/p>\n<p>Gilmar Mendes anulou todos os atos processuais produzidos por Moro em duas a\u00e7\u00f5es penais contra Jos\u00e9 Dirceu. A decis\u00e3o foi proferida na Peti\u00e7\u00e3o (PET) 12229 e divulgada nesta ter\u00e7a-feira. O ex-ministro foi beneficiado pelo fato de a Segunda Turma do Supremo, em mar\u00e7o de 2021, declarar a parcialidade de Moro nas a\u00e7\u00f5es penais contra Lula.<\/p>\n<p>Segundo o ministro do STF, com base nos di\u00e1logos revelados pela Vaza Jato e outros elementos trazidos nos autos, houve a\u00e7\u00e3o coordenada entre Moro e a for\u00e7a-tarefa da Lava-Jato para acusar e denunciar Jos\u00e9 Dirceu. A atua\u00e7\u00e3o serviria de ensaio para a den\u00fancia que seria posteriormente oferecida contra o presidente Lula. Apesar de o ex-ministro n\u00e3o ter sido denunciado no caso, Jos\u00e9 Dirceu \u00e9 mencionado 72 vezes na den\u00fancia contra Lula no caso do triplex do Guaruj\u00e1.<\/p>\n<p>Na decis\u00e3o, Gilmar critica a &#8220;confraria formada pelo ex-juiz Sergio Moro e os procuradores de Curitiba&#8221;. Avalia que a Opera\u00e7\u00e3o Lava-Jato &#8220;encarava a condena\u00e7\u00e3o de Dirceu como objetivo a ser alcan\u00e7ado para alicer\u00e7ar as den\u00fancias que, em seguida, seriam oferecidas contra Luiz In\u00e1cio Lula da Silva&#8221;. E que houve &#8220;aus\u00eancia de imparcialidade&#8221; na condu\u00e7\u00e3o dos processos e, por isso, o ex-ministro n\u00e3o teve um julgamento justo. Com a decis\u00e3o, na pr\u00e1tica, Dirceu passa a ser considerado &#8220;ficha-limpa&#8221;.<\/p>\n<p><strong>Segunda vit\u00f3ria<\/strong><\/p>\n<p>A senten\u00e7a atende ao pedido da defesa para estender ao ex-ministro a decis\u00e3o da 2\u00aa Turma do STF que considerou Moro parcial ao julgar Lula. Gilmar afirma: &#8220;A extens\u00e3o, assim, legitima-se n\u00e3o como uma medida geral, que aproveita a qualquer outro investigado na Lava-Jato, mas devido a indicativos de que o juiz e procuradores ajustaram estrat\u00e9gias contra esses r\u00e9us, tendo a condena\u00e7\u00e3o de um deles como alicerce da den\u00fancia oferecida contra outro&#8221;.<\/p>\n<p>Prossegue o ministro do STF: &#8220;Ante o exposto, ante a situa\u00e7\u00e3o particular do r\u00e9u, defiro o pedido da defesa para determinar a extens\u00e3o da ordem de Habeas Corpus (&#8230;) anulando todos os atos processuais do ex-juiz federal Sergio Moro nesses processos e em procedimentos conexos, exclusivamente em rela\u00e7\u00e3o ao ex-ministro Jos\u00e9 Dirceu&#8221;. Ao longo de 24 p\u00e1ginas, Gilmar menciona sete ind\u00edcios que o Supremo levou em conta ao considerar que houve quebra de imparcialidade por Moro ao julgar Lula e cita mensagens entre a for\u00e7a-tarefa de Curitiba e o ex-juiz reveladas pela imprensa.<\/p>\n<p>O fato de Moro ter deixado a magistratura para assumir o Minist\u00e9rio da Justi\u00e7a do governo Bolsonaro tamb\u00e9m \u00e9 apontado como demonstra\u00e7\u00e3o de parcialidade. Segundo o ministro do STF, Moro tinha o desejo de &#8220;impulsionar movimentos sociais e for\u00e7as de oposi\u00e7\u00e3o ao partido pol\u00edtico liderado pelo paciente \u2014for\u00e7as estas a que ele mesmo, em seguida, viria a aderir, quando aceitou o convite para integrar o governo de Jair Bolsonaro&#8221;.<\/p>\n<p>Esta \u00e9 a segunda vit\u00f3ria obtida por Dirceu neste ano no tribunal. A Segunda Turma do STF extinguiu no final de maio a pena \u00e0 qual o ex-ministro foi condenado, por corrup\u00e7\u00e3o passiva, no \u00e2mbito da Opera\u00e7\u00e3o Lava-Jato. O ex-ministro da Casa Civil, no entanto, seguia ineleg\u00edvel pela Lei da Ficha Limpa, apesar da vit\u00f3ria que obteve no STF. Isso porque havia recursos contra duas condena\u00e7\u00f5es em tramita\u00e7\u00e3o no Superior Tribunal de Justi\u00e7a (STJ) aguardando julgamento. Agora n\u00e3o h\u00e1 mais.<\/p>\n<p><em>Todas as colunas anteriores no Blog do Azedo<\/em>:\u00a0<a href=\"https:\/\/blogs.correiobraziliense.com.br\/azedo\/\">https:\/\/blogs.correiobraziliense.com.br\/azedo\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gilmar Mendes anulou todos os atos processuais produzidos pelo ex-juiz Sergio Moro em duas a\u00e7\u00f5es penais contra o ex-ministro petista, por parcialidade A anula\u00e7\u00e3o das condena\u00e7\u00f5es do ex-deputado federal Jos\u00e9 Dirceu, pelo ministro Gilmar Mendes, do Supremo Tribunal Federal (STF), trouxe o petista hist\u00f3rico de volta \u00e0 cena pol\u00edtica do pa\u00eds, com plenos direitos pol\u00edticos. Dirceu havia sido condenado a [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":9633,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1223,980,371,4,7,5,972,8,9,3],"tags":[174,159,311,1807,10,17],"class_list":["post-9625","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasilia","category-eleicoes-2","category-etica","category-governo","category-justica","category-lava-jato","category-memoria","category-partidos","category-politica-2","category-politica","tag-dirceu","tag-moro","tag-pt","tag-stf","tag-lula","tag-mendes"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/9625","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/comments?post=9625"}],"version-history":[{"count":3,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/9625\/revisions"}],"predecessor-version":[{"id":9635,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/9625\/revisions\/9635"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/media\/9633"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/media?parent=9625"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/categories?post=9625"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/tags?post=9625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}