{"id":9620,"date":"2024-10-29T07:24:33","date_gmt":"2024-10-29T10:24:33","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/?p=9620"},"modified":"2024-10-29T07:24:33","modified_gmt":"2024-10-29T10:24:33","slug":"nas-entrelinhas-eleicao-nos-eua-influenciara-futuro-de-lula","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/nas-entrelinhas-eleicao-nos-eua-influenciara-futuro-de-lula\/","title":{"rendered":"Nas entrelinhas: Elei\u00e7\u00e3o nos EUA influenciar\u00e1 futuro de Lula"},"content":{"rendered":"<p><em><strong>A estreita vantagem de Kamala nas pesquisas, ao manter Trump como uma alternativa de poder, tamb\u00e9m repercute na geopol\u00edtica e na economia global<\/strong><\/em><\/p>\n<p>A uma semana para as elei\u00e7\u00f5es nos Estados Unidos, 5 de novembro, as pesquisas mostram que, nesta reta final, a disputa entre a vice-presidente Kamala Harris e o ex-presidente Donald Trump \u00e9 dram\u00e1tica. Seu resultado \u00e9 incerto, por\u00e9m ser\u00e1 uma vari\u00e1vel externa a ser levada em conta pelo governo Lula, tendo em vista sua repercuss\u00e3o na pol\u00edtica interna brasileira at\u00e9 as elei\u00e7\u00f5es de 2026.<\/p>\n<p>Eleita, Kamala ser\u00e1 a primeira mulher a presidir os Estados Unidos e uma aliada natural de Lula. Se as contradi\u00e7\u00f5es geopol\u00edticas entre os dois pa\u00edses n\u00e3o se aprofundarem, sua vit\u00f3ria ser\u00e1 uma esp\u00e9cie de &#8220;mais do mesmo&#8221; em rela\u00e7\u00e3o \u00e0 pol\u00edtica do presidente Joe Biden. Seus principais pontos de tens\u00e3o com Lula s\u00e3o as guerras da Ucr\u00e2nia e de Gaza. Venezuela e Nicar\u00e1gua, \u00e1reas sens\u00edveis para o Itamaraty, hoje, mais aproximam do que distanciam o Brasil dos Estados Unidos. A rela\u00e7\u00e3o do Brasil com a China, nosso maior parceiro comercial, para onde vai a maior parte da nossa produ\u00e7\u00e3o agr\u00edcola, n\u00e3o interfere nas rela\u00e7\u00f5es com os Estados Unidos, o maior mercado para a nossa ind\u00fastria, a ponto de estressar o di\u00e1logo de Lula com Biden.<\/p>\n<p>Entretanto, uma eventual vit\u00f3ria de Trump pode alterar muito esse cen\u00e1rio, talvez mais at\u00e9 em rela\u00e7\u00e3o \u00e0 nossa pol\u00edtica interna. Explica-se: as posi\u00e7\u00f5es de Trump s\u00e3o mais pr\u00f3ximas do Brasil em rela\u00e7\u00e3o \u00e0 Ucr\u00e2nia, porque o ex-presidente dialoga com Putin, ao contr\u00e1rio de Biden, por\u00e9m s\u00e3o mais distantes quanto ao Oriente M\u00e9dio. Se depender do ex-presidente norte-americano, a disputa comercial com a China deve ser intensificada, e o equil\u00edbrio do Brasil entre as duas canoas ser\u00e1 mais dif\u00edcil, porque a reestrutura\u00e7\u00e3o das cadeias de valor regionais ser\u00e1 mais acelerada. A expans\u00e3o do Brics reflete essa reestrutura\u00e7\u00e3o; em contrapartida, o acordo do Mercosul com a Uni\u00e3o Europeia n\u00e3o sai do papel.<\/p>\n<p>Mas o grande problema \u00e9 a repercuss\u00e3o que uma eventual vit\u00f3ria de Trump ter\u00e1 na nossa pol\u00edtica interna. Lula teve o apoio decisivo de Biden na disputa eleitoral contra Jair Bolsonaro, um dos fatores que ajudou a frustrar a tentativa de golpe de Estado de 8 de janeiro, no entanto, uma vit\u00f3ria de Trump levaria \u00e1gua para o moinho do ex-presidente brasileiro, ainda que esteja ineleg\u00edvel. Os resultados das elei\u00e7\u00f5es municipais de domingo mostram que Bolsonaro se isolou e foi derrotado pelas for\u00e7as de centro-direita, entretanto o bolsonarismo continua sendo uma for\u00e7a eleitoral consider\u00e1vel. Os resultados eleitorais do PL demostram isso.<\/p>\n<p>Trump e Bolsonaro s\u00e3o aliados diante de um espelho. T\u00eam posi\u00e7\u00f5es muito pr\u00f3ximas em rela\u00e7\u00e3o \u00e0 Venezuela e a Israel. Mais do que isso, t\u00eam uma vis\u00e3o de mundo semelhante, com vi\u00e9s bastante autorit\u00e1rio, sobre os respectivos pa\u00edses e suas institui\u00e7\u00f5es. Um dos principais financiadores da campanha de Trump \u00e9 o magnata da tecnologia Elon Musk, desafeto de Lula e aliado de Bolsonaro. N\u00e3o ser\u00e1 f\u00e1cil a vida de Lula com uma eventual vit\u00f3ria do republicano.<\/p>\n<p><strong>Disputa indefinida<\/strong><\/p>\n<p>A estreita vantagem de Kamala nas pesquisas, ao manter Trump como uma alternativa de poder, tamb\u00e9m repercute na geopol\u00edtica e na economia global. Kamala lidera desde o debate com Trump na Pensilv\u00e2nia, em 10 de dezembro, quando virou o jogo numa disputa na qual o presidente Biden estava sendo derrotado. Ocorre que os EUA utilizam um sistema de col\u00e9gio eleitoral para eleger seu presidente. Nele, conseguir eleger a maioria dos delegados \u00e9 mais importante do que a soma dos votos que os elegeram.<\/p>\n<p>Historicamente, a maioria dos estados vota sempre com os republicanos ou com os democratas, mas h\u00e1 aqueles nos quais a maioria varia de uma elei\u00e7\u00e3o para outra, ora vencem os republicanos, ora os democratas. S\u00e3o nesses estados que Kamala e Trump concentram a campanha eleitoral nesta reta final. No momento, as pesquisas est\u00e3o muito apertadas em sete estados considerados decisivos para a disputa. O principal \u00e9 a Pensilv\u00e2nia, que tem o maior n\u00famero de votos no col\u00e9gio eleitoral.<\/p>\n<p>Com Michigan e Wisconsin, esses redutos democratas se tornaram republicanos em 2016, desequilibrando a disputa em favor de Trump. Biden recuperou esses estados em 2020, mas a disputa de Harris com Trump nesses col\u00e9gios eleitorais est\u00e1 acirrad\u00edssima. Nacionalmente, a m\u00e9dia ponderada das \u00faltimas 13 pesquisas, calculada pelo Real Clear Politics, mostra Trump com 48,5% das inten\u00e7\u00f5es de voto, e Kamala com 48,3%. Na mesma fase final do pleito de 2020, Joe Biden mantinha 7,4 pontos de vantagem sobre o republicano.<\/p>\n<p>Analistas registram uma estagna\u00e7\u00e3o na campanha de Kamala que contrasta com sua capacidade de arrecada\u00e7\u00e3o. Essa defasagem seria consequ\u00eancia da grande preocupa\u00e7\u00e3o dos eleitores com a economia. Biden conseguiu reduzir a infla\u00e7\u00e3o sem provocar uma recess\u00e3o, mas os resultados positivos n\u00e3o est\u00e3o se traduzindo em votos. A maioria dos eleitores tem melhores expectativas econ\u00f4micas em rela\u00e7\u00e3o a Trump.<\/p>\n<p>Al\u00e9m disso, o discurso negacionista de Trump em rela\u00e7\u00e3o ao clima, suas posi\u00e7\u00f5es contra os gastos militares com a Organiza\u00e7\u00e3o do Tratado do Atl\u00e2ntico Norte (Otan) e as acusa\u00e7\u00f5es de que s\u00f3 perde a elei\u00e7\u00e3o se houver fraude ainda t\u00eam resson\u00e2ncia junto a grande contingente de eleitores. Trump explora a inseguran\u00e7a provocada pelas mudan\u00e7as econ\u00f4micas na vida dos trabalhadores americanos e os preconceitos da sociedade em rela\u00e7\u00e3o aos imigrantes, bandeiras de campanha que o ajudaram a vencer em 2016.<\/p>\n<p><em>Todas as colunas anteriores no Blog do Azedo<\/em>:\u00a0<a href=\"https:\/\/blogs.correiobraziliense.com.br\/azedo\/\">https:\/\/blogs.correiobraziliense.com.br\/azedo\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A estreita vantagem de Kamala nas pesquisas, ao manter Trump como uma alternativa de poder, tamb\u00e9m repercute na geopol\u00edtica e na economia global A uma semana para as elei\u00e7\u00f5es nos Estados Unidos, 5 de novembro, as pesquisas mostram que, nesta reta final, a disputa entre a vice-presidente Kamala Harris e o ex-presidente Donald Trump \u00e9 dram\u00e1tica. Seu resultado \u00e9 incerto, [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":9626,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1223,481,722,677,36,980,589,370,4,277,369,972,8,9,3,1103,1136],"tags":[840,130,1737,165,58,10],"class_list":["post-9620","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasilia","category-china","category-ciencia","category-comunicacao","category-economia","category-eleicoes-2","category-eua","category-exportacoes","category-governo","category-israel","category-itamaraty","category-memoria","category-partidos","category-politica-2","category-politica","category-russia","category-ucrania","tag-biden","tag-bolsonaro","tag-kamala","tag-putin","tag-trump","tag-lula"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/9620","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/comments?post=9620"}],"version-history":[{"count":2,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/9620\/revisions"}],"predecessor-version":[{"id":9627,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/9620\/revisions\/9627"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/media\/9626"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/media?parent=9620"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/categories?post=9620"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/tags?post=9620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}