{"id":9496,"date":"2024-09-27T07:51:14","date_gmt":"2024-09-27T10:51:14","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/?p=9496"},"modified":"2024-09-27T07:52:24","modified_gmt":"2024-09-27T10:52:24","slug":"pesquisa-aponta-segundo-turno-entre-nunes-e-boulos-porem","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/pesquisa-aponta-segundo-turno-entre-nunes-e-boulos-porem\/","title":{"rendered":"Pesquisa aponta segundo turno entre Nunes e Boulos, por\u00e9m&#8230;"},"content":{"rendered":"<p><em><strong>O Brasil est\u00e1 de olho nas elei\u00e7\u00f5es em S\u00e3o Paulo, porque o ocupante da cadeira de prefeito, com o or\u00e7amento de R$ 111,8 bilh\u00f5es, sempre tem proje\u00e7\u00e3o nacional<\/strong><\/em><\/p>\n<p>Pesquisa Datafolha divulgada nesta quinta-feira (26) sobre a disputa pela Prefeitura de S\u00e3o Paulo mostra Ricardo Nunes (MDB) com 27% de inten\u00e7\u00f5es de votos, Guilherme Boulos (Psol) com 25%, e Pablo Mar\u00e7al (PRTB) com 21%. O empate t\u00e9cnico entre Nunes e Boulos e a resili\u00eancia de Mar\u00e7al, que manteve o terceiro lugar, deixam a elei\u00e7\u00e3o ainda indefinida, segundo as respectivas campanhas. Tabata Amaral (PSB), com 9%, teve ligeira recupera\u00e7\u00e3o; e Jos\u00e9 Luiz Datena (PSDB), manteve-se com 6%. A \u00fanica certeza \u00e9 a de que haver\u00e1 o segundo turno, mas quem deve ficar de fora, com esses resultados, permanece uma indefini\u00e7\u00e3o.<\/p>\n<p>O prefeito Ricardo Nunes manteve-se no patamar das duas \u00faltimas pesquisas do Datafolha. A pergunta \u00e9 se este \u00e9 o seu teto eleitoral, depois de uma arrancada espetacular no in\u00edcio da propaganda eleitoral na tev\u00ea. Boulos cedeu um ponto e voltou \u00e0 posi\u00e7\u00e3o do come\u00e7o de setembro, depois de ter chegado a 27% na pesquisa passada. Mar\u00e7al recuperou-se dos desgastes dos debates, chegando ao patamar em que estava em agosto, depois de cair de 22% para 19% dos votos. Tabata cresceu um ponto percentual e Datena manteve se na mesma. Algumas considera\u00e7\u00f5es sobre as elei\u00e7\u00f5es em S\u00e3o Paulo.<\/p>\n<p><strong>Nacionaliza\u00e7\u00e3o<\/strong><\/p>\n<p>O Brasil inteiro est\u00e1 de olho nas elei\u00e7\u00f5es em S\u00e3o Paulo, porque o ocupante da cadeira de prefeito, com o or\u00e7amento de R$ 111,8 bilh\u00f5es, sempre tem proje\u00e7\u00e3o de poder nacional. Entretanto, o eixo da disputa n\u00e3o s\u00e3o as quest\u00f5es nacionais nem o confronto pol\u00edtico entre o presidente Luiz In\u00e1cio Lula da Silva, que apoia Boulos, e o ex-presidente Jair Bolsonaro, que est\u00e1 com Nunes. S\u00e3o os problemas da popula\u00e7\u00e3o da maior cidade do pa\u00eds, com 11, 45 milh\u00f5es de habitantes. Por isso mesmo, o ator externo \u00e0s elei\u00e7\u00f5es municipais mais influente \u00e9 o governador Tarc\u00edsio de Freitas (PR), com mais poder de transfer\u00eancia de votos. Lula venceu as elei\u00e7\u00f5es presidenciais na capital, mas at\u00e9 agora n\u00e3o se envolveu diretamente na campanha, exceto na articula\u00e7\u00e3o da chapa com a ex-prefeita Marta Suplicy, que voltou ao PT, e no lan\u00e7amento da candidatura de Boulos.<\/p>\n<p><strong>M\u00e1quina p\u00fablica<\/strong><\/p>\n<p>O peso das estruturas administrativas do governo estadual e da prefeitura, que muitas vezes se anularam, quando o governador e o prefeito eram advers\u00e1rios, nestas elei\u00e7\u00f5es favorecem bastante a candidatura de Nunes, principalmente nas periferias, onde o uso dos servi\u00e7os p\u00fablicos \u00e9 um fator decisivo na vida da popula\u00e7\u00e3o de baixa renda. Nesses segmentos, onde o PT j\u00e1 foi hegem\u00f4nico, o que alavanca a candidatura de Boulos \u00e9 o prest\u00edgio de Marta Suplicy, com muitas realiza\u00e7\u00f5es administrativas, principalmente nas \u00e1reas de educa\u00e7\u00e3o e transportes. Mar\u00e7al tem penetra\u00e7\u00e3o por causa da narrativa de empreendedor bem-sucedido.<\/p>\n<p>Nesse aspecto, a Zona Leste da capital, que sempre protagonizou a grande onda eleitoral da reta final da campanha, \u00e9 o terreno de disputa mais acirrada entre os candidatos. Nessa regi\u00e3o, as demandas sociais s\u00e3o muito fortes, o que gera uma camada de eleitores insatisfeitos com as administra\u00e7\u00f5es, quaisquer que sejam. Por isso mesmo, nesta reta final, as agendas dos tr\u00eas candidatos transformaram a Zona Leste no principal campo de batalha eleitoral.<\/p>\n<p><strong>Viol\u00eancia e rejei\u00e7\u00e3o<\/strong><\/p>\n<p>O aspecto mais negativo das elei\u00e7\u00f5es de S\u00e3o Paulo vem sendo a viol\u00eancia entre candidatos. A virul\u00eancia verbal de Mar\u00e7al nas redes sociais, reproduzida durante os debates, derivou para as agress\u00f5es f\u00edsica, seja quando recebeu uma cadeirada de Datena ou quando seu assessor agrediu o marqueteiro de Nunes, Nahuel Meina. Os epis\u00f3dios foram muito criticados pela m\u00eddia, impactaram a campanha de Mar\u00e7al, mas foram decantados, como mostra a pesquisa.<\/p>\n<p>Onde seus efeitos ainda podem ser observados? Na rejei\u00e7\u00e3o dos candidatos. H\u00e1 uma vantagem estrat\u00e9gica do prefeito Nunes, que tem apenas 21% de rejei\u00e7\u00e3o, o que \u00e9 surpreendente para quem administra uma cidade do tamanho de S\u00e3o Paulo. Mar\u00e7al, por\u00e9m, bateu 48% de rejei\u00e7\u00e3o. A rejei\u00e7\u00e3o tamb\u00e9m \u00e9 o maior desafio para Boulos, com 38%, principalmente se chegar ao segundo turno. Hoje, segundo o Datafolha, Nunes venceria o segundo turno contra Boulos ou Mar\u00e7al; Boulos, por\u00e9m, venceria Mar\u00e7al.<\/p>\n<p>A maior dificuldade de Boulos \u00e9 atrair os eleitores de Tabata e Datena no segundo turno, ainda que ambos venham a apoi\u00e1-lo, porque nas atuais pesquisas eles derivam majoritariamente para Nunes. Um segmento de classe m\u00e9dia e grande parcela da elite paulista veem Boulos como um radical de esquerda e patrocinador de invas\u00f5es, por sua trajet\u00f3ria de l\u00edder dos sem-teto de S\u00e3o Paulo. Ontem, por\u00e9m, ao ser questionado durante entrevista na TV Globo, surpreendeu os pr\u00f3prios correligion\u00e1rios ao classificar a Venezuela como uma ditadura, em franca oposi\u00e7\u00e3o ao PT. Entretanto, ainda precisa convencer esses eleitores de que pode resolver o problema dos moradores de rua sem permitir invas\u00f5es.<\/p>\n<p><em>Todas as colunas anteriores no Blog do Azedo<\/em>:\u00a0<a href=\"https:\/\/blogs.correiobraziliense.com.br\/azedo\/\">https:\/\/blogs.correiobraziliense.com.br\/azedo\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Brasil est\u00e1 de olho nas elei\u00e7\u00f5es em S\u00e3o Paulo, porque o ocupante da cadeira de prefeito, com o or\u00e7amento de R$ 111,8 bilh\u00f5es, sempre tem proje\u00e7\u00e3o nacional Pesquisa Datafolha divulgada nesta quinta-feira (26) sobre a disputa pela Prefeitura de S\u00e3o Paulo mostra Ricardo Nunes (MDB) com 27% de inten\u00e7\u00f5es de votos, Guilherme Boulos (Psol) com 25%, e Pablo Mar\u00e7al [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[176,980,1642,8,3,9,323,68],"tags":[136,595,213,1721,1353,1352],"class_list":["post-9496","post","type-post","status-publish","format-standard","hentry","category-cidades","category-eleicoes-2","category-habitacao","category-partidos","category-politica","category-politica-2","category-sao-paulo","category-violencia","tag-boulos","tag-datafolha","tag-eleicoes","tag-marcal","tag-nunes","tag-saopaulo"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/9496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/comments?post=9496"}],"version-history":[{"count":4,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/9496\/revisions"}],"predecessor-version":[{"id":9503,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/9496\/revisions\/9503"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/media?parent=9496"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/categories?post=9496"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/tags?post=9496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}