{"id":8141,"date":"2023-08-12T09:12:21","date_gmt":"2023-08-12T12:12:21","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/?p=8141"},"modified":"2023-08-12T13:36:41","modified_gmt":"2023-08-12T16:36:41","slug":"nas-entrelinhas-como-e-dificil-escrever-sobre-a-morte-de-dad-squarisi","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/nas-entrelinhas-como-e-dificil-escrever-sobre-a-morte-de-dad-squarisi\/","title":{"rendered":"Nas entrelinhas: Como \u00e9 dif\u00edcil escrever sobre a morte de Dad Squarisi"},"content":{"rendered":"<p><em>&#8220;<strong>A admira\u00e7\u00e3o e o afeto continuam existindo, apesar da perda f\u00edsica. Hoje, me despe\u00e7o dessa grande dama do nosso idioma. Vai, Dad, ensinar portugu\u00eas nas estrelas!&#8221;<\/strong><\/em><\/p>\n<p>Conheci Dad Squarisi quando cheguei ao Correio Braziliense, em 2004, para ser rep\u00f3rter especial da Editoria de Pol\u00edtica. Nessa \u00e9poca, circulava na reda\u00e7\u00e3o uma mensagem do &#8220;Aqu\u00e1rio&#8221; \u2014 no jarg\u00e3o da reda\u00e7\u00e3o, a sala com paredes de vidros nas quais os editores da primeira p\u00e1gina se re\u00fanem para &#8220;fechar&#8221; o jornal. Eram observa\u00e7\u00f5es sobre a edi\u00e7\u00e3o do dia, entre as quais os erros de portugu\u00eas que escapavam da revis\u00e3o e eram devidamente assinalados, para que n\u00e3o se repetissem.<\/p>\n<p>Chamava-se &#8220;Pelourinho&#8221; e do\u00eda mais pela vergonha \u00edntima que pass\u00e1vamos do que pela dureza das cr\u00edticas. O pux\u00e3o de orelha n\u00e3o citava o autor nem a mat\u00e9ria. \u00c0s vezes, era uma dica para melhorar a qualidade do texto: &#8220;Fim de semana ou final de semana? Tanto faz. Ambos dizem a mesma coisa. Qual o prefer\u00edvel? Menor \u00e9 melhor. Fique com fim de semana. Voc\u00ea ganha uma s\u00edlaba.&#8221;<\/p>\n<p>Quando a frequ\u00eancia de erro aumentava, Dad programava uma aula de portugu\u00eas. O audit\u00f3rio do Correio ficava cheio. Foi o caso da v\u00edrgula nas ora\u00e7\u00f5es restritivas. Did\u00e1tica, tanto nas palestras quanto nas aulinhas, usava exemplos divertidos e &#8220;causos&#8221;, que parecia colecionar e catalogar. &#8220;Ora\u00e7\u00e3o explicativa pede a v\u00edrgula; restritiva, n\u00e3o&#8221;. Nos 100 anos da Associa\u00e7\u00e3o Brasileira de Imprensa (ABI), uma pe\u00e7a comemorativa fez muito sucesso: enaltecia a import\u00e2ncia da v\u00edrgula. Ela pode mudar o sentido de quase tudo.<\/p>\n<p>O Manual da Reda\u00e7\u00e3o do Correio, de autoria da Dad, com o tempo, virou obra rara. Como a rotatividade na reda\u00e7\u00e3o \u00e9 alta, o colega mudava de emprego e levava consigo o Manual. No principal jornal do Distrito Federal, Dad formava jornalistas para todas as \u00e1reas de uma reda\u00e7\u00e3o e a concorr\u00eancia vem em busca dos novos talentos. Para ningu\u00e9m levar meu exemplar, por engano, escrevi meu nome na lombada do manual, um &#8220;macete&#8221; do tempo dos dicion\u00e1rios de papel.<\/p>\n<p>Dad tinha uma sala s\u00f3 para ela e os editorialistas, mas circulava muito pela reda\u00e7\u00e3o. No meu caso, como sou rep\u00f3rter de pol\u00edtica e minha bancada fica pr\u00f3xima ao corredor principal da reda\u00e7\u00e3o, era comum ela parar para conversar comigo. Pedia uma informa\u00e7\u00e3o, \u00e0s vezes uma sugest\u00e3o de editorial. Fazia isso com a maior naturalidade, mas meu ego exultava, apesar de ser macaco velho: era uma esp\u00e9cie de reconhecimento de parte de algu\u00e9m que n\u00f3s t\u00ednhamos como refer\u00eancia profissional.<\/p>\n<p>Libanesa, Dad era poliglota \u2014 falava \u00e1rabe, ingl\u00eas, franc\u00eas e espanhol. Seus conhecimentos de latim, l\u00edngua muito citada nos tribunais, ajudava a reda\u00e7\u00e3o a n\u00e3o trocar via crucis por via-cr\u00facis. &#8220;Latim n\u00e3o usa h\u00edfen nem acento&#8221;, explicava. Algumas palavras em latim s\u00e3o inevit\u00e1veis numa reda\u00e7\u00e3o, como habeas corpus. No caso de Bras\u00edlia, carpe diem (aproveite o dia de hoje) tamb\u00e9m era um famoso bar da Asa Sul, muito frequentado por jornalistas e suas fontes. Dad nos deixou muitos livros sobre textos jornal\u00edsticos e a l\u00edngua portuguesa, alguns para crian\u00e7as.<\/p>\n<p><strong>Brava luta<\/strong><\/p>\n<p>Nossa &#8220;mestra&#8221; lutou bravamente contra o c\u00e2ncer. Ap\u00f3s seu tratamento no Albert Einstein, escreveu um livro sobre o hospital, em agradecimento aos m\u00e9dicos, enfermeiros e funcion\u00e1rios que a acolheram. A recidiva da leucemia, alguns anos depois, foi dur\u00edssima. Por isso, a frequ\u00eancia na reda\u00e7\u00e3o se tornou cada vez mais rarefeita nos \u00faltimos anos, mesmo antes de pandemia. Sua editora-adjunta, Rosane Garcia, amiga e disc\u00edpula, \u00e9 minha vizinha de bancada.<\/p>\n<p>Tive dois encontros casuais com Dad nesse per\u00edodo mais recente da doen\u00e7a. Um foi num pequeno restaurante italiano do Lago Sul \u2014 ela almo\u00e7ava com uma amiga jornalista. Estava abatida, mas sorridente. Era elegante por natureza e n\u00e3o deixava a peteca cair. N\u00e3o reclamava da vida, nem mesmo da dor. A outra foi bem mais recente, na \u00e1rea da piscina do apart-hotel onde morava. Conversava com outra amiga, que eu n\u00e3o conhecia. Estava muito mais fraca, mas continuava com aquele sorriso que a todos cativava.<\/p>\n<p>N\u00e3o posso dizer que sou um dos amigos da Dad no sentido estrito da palavra. Sou um dos seus colegas de trabalho e grande admirador. Foi um privil\u00e9gio conhec\u00ea-la e sei que sua morte \u00e9 uma imensa perda para o jornalismo e nossa cultura. \u00c9 muito dif\u00edcil a despedida definitiva, ainda mais numa idade em que a morte de pessoas pr\u00f3ximas, parentes, amigos e colegas de trabalho, \u00e9 cada vez mais frequente. Sempre fica aquela sensa\u00e7\u00e3o de que logo chegar\u00e1 a nossa hora, um sentimento que n\u00e3o t\u00ednhamos quando \u00e9ramos jovens e &#8220;imortais&#8221;.<\/p>\n<p>Estou de luto. Na coluna de sexta-feira, n\u00e3o consegui escrever sobre sua morte. Dad compreenderia: &#8220;Quem j\u00e1 passou horas diante de uma tela em branco de computador em d\u00favidas sobre por onde come\u00e7ar, sabe o que \u00e9 ang\u00fastia&#8221;. Para n\u00f3s, jornalistas, a morte \u00e9 uma not\u00edcia. Fomos treinados para tratar desse assunto jornalisticamente, ou seja, como um fato do cotidiano. \u00c9 comum nas reda\u00e7\u00f5es que os obitu\u00e1rios estejam prontos antes mesmo de algu\u00e9m importante falecer. Quando a ang\u00fastia se mistura com o luto, por\u00e9m, tudo fica muito dif\u00edcil.<\/p>\n<p>Embora a morte seja o que existe de mais previs\u00edvel nas nossas vidas, o rito da morte concentra e compacta toda uma vida, num momento \u00fanico. E o luto transcende o rito. \u00c9 que a admira\u00e7\u00e3o e o afeto continuam existindo, apesar da perda f\u00edsica. Hoje, me despe\u00e7o dessa grande dama do nosso idioma. Vai, Dad, ensinar portugu\u00eas nas estrelas!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;A admira\u00e7\u00e3o e o afeto continuam existindo, apesar da perda f\u00edsica. Hoje, me despe\u00e7o dessa grande dama do nosso idioma. Vai, Dad, ensinar portugu\u00eas nas estrelas!&#8221; Conheci Dad Squarisi quando cheguei ao Correio Braziliense, em 2004, para ser rep\u00f3rter especial da Editoria de Pol\u00edtica. Nessa \u00e9poca, circulava na reda\u00e7\u00e3o uma mensagem do &#8220;Aqu\u00e1rio&#8221; \u2014 no jarg\u00e3o da reda\u00e7\u00e3o, a sala [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1223,677,28,38,92,972,3],"tags":[985,1475,1476,733,1477],"class_list":["post-8141","post","type-post","status-publish","format-standard","hentry","category-brasilia","category-comunicacao","category-cultura","category-educacao","category-literatura","category-memoria","category-politica","tag-brasilia","tag-dad","tag-jornalismo","tag-luto","tag-portugues"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/8141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/comments?post=8141"}],"version-history":[{"count":5,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/8141\/revisions"}],"predecessor-version":[{"id":8151,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/8141\/revisions\/8151"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/media?parent=8141"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/categories?post=8141"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/tags?post=8141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}