{"id":7566,"date":"2023-02-03T06:21:41","date_gmt":"2023-02-03T09:21:41","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/?p=7566"},"modified":"2023-02-03T06:21:41","modified_gmt":"2023-02-03T09:21:41","slug":"nas-entrelinhas-entre-o-mito-do-super-heroi-e-a-fama-de-traidor","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/nas-entrelinhas-entre-o-mito-do-super-heroi-e-a-fama-de-traidor\/","title":{"rendered":"Nas entrelinhas: Entre o mito do super-her\u00f3i e a fama de traidor"},"content":{"rendered":"<p><em><strong>Do Val pode ser o elo perdido da conspira\u00e7\u00e3o para impedir a posse do Lula e, depois, para destitu\u00ed-lo. A sua reuni\u00e3o com o presidente Bolsonaro e Daniel Silveira se encaixa perfeitamente na trama golpista<\/strong><\/em><\/p>\n<p>Autor do best-seller O Nome da Rosa, o escritor italiano Umberto Eco nasceu em 1932, em Alessandria, no noroeste da It\u00e1lia, e cresceu \u00e0 sombra do fascismo. Aos 10 anos, venceu um concurso de reda\u00e7\u00e3o sobre o tema &#8220;Devemos morrer pela gl\u00f3ria de Mussolini e pelo destino imortal da It\u00e1lia?&#8221;. Muitos anos mais tarde, num ensaio publicado no The New York Review of Books, relembrou o epis\u00f3dio para explicar as muitas faces do fascismo: &#8220;Minha resposta foi positiva. Eu era um garoto esperto&#8221;, escreveu, ironicamente.<\/p>\n<p>Para ele, uma das caracter\u00edsticas do fascismo \u00e9 a obsess\u00e3o pela trama, segundo a qual todos os eventos da hist\u00f3ria s\u00e3o resultados de conluios secretos. Obviamente, essa \u00e9 uma das caracter\u00edsticas de seus livros, entre os quais O p\u00eandulo de Foucault, Cemit\u00e9rio de Praga e Seis passeios pelos bosques da fic\u00e7\u00e3o. N\u00famero Zero, o \u00faltimo romance de Eco, p\u00f5e em cena um jornalista italiano que tenta provar a tese de que Mussolini n\u00e3o foi morto em 1945. Umberto Eco era um estudioso da cultura de massas, em particular dos her\u00f3is das hist\u00f3rias em quadrinhos.<\/p>\n<p>\u00c9 o caso, por exemplo, do Superman. Eco define a mitifica\u00e7\u00e3o como um simbolismo inconsciente, a identifica\u00e7\u00e3o nem sempre racional, que projeta desejos, comportamentos e medos emergente nos indiv\u00edduos, nas comunidades ou em toda uma \u00e9poca hist\u00f3rica. O Superman \u00e9 um mito moderno. O her\u00f3i dotado de poderes superiores aos do homem comum \u00e9 uma constante da imagina\u00e7\u00e3o popular.<\/p>\n<p>Entretanto, os super-her\u00f3is das hist\u00f3rias em quadrinhos se humanizam na medida em que alguns de seus atributos s\u00e3o os mesmos de um homem comum, como \u00e9 o caso do personagem Clark Kent, o her\u00f3i que possui uma identidade secreta. Com \u00f3culos e penteado diferenciado, Clark consegue confundir seus colegas de trabalho e fazer com que ningu\u00e9m desconfie que, na verdade, \u00e9 o Superman. A aproxima\u00e7\u00e3o entre o her\u00f3i e o leitor se d\u00e1 no campo dessa possibilidade.<\/p>\n<p>O homem comum pode exercer a mesma virtude, aquela que dar\u00e1 o desfecho mais importante da hist\u00f3ria, mas n\u00e3o \u00e9 baseada na for\u00e7a f\u00edsica ou em caracter\u00edsticas supra-humanas. No trabalho, Kent \u00e9 um tanto atrapalhado, n\u00e3o tem proje\u00e7\u00e3o social relevante e \u00e9 m\u00edope, apesar de ter uma vis\u00e3o de raio-x. Constr\u00f3i-se um mito, tamb\u00e9m, pela identifica\u00e7\u00e3o e aproxima\u00e7\u00e3o. O indiv\u00edduo comum, funcion\u00e1rio, sem recursos, dotes e for\u00e7a, se identifica imediatamente.<\/p>\n<p>Eco era professor da Universidade de Bolonha, nos campos da cr\u00edtica cultural, da semiologia e do medievalismo, al\u00e9m de romancista. Como ensa\u00edsta e cr\u00edtico, navegou entre James Joyce e o Super-Homem. Morreu em decorr\u00eancia de c\u00e2ncer, em 19 de fevereiro de 2016, aos 84 anos, em Mil\u00e3o, na companhia da mulher e de 30.000 livros. Em 2015, ao ser homenageado na Universidade de Torino, criou grande pol\u00eamica ao dizer que a internet deu voz a multid\u00f5es de imbecis.<\/p>\n<p><strong>Teorias conspirat\u00f3rias<\/strong><\/p>\n<p>O senador Marcos Do Val (Podemos-ES) \u00e9 um personagem das redes sociais que nos remete \u00e0s hist\u00f3rias em quadrinhos. Criado por um velho mestre japon\u00eas de Aikido, arte marcial na qual \u00e9 faixa-preta 2\u00ba dan, depois de prestar servi\u00e7o militar no Ex\u00e9rcito, no in\u00edcio dos anos 1990, fundou a CATI, empresa de seguran\u00e7a voltada ao treinamento avan\u00e7ado de policiais, focado no uso n\u00e3o violento da for\u00e7a. Por meio dessa empresa, ministrou cursos e palestras que visam a difus\u00e3o de diversas t\u00e9cnicas e doutrinas inerentes a abordagens e imobiliza\u00e7\u00f5es t\u00e1ticas n\u00e3o letais.<\/p>\n<p>Ganhou fama ap\u00f3s se tornar instrutor da pol\u00edcia de Dallas, Texas, nos EUA, nas unidades da SWAT, no final dos anos 1990. Isso lhe abriu as portas para o treinamento de agentes do FBI, DEA, U.S. Marshalls, o grupo antiterrorismo da equipe de Opera\u00e7\u00f5es Especiais da Nasa (a Marshall Space Flight Center), a seguran\u00e7a do Vaticano, a Carabineri da Pol\u00edcia de Roma e para militares das For\u00e7as Armadas Americanas. Tornou-se, assim, uma esp\u00e9cie de mito entre os capixabas e ganhou muita proje\u00e7\u00e3o nas redes sociais entre os bolsonaristas, que lhe garantiu a elei\u00e7\u00e3o ao Senado.<\/p>\n<p>Do Val pode ser o elo perdido da conspira\u00e7\u00e3o para impedir a posse do Lula e, depois, para destitu\u00ed-lo, em 8 de janeiro. A sua reuni\u00e3o com o presidente Jair Bolsonaro e Daniel Silveira, na qual teria sido proposto que gravasse uma conversa comprometedora com o presidente do Tribunal Superior Eleitoral (TSE), ministro Alexandre de Moraes, se encaixa perfeitamente na trama golpista. Os dois supostos encontros com o ministro, no qual relatou o convite e as conversas ocorridas no encontro, tamb\u00e9m. A troca de mensagens com Silveira, idem.<\/p>\n<p>Isso explicaria o teor da minuta de decreto encontrada na casa do ex-ministro da Justi\u00e7a Anderson Torres, outros fatos protagonizados por Bolsonaro e seus aliados de extrema direita, bem como as decis\u00f5es tomadas por Moraes na sequ\u00eancia desses epis\u00f3dios. Mas acontece que, a cada entrevista, Do Val muda a vers\u00e3o dos fatos, a ponto de n\u00e3o lembrar se a reuni\u00e3o clandestina com Bolsonaro foi no Pal\u00e1cio do Alvorada ou na Granja do Torto.<\/p>\n<p>\u00c9 a\u00ed que surgem as teorias conspirat\u00f3rias de que estaria fazendo a den\u00fancia para provocar uma CPI no Senado ou, mesmo, provocar o afastamento de Moraes nas investiga\u00e7\u00f5es. Num de seus depoimentos, queixou-se de ser chamado de traidor nas redes sociais pelos bolsonaristas, o que teria motivado a sua decis\u00e3o de contar tudo o que sabe. Tanta contradi\u00e7\u00e3o, agora, tamb\u00e9m alimenta a tese de que Do Val se tornou um mit\u00f4mano. A persona do super-her\u00f3i nas redes sociais est\u00e1 sendo desconstru\u00edda por seus advers\u00e1rios de esquerda e antigos aliados de direita.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Do Val pode ser o elo perdido da conspira\u00e7\u00e3o para impedir a posse do Lula e, depois, para destitu\u00ed-lo. A sua reuni\u00e3o com o presidente Bolsonaro e Daniel Silveira se encaixa perfeitamente na trama golpista Autor do best-seller O Nome da Rosa, o escritor italiano Umberto Eco nasceu em 1932, em Alessandria, no noroeste da It\u00e1lia, e cresceu \u00e0 sombra [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1223,677,6,28,980,371,4,7,92,972,113,8,9,3,80,68],"tags":[130,1331,202,676,375,119,1332,79,1330,10],"class_list":["post-7566","post","type-post","status-publish","format-standard","hentry","category-brasilia","category-comunicacao","category-congresso","category-cultura","category-eleicoes-2","category-etica","category-governo","category-justica","category-literatura","category-memoria","category-militares","category-partidos","category-politica-2","category-politica","category-seguranca","category-violencia","tag-bolsonaro","tag-eco","tag-fascismo","tag-golpismo","tag-moraes","tag-senado","tag-superman","tag-supremo","tag-val","tag-lula"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/7566","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/comments?post=7566"}],"version-history":[{"count":2,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/7566\/revisions"}],"predecessor-version":[{"id":7572,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/7566\/revisions\/7572"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/media?parent=7566"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/categories?post=7566"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/tags?post=7566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}