{"id":7051,"date":"2022-09-06T07:28:16","date_gmt":"2022-09-06T10:28:16","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/?p=7051"},"modified":"2022-09-06T08:00:08","modified_gmt":"2022-09-06T11:00:08","slug":"nas-entrelinhas-o-recado-que-vem-dos-chilenos","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/nas-entrelinhas-o-recado-que-vem-dos-chilenos\/","title":{"rendered":"Nas entrelinhas: O recado que vem dos chilenos"},"content":{"rendered":"<p><em><strong>Lula da Silva \u00e9 favorito, com uma narrativa voltada para o passado, ou seja, as realiza\u00e7\u00f5es de seus dois mandatos, e uma agenda opaca em rela\u00e7\u00e3o ao futuro, como quem deseja assumir o poder com carta branca <\/strong><\/em><\/p>\n<p>Por esmagadora maioria \u2014 61,86% \u2014, os chilenos rejeitaram a proposta de uma nova Constitui\u00e7\u00e3o, que buscava estabelecer maiores direitos sociais e ampliar a democracia chilena. Apenas 38,14% do eleitorado votaram a favor do texto, com 99,97% da apura\u00e7\u00e3o oficial conclu\u00edda. O resultado surpreendeu o mundo pol\u00edtico e a pr\u00f3pria m\u00eddia chilena. Com o voto obrigat\u00f3rio, 13 milh\u00f5es de eleitores participaram do plebiscito, cujo objetivo era referendar a nova Constitui\u00e7\u00e3o, em substitui\u00e7\u00e3o \u00e0 Carta de 1980, do regime de Augusto Pinochet, reformada durante o governo de Ricardo Lagos, em 2005.<\/p>\n<p>O &#8220;Rechazo&#8221; da nova Constitui\u00e7\u00e3o foi geral, vitorioso, inclusive, na Grande Santiago, onde a esquerda e a centro-esquerda sempre foram maioria. &#8220;Esse Chile n\u00e3o \u00e9 apenas Santiago; n\u00e3o foi uma elei\u00e7\u00e3o municipal, para se falar em bairros ricos e pobres. H\u00e1 um sentimento de unidade nacional que se imp\u00f4s democraticamente. A esquerda mais identit\u00e1ria (de todos os tipos de identitarismo) fracassou em sua perspectiva hegem\u00f4nica. Isso n\u00e3o se chama &#8216;progressismo&#8217;, j\u00e1 que parte dos progressistas n\u00e3o apoiou a op\u00e7\u00e3o apruebo&#8221;, destaca o historiador Alberto Aggio, professor titular de Hist\u00f3ria da Unesp (Universidade Estadual Paulista) de Franca (SP), especialista na pol\u00edtica chilena.<\/p>\n<p>Segundo ele, a disjuntiva refunda\u00e7\u00e3o versus pinochetismo fracassou, porque era uma leitura errada do sentimento da sociedade em seu conjunto. &#8220;N\u00e3o houve, da parte da &#8216;nova esquerda&#8217;, apenas um erro de c\u00e1lculo, de dire\u00e7\u00e3o e de voluntarismo; Boric corre um s\u00e9rio risco se n\u00e3o entender o que aconteceu. Sua \u00fanica op\u00e7\u00e3o &#8216;progressista&#8217; era e ainda \u00e9 um governo &#8216;mais amplo&#8217;, com apoio da ex- Concertaci\u00f3n; permanece o sentimento de elaborar e aprovar uma &#8216;nova Constitui\u00e7\u00e3o&#8217;, \u00e9 um sentimento majorit\u00e1rio no pa\u00eds.&#8221;<\/p>\n<p>Sua observa\u00e7\u00e3o \u00e9 muito importante diante do cen\u00e1rio eleitoral brasileiro, no qual o ex-presidente Luiz In\u00e1cio Lula da Silva (PT) \u00e9 favorito, com uma narrativa voltada para o passado, ou seja, as realiza\u00e7\u00f5es de seus dois mandatos, e uma agenda opaca em rela\u00e7\u00e3o ao futuro, como quem deseja assumir o poder com carta branca para promover reformas pol\u00edticas e institucionais. Ningu\u00e9m sabe quais s\u00e3o essas reformas, a n\u00e3o ser que sejam deduzidas da autocr\u00edtica que o PT fez ap\u00f3s o impeachment de Dilma Rousseff, o que n\u00e3o seria um bom sinal.<\/p>\n<p>Agenda identit\u00e1ria<\/p>\n<p>At\u00e9 agora, a estrat\u00e9gia eleitoral de Lula est\u00e1 fundada no apoio eleitoral das parcelas mais pobres da popula\u00e7\u00e3o e de uma frente de esquerda, que rejeitou alian\u00e7as ao centro nos maiores col\u00e9gios eleitorais do pa\u00eds, todas vi\u00e1veis quando Lula parecia imbat\u00edvel. O erro da esquerda chilena foi esquecer as li\u00e7\u00f5es da crise do governo Allende e do golpe de Pinochet. A Conven\u00e7\u00e3o Constitucional aut\u00f4noma, parit\u00e1ria, externa aos partidos e com uma maioria de independentes, que elaborou a nova Constitui\u00e7\u00e3o, traduziu o &#8220;estallido social&#8221; de outubro de 2019 para o texto da nova Carta, na linha de ultrapassagem da democracia representativa, dita burguesa. Foi o erro.<\/p>\n<p>A nova Constitui\u00e7\u00e3o consagrava a paridade entre homens e mulheres em todos os cargos p\u00fablicos; um &#8220;Estado plurinacional e intercultural&#8221;, reconhecendo 11 povos e na\u00e7\u00f5es (Mapuche, Aymara, Rapa Nui, Lickanantay, Qu\u00e9chua, Colla, Diaguita, Chango, Kawashkar, Yaghan, Selk&#8217;nam); direito \u00e0 natalidade e ao aborto aut\u00f4nomos; Estado de bem-estar social, com educa\u00e7\u00e3o, moradia, sa\u00fade, previd\u00eancia, trabalho; a extin\u00e7\u00e3o do Senado e a \u00e1gua como bem inapropri\u00e1vel (a crise h\u00eddrica chilena \u00e9 ser\u00edssima). Consagrava a utopia pol\u00edtica, mas o passo foi maior do que as pernas.<\/p>\n<p>A vit\u00f3ria de Gabriel Boric, jovem pol\u00edtico de esquerda radical, parecia dar uma dire\u00e7\u00e3o pol\u00edtica mais permanente ao processo iniciado em 2019, mas o novo presidente, antevendo as dificuldades, assumiu um perfil mais conciliador, apesar da forte oposi\u00e7\u00e3o \u00e0 esquerda. A nova Constitui\u00e7\u00e3o traduzia o desejo da esquerda chilena de refundar o pa\u00eds, mas essa n\u00e3o \u00e9 a vontade da maioria dos chilenos. Est\u00e1 posto um novo problema, porque tamb\u00e9m n\u00e3o se pode voltar \u00e0 velha Carta de Pinochet.<\/p>\n<p>A situa\u00e7\u00e3o do Chile serve de advert\u00eancia para a frente de esquerda que se formou em torno do ex-presidente Lula. O presidente Jair Bolsonaro (PL) faz campanha com uma agenda emergencial, alavanca sua candidatura com o pacote de bondades insustent\u00e1vel fiscalmente. Ciro Gomes (PDT) e Simone Tebet (MDB) tentam oferecer alternativas de futuro, sem os mesmos lastros de poder e\/ou eleitoral dos que lideram a disputa. A mesma coisa faz Felipe D&#8217;\u00c1vila (Novo) e Soraya Thronicke (Uni\u00e3o Brasil). Lula precisa apresentar sua alternativa para o futuro e recha\u00e7ar a veleidade de que o Brasil dar\u00e1 uma grande quinada \u00e0 esquerda. O que as pesquisas est\u00e3o mostrando \u00e9 outra coisa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lula da Silva \u00e9 favorito, com uma narrativa voltada para o passado, ou seja, as realiza\u00e7\u00f5es de seus dois mandatos, e uma agenda opaca em rela\u00e7\u00e3o ao futuro, como quem deseja assumir o poder com carta branca Por esmagadora maioria \u2014 61,86% \u2014, os chilenos rejeitaram a proposta de uma nova Constitui\u00e7\u00e3o, que buscava estabelecer maiores direitos sociais e ampliar [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[561,677,978,36,980,371,8,9,3],"tags":[130,1071,542,129,213,1222,1220,10],"class_list":["post-7051","post","type-post","status-publish","format-standard","hentry","category-chile","category-comunicacao","category-cuba","category-economia","category-eleicoes-2","category-etica","category-partidos","category-politica-2","category-politica","tag-bolsonaro","tag-boric","tag-chile","tag-ciro","tag-eleicoes","tag-simone-davila","tag-soraya","tag-lula"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/7051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/comments?post=7051"}],"version-history":[{"count":3,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/7051\/revisions"}],"predecessor-version":[{"id":7061,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/7051\/revisions\/7061"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/media?parent=7051"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/categories?post=7051"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/tags?post=7051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}