{"id":6896,"date":"2022-07-15T06:59:00","date_gmt":"2022-07-15T09:59:00","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/?p=6896"},"modified":"2022-07-15T07:12:18","modified_gmt":"2022-07-15T10:12:18","slug":"nas-entrelinhas-as-duas-taticas-de-bolsonaro-para-se-manter-no-poder","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/nas-entrelinhas-as-duas-taticas-de-bolsonaro-para-se-manter-no-poder\/","title":{"rendered":"Nas entrelinhas: As duas t\u00e1ticas de Bolsonaro para se manter no poder"},"content":{"rendered":"<p>O presidente Jair Bolsonaro opera simultaneamente duas t\u00e1ticas para se manter no poder. Ambas podem dar errado, se n\u00e3o conseguir reverter a grande vantagem do ex-presidente Luiz In\u00e1cio Lula da Silva nas elei\u00e7\u00f5es. Ambas se combinam quando \u00e0 possibilidade cada vez mais evidente de que planeja melar as elei\u00e7\u00f5es de outubro pr\u00f3ximo, caso seus resultados sejam desfavor\u00e1veis. A primeira, operada com extrema compet\u00eancia pelo Centr\u00e3o, \u00e9 a PEC da Elei\u00e7\u00e3o, promulgada ontem, com medidas para transferir recursos para a popula\u00e7\u00e3o de baixa renda, caminhoneiros e taxistas.<\/p>\n<p>A PEC nasceu no Senado, onde somente n\u00e3o conseguiu a unanimidade porque o senador Jos\u00e9 Serra (PSDB-SP), solitariamente, votou contra. Na C\u00e2mara, o presidente da Casa, Arthur Lira (PP-AL), operou um rolo compressor para que a emenda constitucional fosse aprovada em dois turnos e promulgada nesta semana, ap\u00f3s 72 horas de articula\u00e7\u00f5es, sess\u00f5es rel\u00e2mpagos e vota\u00e7\u00f5es. Somente o Novo e alguns parlamentares isolados em seus partidos, votaram contra a PEC.<\/p>\n<p>Na ess\u00eancia, a proposta tem um vi\u00e9s golpista, porque a legisla\u00e7\u00e3o eleitoral pro\u00edbe a ado\u00e7\u00e3o de medidas de car\u00e1ter assistencialista a menos de 100 dias elei\u00e7\u00f5es. Para que isso seja poss\u00edvel, o Congresso aprovou um &#8220;estado de emerg\u00eancia&#8221;, que possibilita descumprir a legisla\u00e7\u00e3o eleitoral, tendo como pretexto a guerra da Ucr\u00e2nia, por causa da crise dos combust\u00edveis. Com isso, a m\u00e1quina do governo federal ser\u00e1 usada para influenciar o voto dos eleitores de forma sem precedentes.<\/p>\n<p>A legisla\u00e7\u00e3o eleitoral estabelece um equil\u00edbrio entre a vontade dos pol\u00edticos no poder (\u00e9tica das convic\u00e7\u00f5es) e a legitimidade dos meios de sua atua\u00e7\u00e3o nas elei\u00e7\u00f5es (\u00e9tica da responsabilidade), a cargo dos \u00f3rg\u00e3os de controle do pr\u00f3prio Estado: Controladoria-Geral da Uni\u00e3o (CGU), Receita Federal, Pol\u00edcia Federal, Tribunal de Contas da Uni\u00e3o (TCU), Procuradoria-Geral das Rep\u00fablica (PGR) e Justi\u00e7a Eleitoral. Com a PEC, esses \u00f3rg\u00e3os nada poder\u00e3o fazer para evitar o abuso de poder econ\u00f4mico e outros crimes eleitorais, derivados da execu\u00e7\u00e3o da PEC em plena campanha eleitoral. A \u00fanica barreira a ser vencida \u00e9 a resist\u00eancia surda da pr\u00f3pria burocracia, respons\u00e1vel pela implementa\u00e7\u00e3o das medidas.<\/p>\n<p>A outra t\u00e1tica em curso, sob responsabilidade dos generais do Pal\u00e1cio do Planalto, \u00e9 semear a desconfian\u00e7a em rela\u00e7\u00e3o \u00e0 seguran\u00e7a das urnas eletr\u00f4nicas, corroborando os ataques que o presidente Jair Bolsonaro vem fazendo contra o Tribunal Superior Eleitoral (TSE) e os ministros Edson Fachin, atual presidente, e Alexandre de Moraes, o pr\u00f3ximo a comandar a Corte. Para isso, o Minist\u00e9rio da Defesa est\u00e1 sendo acionado, contrapondo o prest\u00edgio das For\u00e7as Armadas \u00e0 legitimidade do TSE no processo eleitoral, o que n\u00e3o \u00e9 nenhuma novidade na hist\u00f3ria republicana.<\/p>\n<p>O golpe<\/p>\n<p>Ontem, durante audi\u00eancia no Senado, palco de ataques \u00e0 Justi\u00e7a Eleitoral, o ministro da Defesa, general Paulo S\u00e9rgio Nogueira, chegou a propor que fosse utilizado o voto impresso durante a vota\u00e7\u00e3o, para checar as urnas eletr\u00f4nicas por amostragem, proposta j\u00e1 recusada pelo TSE. No encontro, o coronel Marcelo Nogueira de Souza, especialista em guerra cibern\u00e9tica, admitiu que as urnas s\u00e3o inviol\u00e1veis a ataques de hacker externos, por\u00e9m sustentou que n\u00e3o s\u00e3o seguras do ponto de vista de eventuais viola\u00e7\u00f5es internas, ou seja, colocou sob suspeita a pr\u00f3prio TSE.<\/p>\n<p>Mesmo que a inten\u00e7\u00e3o do ministro da Defesa n\u00e3o fosse p\u00f4r sob suspeita a seguran\u00e7a das elei\u00e7\u00f5es, o resultado pr\u00e1tico da audi\u00eancia foi fortalecer a percep\u00e7\u00e3o de que o presidente Bolsonaro n\u00e3o pretende aceitar um resultado desfavor\u00e1vel nas urnas, e as For\u00e7as Armadas estariam coniventes com isso. Imposs\u00edvel n\u00e3o lembrar do Plano Cohen, documento divulgado em 30 de setembro de 1937, com supostas &#8220;instru\u00e7\u00f5es da Internacional Comunista (Komintern) para a a\u00e7\u00e3o de seus agentes no Brasil&#8221;. Na realidade, tratava-se de um plano simulado como &#8220;hip\u00f3tese de trabalho&#8221;, segundo seu verdadeiro autor, o capit\u00e3o Ol\u00edmpio Mour\u00e3o Filho, ent\u00e3o chefe do servi\u00e7o secreto da A\u00e7\u00e3o Integralista Brasileira (AIB).<\/p>\n<p>Com base no Plano Cohen, o presidente Get\u00falio Vargas solicitou imediatamente ao Congresso autoriza\u00e7\u00e3o para decretar o estado de guerra pelo prazo de 90 dias. A aprova\u00e7\u00e3o da medida abriu caminho para o golpe do Estado Novo, desfechado em 10 de novembro de 1937, que suspendeu as elei\u00e7\u00f5es e institucionalizou a ditadura. A fraude do Plano Cohen s\u00f3 foi revelada ap\u00f3s a extin\u00e7\u00e3o do Estado Novo, em 1945.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O presidente Jair Bolsonaro opera simultaneamente duas t\u00e1ticas para se manter no poder. Ambas podem dar errado, se n\u00e3o conseguir reverter a grande vantagem do ex-presidente Luiz In\u00e1cio Lula da Silva nas elei\u00e7\u00f5es. Ambas se combinam quando \u00e0 possibilidade cada vez mais evidente de que planeja melar as elei\u00e7\u00f5es de outubro pr\u00f3ximo, caso seus resultados sejam desfavor\u00e1veis. A primeira, operada [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[677,37,36,980,371,4,7,972,113,8,9,3],"tags":[130,681,213,78,114,375,10],"class_list":["post-6896","post","type-post","status-publish","format-standard","hentry","category-comunicacao","category-desemprego","category-economia","category-eleicoes-2","category-etica","category-governo","category-justica","category-memoria","category-militares","category-partidos","category-politica-2","category-politica","tag-bolsonaro","tag-centrao","tag-eleicoes","tag-fachin","tag-militares","tag-moraes","tag-lula"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/6896","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/comments?post=6896"}],"version-history":[{"count":1,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/6896\/revisions"}],"predecessor-version":[{"id":6899,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/6896\/revisions\/6899"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/media?parent=6896"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/categories?post=6896"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/tags?post=6896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}