{"id":6643,"date":"2022-03-17T06:30:05","date_gmt":"2022-03-17T09:30:05","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/?p=6643"},"modified":"2022-03-17T06:30:05","modified_gmt":"2022-03-17T09:30:05","slug":"nas-entrelinhas-conspiracao-e-desespero-na-terceira-via","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/nas-entrelinhas-conspiracao-e-desespero-na-terceira-via\/","title":{"rendered":"Nas entrelinhas: Conspira\u00e7\u00e3o e desespero na terceira via"},"content":{"rendered":"<p><b><i>Apesar das adversidades eleitorais e da conspira\u00e7\u00e3o dos aliados, Doria n\u00e3o d\u00e1, at\u00e9 agora, nenhum sinal de que pretende desistir. Pelo contr\u00e1rio, aposta na sa\u00edda de Eduardo Leite do PSDB<\/i><\/b><\/p>\n<p>Uma opera\u00e7\u00e3o de cerco e aniquilamento da pr\u00e9-candidatura do governador de S\u00e3o Paulo, Jo\u00e3o Doria, como hav\u00edamos antecipado, est\u00e1 em pleno curso. Praticamente todas as lideran\u00e7as da chamada terceira via se articulam para substitu\u00ed-lo pelo governador do Rio Grande do Sul, Eduardo Leite, como o candidato unificado da terceira via. As conversas de bastidores no Congresso incluem, tamb\u00e9m, os deputados da bancada paulista aliados do vice Rodrigo Garcia.<\/p>\n<p>Derrotado por Doria nas pr\u00e9vias do PSDB, Eduardo Leite acredita que o cavalo est\u00e1 passando arreado para sua candidatura \u00e0 Presid\u00eancia, desta vez, para valer. Na primeira oportunidade, quem montou foi o governador paulista, que n\u00e3o est\u00e1 conseguindo bom desempenho na corrida presidencial. Doria empacou nas pesquisas. No levantamento do instituto Quaest\/Genial, divulgado, ontem, pela CNN, Doria aparece empatado com o deputado Andr\u00e9 Janones (Avante), ambos em quinto lugar, com 2% de inten\u00e7\u00f5es de votos.<\/p>\n<p>A pesquisa traduziu as dificuldades enfrentadas pelos partidos de centro para construir uma candidatura de terceira via, em raz\u00e3o da polariza\u00e7\u00e3o entre o ex-presidente Luiz In\u00e1cio Lula da Silva (PT), que aparece com 44% das inten\u00e7\u00f5es de voto, e o presidente Jair Bolsonaro (PL), com 26%. Empatados em terceiro lugar, com 7%, est\u00e3o os pr\u00e9-candidatos Sergio Moro (Podemos) e Ciro Gomes (PDT). Outra postulante do apoio da terceira via, a senadora Simone Tebet (MDB) aparece com 1%.<\/p>\n<p>Eduardo Leite est\u00e1 de malas prontas para o PSD, de Gilberto Kassab, com quem discutiu, inclusive, o apoio financeiro da legenda \u00e0 candidatura presidencial. O ex-prefeito de S\u00e3o Paulo garantiu ao governador ga\u00facho que as resist\u00eancias existentes na sigla est\u00e3o sendo superadas. Para o PSD, uma candidatura pr\u00f3pria \u00e9 vital para o partido, que hoje tem 11 senadores e pode chegar a 50 deputados. Se for bem-sucedida, a legenda estar\u00e1 entre as cinco maiores do pa\u00eds, ao lado de PT, Uni\u00e3o Brasil, PP e PL. A candidatura pr\u00f3pria, ainda mais com um pol\u00edtico jovem, de perfil liberal e ideais novas, daria mais identidade ao PSD. Sem uma candidatura com esse perfil, a divis\u00e3o da sigla ser\u00e1 inevit\u00e1vel, com uma ala derivando para o apoio \u00e0 reelei\u00e7\u00e3o de Bolsonaro e outra, capitaneada pelo pr\u00f3prio Kassab, apoiando Lula.<\/p>\n<p>A conversa de Leite com Kassab provocou um corre-corre na terceira via, com o deputado A\u00e9cio Neves (PSDB-MG), desafeto figadal de Doria, mobilizando aliados para segurar o governador ga\u00facho no PSDB, no pressuposto de que, na sua legenda de origem, teria mais possibilidades de receber apoio de Uni\u00e3o Brasil, MDB e Cidadania. Dirigentes das tr\u00eas legendas fizeram coro com A\u00e9cio, porque todos t\u00eam conhecimento de que as bancadas federais dessas siglas em S\u00e3o Paulo come\u00e7am a entrar em desespero com o fraco desempenho de Doria nas pesquisas. Prometem remover Doria, caso Leite permane\u00e7a no PSDB.<\/p>\n<p><strong>Maratona<\/strong><\/p>\n<p>O cen\u00e1rio eleitoral estimula a conspira\u00e7\u00e3o, porque a polariza\u00e7\u00e3o entre Lula e Bolsonaro em S\u00e3o Paulo est\u00e1 cristalizada e come\u00e7a a se refletir na disputa pelo Pal\u00e1cio dos Bandeirantes, com o alinhamento de seus eleitores com os candidatos que apoiam o ex-prefeito Fernando Haddad (PT) e o ministro da Infraestrutura, Tarc\u00edsio de Freitas. O vice-governador Rodrigo Garcia (PSDB), candidato de Doria, que tamb\u00e9m n\u00e3o decola, corre risco de virar marisco.<\/p>\n<p>No \u00faltimo levantamento do Ipespe, nos dois cen\u00e1rios principais, a posi\u00e7\u00e3o de Garcia n\u00e3o era boa. Na disputa com Haddad (PT), 28%; M\u00e1rcio Fran\u00e7a (PSB), 18%; Guilherme Boulos (PSol), 11%; e Tarc\u00edsio de Freitas (sem partido), 10%, o vice-governador tem apenas 5%. Brancos e nulos somam 24%, e n\u00e3o sabe\/n\u00e3o respondeu, 4%. No cen\u00e1rio mais prov\u00e1vel \u2014 Haddad, apoiado por Lula e Alckmin, com 38%; Tarc\u00edsio de Freitas, apoiado por Bolsonaro, com 25% \u2014, Garcia, com apoio de Doria, teria apenas 10%. Brancos e nulos somariam 23%; n\u00e3o sabe\/n\u00e3o respondeu, 4%.<\/p>\n<p>Apesar das adversidades eleitorais e da conspira\u00e7\u00e3o dos aliados, Doria n\u00e3o d\u00e1, at\u00e9 agora, nenhum sinal de que pretende desistir. Pelo contr\u00e1rio, aposta na sa\u00edda de Eduardo Leite do PSDB, que n\u00e3o aceita o resultado das pr\u00e9vias, e considera as articula\u00e7\u00f5es de A\u00e9cio Neves um gesto de desespero. Tamb\u00e9m n\u00e3o acredita que a bancada paulista desista, ap\u00f3s sua desincompatibiliza\u00e7\u00e3o, quando Rodrigo Garcia assumir\u00e1 o Pal\u00e1cio dos Bandeirantes, pois o acordo entre ambos j\u00e1 foi selado, na medida em que Doria n\u00e3o pretende, de forma alguma, concorrer \u00e0 reelei\u00e7\u00e3o.<\/p>\n<p>A agenda do governador paulista est\u00e1 focada na maratona de inaugura\u00e7\u00f5es que programou para seus \u00faltimos dias no cargo. Somente depois come\u00e7ar\u00e1 a pr\u00e9-campanha para a Presid\u00eancia, articulando seus palanques regionais. Doria tem muitos problemas a resolver fora de S\u00e3o Paulo para consolidar a federa\u00e7\u00e3o com o Cidadania e articular seus palanques majorit\u00e1rios. Em muitos estados, o PSDB est\u00e1 mais para Bolsonaro do que para Eduardo Leite.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apesar das adversidades eleitorais e da conspira\u00e7\u00e3o dos aliados, Doria n\u00e3o d\u00e1, at\u00e9 agora, nenhum sinal de que pretende desistir. Pelo contr\u00e1rio, aposta na sa\u00edda de Eduardo Leite do PSDB Uma opera\u00e7\u00e3o de cerco e aniquilamento da pr\u00e9-candidatura do governador de S\u00e3o Paulo, Jo\u00e3o Doria, como hav\u00edamos antecipado, est\u00e1 em pleno curso. Praticamente todas as lideran\u00e7as da chamada terceira via [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,980,8,3,9,1075,323],"tags":[266,146,944,186,325,1153],"class_list":["post-6643","post","type-post","status-publish","format-standard","hentry","category-congresso","category-eleicoes-2","category-partidos","category-politica","category-politica-2","category-rio-grande-do-sul","category-sao-paulo","tag-cidadania","tag-doria","tag-leite","tag-mdb","tag-psdb","tag-uniao-brasil"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/6643","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/comments?post=6643"}],"version-history":[{"count":2,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/6643\/revisions"}],"predecessor-version":[{"id":6649,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/6643\/revisions\/6649"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/media?parent=6643"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/categories?post=6643"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/tags?post=6643"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}