{"id":6251,"date":"2021-10-29T07:42:38","date_gmt":"2021-10-29T10:42:38","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/?p=6251"},"modified":"2021-10-29T07:42:38","modified_gmt":"2021-10-29T10:42:38","slug":"nas-entrelinhas-jogo-bruto-no-psdb","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/nas-entrelinhas-jogo-bruto-no-psdb\/","title":{"rendered":"Nas entrelinhas: Jogo bruto no PSDB"},"content":{"rendered":"<p><em><strong>A disputa no ninho tucano virou um jogo de xadrez entre os l\u00edderes partid\u00e1rios. A exclus\u00e3o dos 92 prefeitos e vice-prefeitos da vota\u00e7\u00e3o pode alterar o resultado final<\/strong><\/em><\/p>\n<p>A Executiva Nacional do PSDB decidiu, ontem, desconsiderar os votos de 92 prefeitos e vices de S\u00e3o Paulo recentemente filiados \u00e0 legenda nas pr\u00e9vias que v\u00e3o escolher o candidato do PSDB \u00e0 Presid\u00eancia da Rep\u00fablica. Partid\u00e1rios do governador ga\u00facho Eduardo Leite contestaram as filia\u00e7\u00f5es feitas pelo governador paulista Jo\u00e3o Doria, no rastro da entrada do vice Rodrigo Garcia, que deixou o DEM para ser o candidato tucano ao Pal\u00e1cio dos Bandeirantes.<\/p>\n<p>A Executiva confirmou decis\u00e3o do presidente da legenda, Bruno Ara\u00fajo (PE), que havia acolhido den\u00fancia de que o diret\u00f3rio de S\u00e3o Paulo havia alterado a data das filia\u00e7\u00f5es para que os prefeitos e vice aliados de Doria participassem das pr\u00e9vias. O ex-prefeito de Manaus Arthur Virg\u00edlio, que tamb\u00e9m concorre \u00e0s pr\u00e9vias, apoiou a decis\u00e3o da Executiva. O diret\u00f3rio estadual do PSDB em S\u00e3o Paulo negou as irregularidades. A den\u00fancia fora apresentada pelos diret\u00f3rios de Rio Grande do Sul, Bahia, Cear\u00e1 e Minas Gerais. Todos j\u00e1 declaram apoio a Leite.<\/p>\n<p>A decis\u00e3o acirra ainda mais a disputa no ninho tucano, que virou um jogo bruto nos bastidores e deve deixar muitas sequelas. Pelas regras das pr\u00e9vias, apenas filiados at\u00e9 o dia 31 de maio podem votar. De fato houve \u201cfilia\u00e7\u00e3o em bloco\u201d em S\u00e3o Paulo ap\u00f3s a data limite, mas as ades\u00f5es refletem inequivocamente o crescimento da legenda, em raz\u00e3o da entrada de Garcia no PSDB. Partid\u00e1rios de Doria alegam que as filia\u00e7\u00f5es foram anunciadas ap\u00f3s o prazo em raz\u00e3o do falecimento do ent\u00e3o prefeito de S\u00e3o Paulo Bruno Covas, cujo luto provocou 60 dias de interrup\u00e7\u00e3o de atividades partid\u00e1rias.<\/p>\n<p>Comum nos partidos Democrata e Republicano dos Estados Unidos, as pr\u00e9vias do PSDB s\u00e3o uma inova\u00e7\u00e3o decorrente da disputa instalada na c\u00fapula tucana pelo controle da legenda, desde as \u00faltimas elei\u00e7\u00f5es, principalmente entre o governador Jo\u00e3o Doria e o deputado A\u00e9cio Neves, ex-governador de Minas. Doria chegou a propor, sem sucesso, a expuls\u00e3o do pol\u00edtico mineiro. Entretanto, em dificuldades para alavancar sua candidatura eleitoralmente, confinado em S\u00e3o Paulo por causa da pandemia e com sua lideran\u00e7a muito confrontada por A\u00e9cio, o governador de S\u00e3o Paulo acabou desafiado por outras lideran\u00e7as, como o senador Tasso Jereissati, que desistiu da candidatura, e o governador Eduardo Leite, que cresceu muito junto aos setores descontentes.<\/p>\n<p><strong>As pr\u00e9vias<\/strong><\/p>\n<p>As pr\u00e9vias da legenda, desde sua convoca\u00e7\u00e3o, s\u00e3o pol\u00eamicas. Doria queria uma esp\u00e9cie de voto direto, secreto e universal entre os filiados, o que daria enorme vantagem ao diret\u00f3rio de S\u00e3o Paulo, o ber\u00e7o da legenda e sua fortaleza at\u00e9 hoje, mas a c\u00fapula tucana decidiu ponderar a rela\u00e7\u00e3o entre filiados e mandat\u00e1rios. Ser\u00e3o quatro grupos de votantes, todos com peso unit\u00e1rio de 25% do total de votos v\u00e1lidos: (1) filiados, (2) prefeitos e vice-prefeitos, (3) vereadores, deputados estaduais e distritais (deputados representam 50% do peso do grupo, e vereadores, os outros 50%); e (4) governadores, vice-governadores, ex-presidentes e o atual presidente da Comiss\u00e3o Executiva Nacional do PSDB, senadores e deputados federais. Mandat\u00e1rios poder\u00e3o votar\u00e3o presencialmente, em Bras\u00edlia, em urnas eletr\u00f4nicas; vereadores e filiados votar\u00e3o virtualmente, por aplicativo.<\/p>\n<p>A disputa no ninho tucano virou um jogo de xadrez, com resultado imprevis\u00edvel. A exclus\u00e3o dos 92 prefeitos e vice prefeitos pode, sim, alterar o resultado final. Eduardo Leite j\u00e1 est\u00e1 sendo apontado como favorito pela maioria dos l\u00edderes hist\u00f3ricos do PSDB. Qualquer que seja o resultado das pr\u00e9vias, a possibilidade de um racha no PSDB \u00e9 muito grande. O governador de S\u00e3o Paulo movimenta-se como um candidato sem retorno ao Pal\u00e1cio dos Bandeirantes, pelas alian\u00e7as que teceu em torno de Rodrigo Garcia. Se perder, sua linha de recuo para concorrer \u00e0 reelei\u00e7\u00e3o \u00e9 muito estreita, embora exista. No campo de Eduardo Leite, a pr\u00e9-disposi\u00e7\u00e3o para cristianizar Doria tamb\u00e9m \u00e9 grande, principalmente em Minas Gerais, na Bahia e no Cear\u00e1.<\/p>\n<p>Quem quer que seja o vencedor das pr\u00e9vias, internamente, ter\u00e1 que fazer um esfor\u00e7o muito grande para acomodar os descontentes, principalmente em n\u00edvel regional; em alguns casos, isso ser\u00e1 imposs\u00edvel. Externamente, o ganhador ter\u00e1 que fazer um movimento muito robusto para ampliar suas alian\u00e7as e criar um fato pol\u00edtico novo, o que n\u00e3o \u00e9 f\u00e1cil, haja vista que os poss\u00edveis aliados est\u00e3o lan\u00e7ando seus pr\u00f3prios candidatos e nenhum dos tucanos, at\u00e9 agora, decolou nas pesquisas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A disputa no ninho tucano virou um jogo de xadrez entre os l\u00edderes partid\u00e1rios. A exclus\u00e3o dos 92 prefeitos e vice-prefeitos da vota\u00e7\u00e3o pode alterar o resultado final A Executiva Nacional do PSDB decidiu, ontem, desconsiderar os votos de 92 prefeitos e vices de S\u00e3o Paulo recentemente filiados \u00e0 legenda nas pr\u00e9vias que v\u00e3o escolher o candidato do PSDB \u00e0 [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[980,972,8,3,9,323],"tags":[146,944,1052,325,748],"class_list":["post-6251","post","type-post","status-publish","format-standard","hentry","category-eleicoes-2","category-memoria","category-partidos","category-politica","category-politica-2","category-sao-paulo","tag-doria","tag-leite","tag-previas","tag-psdb","tag-virgilio"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/6251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/comments?post=6251"}],"version-history":[{"count":2,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/6251\/revisions"}],"predecessor-version":[{"id":6257,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/6251\/revisions\/6257"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/media?parent=6251"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/categories?post=6251"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/tags?post=6251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}