{"id":5958,"date":"2021-07-29T08:50:11","date_gmt":"2021-07-29T11:50:11","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/?p=5958"},"modified":"2021-07-29T09:40:03","modified_gmt":"2021-07-29T12:40:03","slug":"nas-entrelinhas-dualidade-de-politicas","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/nas-entrelinhas-dualidade-de-politicas\/","title":{"rendered":"Nas entrelinhas: Dualidade de pol\u00edticas"},"content":{"rendered":"<p><em><strong>Goebbels dizia que uma mentira repetida mil vezes vira verdade, o que parece ser uma m\u00e1xima da pol\u00edtica de comunica\u00e7\u00e3o de Bolsonaro nas redes sociais<\/strong><\/em><\/p>\n<p>Um epis\u00f3dio emblem\u00e1tico demonstra que o governo Bolsonaro passar\u00e1 a ter duas pol\u00edticas, que podem se antagonizar no decorrer do processo. No mesmo dia em que o novo ministro da Casa Civil, Ciro Nogueira (PP-PI), sentava na cadeira de ministro, a Secretaria de Comunica\u00e7\u00e3o da Presid\u00eancia divulgou nas redes sociais uma mensagem comemorativa do Dia do Agricultor, com uma foto de um homem armado com um rifle, em vez das tradicionais imagens de agricultores exibindo as m\u00e3os calejadas, suas ferramentas de trabalho ou mesmo um trator. Diante da repercuss\u00e3o negativa, a nota foi substitu\u00edda por uma tabela com indicadores de invas\u00f5es de terra.\u00a0Para bom entendedor, foi um recado subliminar de que a paz no campo seria obtida fazendo justi\u00e7a pelas pr\u00f3prias m\u00e3os.<\/p>\n<p>Sabe-se que Bolsonaro governa com um grupo de generais de sua confian\u00e7a \u2014 Luiz Ramos, transferido para a Secretaria-Geral da Presid\u00eancia; Augusto Heleno, ministro-chefe do Gabinete de Seguran\u00e7a Institucional (GSI); e o general Braga Netto, ministro da Defesa \u2014 e o cl\u00e3 formado com os filhos Fl\u00e1vio (senador), Eduardo (deputado federal) e Carlos (vereador), o verdadeiro respons\u00e1vel pela pol\u00edtica de comunica\u00e7\u00e3o do governo e operador das redes sociais de Bolsonaro. Foi dele, provavelmente, a ideia de publicar a foto. Como em outros momentos do governo, toda vez que Bolsonaro se afasta da narrativa de sua campanha eleitoral, como agora, ao empoderar o Centr\u00e3o no Pal\u00e1cio do Planalto, logo surge alguma coisa que sinaliza para a base bolsonarista que o presidente n\u00e3o abandonou seus compromissos de extrema-direita.<\/p>\n<p>Pol\u00edtico profissional habilidoso, Ciro Nogueira n\u00e3o \u00e9 ing\u00eanuo e sabe muito bem o que vai enfrentar na Casa Civil para mudar o eixo\u00a0de atua\u00e7\u00e3o do governo. Trata-se de abandonar a radicaliza\u00e7\u00e3o e o confronto com os demais Poderes e optar por uma pol\u00edtica de forma\u00e7\u00e3o de maioria no Congresso e reaproxima\u00e7\u00e3o com os eleitores que se afastaram de Bolsonaro, por causa do seu radicalismo e do mau desempenho do governo. Sua presen\u00e7a na Casa Civil n\u00e3o ter\u00e1 nenhum sentido se tudo continuar como antes. Bolsonaro at\u00e9 tentou retroceder do convite, mas n\u00e3o lhe foi poss\u00edvel, porque seria uma desfeita com Nogueira e o PP oferecer-lhe outra pasta de menor import\u00e2ncia. Pol\u00edticos profissionais n\u00e3o s\u00e3o como generais que aceitam ordem unida, tudo tem algum tipo de barganha.<\/p>\n<p>O novo ministro da Casa Civil, por\u00e9m, precisa fazer uma demonstra\u00e7\u00e3o de for\u00e7a pol\u00edtica. At\u00e9 agora, seu maior trunfo \u00e9 o apoio do presidente da C\u00e2mara, Arthur Lira (PP-AL). A oportunidade para isso ser\u00e1 a cerim\u00f4nia de posse no cargo, prevista para o pr\u00f3ximo dia 3, \u00e0 qual pretende convidar os velhos caciques do PP remanescentes da antiga Arena e do PDS, como Delfim Neto e Francisco Dorneles, e seus aliados dos demais partidos do Centr\u00e3o. Nos bastidores no Senado, o Pal\u00e1cio do Planalto tenta se reaproximar da maioria da bancada do MDB, que tem dois l\u00edderes de governo, o do Senado, Fernando Bezerra (PE), e o do Congresso, Eduardo Gomes (TO). A ideia \u00e9 for\u00e7ar uma reuni\u00e3o para desautorizar o l\u00edder, Eduardo Braga (AM), e o relator da CPI da Covid, senador Renan Calheiros (AL). N\u00e3o \u00e9 da tradi\u00e7\u00e3o da legenda confrontos dessa ordem, porque o MDB \u00e9 uma confedera\u00e7\u00e3o de caciques regionais, que convivem na diverg\u00eancia, uns na oposi\u00e7\u00e3o e outros na base do governo.<\/p>\n<p><strong>Verdades e mentiras<\/strong><br \/>\nA maior demonstra\u00e7\u00e3o de que h\u00e1 uma dualidade de pol\u00edticas no Pal\u00e1cio do Planalto foi dada pelo pr\u00f3prio presidente Bolsonaro, que voltou a responsabilizar o Supremo Tribunal Federal (STF) pela desastrosa atua\u00e7\u00e3o do Minist\u00e9rio da Sa\u00fade, ao afirmar que uma decis\u00e3o da Corte impediu que o governo combatesse a pandemia. A resposta do STF foi in\u00e9dita e pelas redes sociais, o que assinala uma mudan\u00e7a de postura.<\/p>\n<p>Seu presidente, ministro Luiz Fux, mandou divulgar um v\u00eddeo no qual parafraseou o chefe de propaganda do regime nazista de Adolf Hitler, Joseph Goebbels: \u201cUma mentira repetida mil vezes vira verdade? N\u00e3o. \u00c9 falso que o Supremo tenha tirado poderes do presidente da Rep\u00fablica de atuar na pandemia. \u00c9 verdadeiro que o STF decidiu que Uni\u00e3o, estados e prefeituras tinham que atuar juntos, com medidas para proteger a popula\u00e7\u00e3o. N\u00e3o espalhe fake news! Compartilhe as #Verdades- doSTF\u201d. Goebbels dizia que uma mentira repetida mil vezes vira verdade, o que parece ser uma m\u00e1xima da pol\u00edtica de comunica\u00e7\u00e3o de Bolsonaro nas redes sociais.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Goebbels dizia que uma mentira repetida mil vezes vira verdade, o que parece ser uma m\u00e1xima da pol\u00edtica de comunica\u00e7\u00e3o de Bolsonaro nas redes sociais Um epis\u00f3dio emblem\u00e1tico demonstra que o governo Bolsonaro passar\u00e1 a ter duas pol\u00edticas, que podem se antagonizar no decorrer do processo. No mesmo dia em que o novo ministro da Casa Civil, Ciro Nogueira (PP-PI), [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[677,6,980,371,4,7,113,8,9,3,71],"tags":[130,77,990,991,79],"class_list":["post-5958","post","type-post","status-publish","format-standard","hentry","category-comunicacao","category-congresso","category-eleicoes-2","category-etica","category-governo","category-justica","category-militares","category-partidos","category-politica-2","category-politica","category-saude","tag-bolsonaro","tag-congresso","tag-nogueira","tag-planalto","tag-supremo"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/5958","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/comments?post=5958"}],"version-history":[{"count":3,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/5958\/revisions"}],"predecessor-version":[{"id":5966,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/5958\/revisions\/5966"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/media?parent=5958"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/categories?post=5958"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/tags?post=5958"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}