{"id":4824,"date":"2020-06-19T07:54:48","date_gmt":"2020-06-19T10:54:48","guid":{"rendered":"http:\/\/blogs.correiobraziliense.com.br\/azedo\/?p=4824"},"modified":"2020-06-19T07:54:48","modified_gmt":"2020-06-19T10:54:48","slug":"colhendo-a-tempestade","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/colhendo-a-tempestade\/","title":{"rendered":"Colhendo a tempestade"},"content":{"rendered":"<p><em><strong>\u201cWeintraub \u00e9 o terceiro ministro que deixa o governo com proje\u00e7\u00e3o na base eleitoral de Bolsonaro. Mandetta, da Sa\u00fade, e Moro, da Justi\u00e7a, passaram \u00e0 oposi\u00e7\u00e3o\u201d<\/strong><\/em><\/p>\n<p>Nas circunst\u00e2ncias atuais, qualquer presidente da Rep\u00fablica j\u00e1 estaria diante de uma grande borrasca, em raz\u00e3o da pandemia de coranav\u00edrus e da recess\u00e3o econ\u00f4mica dela decorrente. Jair Bolsonaro, por\u00e9m, conseguiu transformar a crise sanit\u00e1ria e econ\u00f4mica numa tempestade perfeita, ao agregar \u00e0s conting\u00eancias ex\u00f3genas de seu governo uma crise pol\u00edtica multifacetada, que, ontem, resultou na sa\u00edda do pol\u00eamico ministro Abraham Weintraub, da Educa\u00e7\u00e3o. O 10\u00ba ministro a deixar o governo, o segundo da pasta, que agora virou objeto dos desejos dos partidos do Centr\u00e3o.<\/p>\n<p>A sa\u00edda do Weintraub \u2014 histri\u00f4nico, incompetente e politicamente trapalh\u00e3o \u2014, desde a semana passada, era pedra cantada. Para a turma do deixa disso, serviria para desanuviar as rela\u00e7\u00f5es do Pal\u00e1cio do Planalto com o Supremo Tribunal Federal (STF). Entretanto, foi eclipsada pela pris\u00e3o de Fabr\u00edcio Queiroz, amigo de Bolsonaro e ex-assessor parlamentar e motorista do seu filho, senador Fl\u00e1vio Bolsonaro (Republicanos-RJ), que estava escondido num s\u00edtio em Atibaia (SP). O caso Queiroz tira Bolsonaro do s\u00e9rio, pois o amigo e ex-assessor do filho \u00e9 um homem-bomba: al\u00e9m de suspeito de ser operador financeiro do cl\u00e3, \u00e9 pe\u00e7a-chave nas hist\u00f3ricas rela\u00e7\u00f5es do presidente com as mil\u00edcias do Rio de Janeiro.<\/p>\n<p>H\u00e1 tr\u00eas dias, Bolsonaro alterna momentos de apatia e grande irrita\u00e7\u00e3o. Com o apoio dos ministros militares do Pal\u00e1cio do Planalto, bateu de frente com o Supremo Tribunal Federal (STF) e tentou intimidar os ministros da Corte. Nesta semana, deu tudo errado: por 10 a 1, o Supremo resolveu dar prosseguimento ao inqu\u00e9rito das fake news presidido pelo ministro Alexandre de Moraes, que Bolsonaro considera um desafeto. O magistrado vem promovendo sucessivas a\u00e7\u00f5es contra os bolsonaristas radicais.<\/p>\n<p>Moraes determinou a pris\u00e3o da ativista Sara Winter e outros militantes do grupo autodenominado 300 do Brasil, que defendem uma interven\u00e7\u00e3o militar e realizavam protestos contra o Supremo e Congresso, com amea\u00e7as a magistrados e parlamentares. Tamb\u00e9m mandou realizar opera\u00e7\u00f5es de busca e apreens\u00e3o em resid\u00eancias e escrit\u00f3rios de empres\u00e1rios, blogueiros, dez deputados e um senador supostamente ligados ao chamado Gabinete do \u00d3dio, a m\u00e1quina de propaganda bolsonarista nas redes sociais.<\/p>\n<p>Bolsonaro est\u00e1 numa saia justa. N\u00e3o pode dobrar a aposta contra os demais Poderes sem provocar uma crise institucional sem precedentes desde a democratiza\u00e7\u00e3o. A pr\u00f3pria sa\u00edda de Weintraub havia se tornado imperativa, em raz\u00e3o de suas declara\u00e7\u00f5es contra o Supremo na reuni\u00e3o ministerial do dia 22 de abril, quando chamou os ministros da Corte de vagabundos e disse que eles deveriam ser presos. No domingo, a gota d\u2019\u00e1gua foi sua participa\u00e7\u00e3o numa manifesta\u00e7\u00e3o proibida na Esplanada, sem m\u00e1scara, o que lhe valeu uma multa de R$ 2 mil aplicada por ordem do governador do Distrito Federal, Ibaneis Rocha (MDB).<\/p>\n<p><b>Investiga\u00e7\u00f5es<\/b><br \/>\nO Pal\u00e1cio do Planalto temia a pris\u00e3o de Weintraub, a qualquer momento, por desafiar o STF. Ao mesmo tempo, o ministro se tornou refer\u00eancia para a ala ideol\u00f3gica do bolsonarismo, por causa dos ataques ao Supremo. Sua despedida do cargo, ontem, foi um constrangimento para Bolsonaro, que lhe ofereceu um cargo de diretor do Banco Mundial. \u00c9 o terceiro ministro importante que deixa o governo com proje\u00e7\u00e3o pol\u00edtica na base eleitoral de Bolsonaro. Os outros foram Luiz Henrique Mandetta, da Sa\u00fade, e Sergio Moro, da Justi\u00e7a, que passaram \u00e0 oposi\u00e7\u00e3o. N\u00e3o \u00e9 o caso de Weintraub, que ganhou um cargo no exterior como pr\u00eamio de consola\u00e7\u00e3o.<\/p>\n<p>Bolsonaro sentiu o golpe: \u201c\u00c9 um momento dif\u00edcil, todos meus compromissos de campanha continuam de p\u00e9 e busco implement\u00e1-los da melhor maneira poss\u00edvel. A confian\u00e7a voc\u00ea n\u00e3o compra, voc\u00ea adquire. Todos que est\u00e3o nos ouvindo, agora, s\u00e3o maiores de idade e sabem o que o Brasil est\u00e1 passando. O momento \u00e9 de confian\u00e7a. Jamais deixaremos de lutar por liberdade. Eu fa\u00e7o o que o povo quiser\u201d, disse Bolsonaro, na grava\u00e7\u00e3o da despedida de Weintraub.<\/p>\n<p>Agora, a dificuldade se chama Fabr\u00edcio Queiroz. Ex-assessor parlamentar de Fl\u00e1vio Bolsonaro na Assembleia Legislativa fluminense, \u00e9 apontado como operador de um esquema de rachadinha, que supostamente ocorria no gabinete do filho do presidente da Rep\u00fablica, quando era deputado estadual no Rio. O policial militar reformado foi preso em um im\u00f3vel do advogado Frederick Wassef, que atua na defesa de Fl\u00e1vio, mas n\u00e3o \u00e9 advogado de Queiroz, acusado de manipular provas e pressionar testemunhas, pelos procuradores do Rio de Janeiro que investigam o caso. O Pal\u00e1cio do Planalto tenta se desvincular, mas o fato de Queiroz ter se escondido numa propriedade do advogado de Fl\u00e1vio, mesmo que isso n\u00e3o seja crime, cria um tremendo problema pol\u00edtico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cWeintraub \u00e9 o terceiro ministro que deixa o governo com proje\u00e7\u00e3o na base eleitoral de Bolsonaro. Mandetta, da Sa\u00fade, e Moro, da Justi\u00e7a, passaram \u00e0 oposi\u00e7\u00e3o\u201d Nas circunst\u00e2ncias atuais, qualquer presidente da Rep\u00fablica j\u00e1 estaria diante de uma grande borrasca, em raz\u00e3o da pandemia de coranav\u00edrus e da recess\u00e3o econ\u00f4mica dela decorrente. Jair Bolsonaro, por\u00e9m, conseguiu transformar a crise sanit\u00e1ria [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38,371,4,7,9,3],"tags":[130,296,719,79,368,731],"class_list":["post-4824","post","type-post","status-publish","format-standard","hentry","category-educacao","category-etica","category-governo","category-justica","category-politica-2","category-politica","tag-bolsonaro","tag-queiroz","tag-rachadinhas","tag-supremo","tag-weintraub","tag-weiuntraub"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/4824","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/comments?post=4824"}],"version-history":[{"count":0,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/4824\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/media?parent=4824"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/categories?post=4824"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/tags?post=4824"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}