{"id":4707,"date":"2020-04-08T07:07:18","date_gmt":"2020-04-08T10:07:18","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/?p=4707"},"modified":"2020-04-08T07:07:18","modified_gmt":"2020-04-08T10:07:18","slug":"nas-entrelinhas-eleicoes-na-berlinda","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/nas-entrelinhas-eleicoes-na-berlinda\/","title":{"rendered":"Nas entrelinhas: Elei\u00e7\u00f5es na berlinda"},"content":{"rendered":"<p><em><strong>\u201cA epidemia n\u00e3o impediu a montagem de chapas de vereadores nem as pr\u00e9-candidaturas a prefeito, mas muita gente torce pelo adiamento do pleito\u201d<\/strong><\/em><\/p>\n<p>Se antecipando ao Tribunal Superior Eleitoral (TSE), o juiz federal Itagiba Catta Preta Neto, da 4\u00aa Vara C\u00edvel da Justi\u00e7a Federal em Bras\u00edlia, detonou, ontem, as elei\u00e7\u00f5es municipais deste ano, para escolha de prefeitos e de vereadores, ao determinar o bloqueio dos recursos do fundo partid\u00e1rio (dinheiro destinado aos partidos pol\u00edticos) e do fundo eleitoral (para custear campanhas eleitorais). Decidiu que os recursos ficar\u00e3o \u00e0 disposi\u00e7\u00e3o do governo federal para serem usados em medidas de combate ao coronav\u00edrus ou em a\u00e7\u00f5es contra os seus reflexos econ\u00f4micos, inviabilizando o funcionamento dos partidos e suas campanhas eleitorais. Ontem, o Brasil atingiu 14.018 casos confirmados do novo coronav\u00edrus, com 686 mortes.<\/p>\n<p>\u201cOs valores podem, contudo, a crit\u00e9rio do Chefe do Poder Executivo, ser usados em favor de campanhas para o combate \u00e0 Pandemia de Coronav\u00edrus \u2014 Covid-19, ou para amenizar suas consequ\u00eancias econ\u00f4micas\u201d, determinou o magistrado, que acolheu a\u00e7\u00e3o popular impetrada por um advogado paulista. Com R$ 959 milh\u00f5es, o fundo partid\u00e1rio \u00e9 usado para permitir o funcionamento das legendas. O fundo de financiamento de campanhas acumula R$ 2,034 bilh\u00f5es, dinheiro que estava destinado \u00e0s campanhas das elei\u00e7\u00f5es municipais de outubro.<\/p>\n<p>A senten\u00e7a, em tom de manifesto, soa como m\u00fasica para aquela parcela da opini\u00e3o p\u00fablica que odeia os pol\u00edticos: \u201cDos sacrif\u00edcios que se exigem de toda a Na\u00e7\u00e3o, n\u00e3o podem ser poupados apenas alguns, justamente os mais poderosos, que controlam, inclusive, o or\u00e7amento da Uni\u00e3o\u201d, argumentou o juiz federal. Segundo ele, a manuten\u00e7\u00e3o dos fundos \u201cse afigura contr\u00e1ria \u00e0 moralidade p\u00fablica\u201d, \u201caos princ\u00edpios da dignidade da pessoa humana, dos valores sociais do trabalho e da livre iniciativa\u201d e, ainda, \u201cao prop\u00f3sito de constru\u00e7\u00e3o de uma sociedade solid\u00e1ria\u201d.<\/p>\n<p>Nos bastidores do Congresso, que vota medidas de emerg\u00eancia para evitar que os trabalhadores informais fiquem sem nenhuma fonte de renda e para garantir a sobreviv\u00eancia das empresas, tamb\u00e9m se discute o adiamento das elei\u00e7\u00f5es, em raz\u00e3o da epidemia. At\u00e9 agora, o calend\u00e1rio eleitoral foi mantido pelo Tribunal Superior Eleitoral (TSE). A epidemia n\u00e3o impediu a montagem de chapas de vereadores nem as pr\u00e9-candidaturas a prefeito, com intensa troca de partidos e novas filia\u00e7\u00f5es, at\u00e9 o \u00faltimo domingo, mas muita gente torce pelo adiamento.<\/p>\n<p><strong>Calend\u00e1rio<\/strong><br \/>\nSempre houve no Congresso quem defendesse a coincid\u00eancia das elei\u00e7\u00f5es, acenando com uma prorroga\u00e7\u00e3o de mandato por mais dois anos para prefeitos e vereadores. Essa ideia, por\u00e9m, vem sendo rejeitada. Mexer na dura\u00e7\u00e3o dos mandatos \u00e9 considerado um precedente perigoso para a democracia, em qualquer hip\u00f3tese, quando nada porque a hist\u00f3ria do Brasil associa essas mudan\u00e7as a rupturas institucionais. Entretanto, a epidemia de coronav\u00edrus realmente coincidir\u00e1 com o processo eleitoral.<\/p>\n<p>As elei\u00e7\u00f5es municipais s\u00f3 ocorrer\u00e3o em outubro, mas a contagem regressiva est\u00e1 em pleno curso. Para os eleitores, 6 de maio \u00e9 o \u00faltimo dia para que regularizem a sua situa\u00e7\u00e3o junto \u00e0 Justi\u00e7a Eleitoral. Pessoas que perderam o recadastramento biom\u00e9trico e tiveram o t\u00edtulo cancelado, que n\u00e3o justificaram a aus\u00eancia nas \u00faltimas elei\u00e7\u00f5es ou desejem alterar o domic\u00edlio eleitoral t\u00eam at\u00e9 esse dia para resolver suas pend\u00eancias nos cart\u00f3rios eleitorais.<\/p>\n<p>Em 15 de maio, come\u00e7a a arrecada\u00e7\u00e3o facultativa de doa\u00e7\u00f5es por pr\u00e9-candidatos aos cargos de prefeito e vereador. Pr\u00e9-candidatos que apresentem programas de r\u00e1dio ou televis\u00e3o ficam proibidos de faz\u00ea-los a partir de 30 de junho. A partir de 4 de julho, est\u00e3o proibidas nomea\u00e7\u00f5es, exonera\u00e7\u00f5es e contrata\u00e7\u00f5es, assim como transfer\u00eancias de recursos, entre outras, ou seja, a administra\u00e7\u00e3o p\u00fablica \u00e9 engessada. As conven\u00e7\u00f5es partid\u00e1rias para a escolha dos candidatos dever\u00e3o ser realizadas de 20 de julho a 5 de agosto.<\/p>\n<p>Segundo o calend\u00e1rio epidemiol\u00f3gico, nesse per\u00edodo, a epidemia estar\u00e1 ultrapassado o seu \u00e1pice, mas isso \u00e9 apenas uma proje\u00e7\u00e3o estat\u00edstica. Os registros de candidaturas devem ser protocolados na Justi\u00e7a Eleitoral antes da meia-noite de 14 de agosto. Em 16 de agosto, come\u00e7a a propaganda eleitoral, inclusive na internet. O hor\u00e1rio eleitoral gratuito no r\u00e1dio e na televis\u00e3o ser\u00e1 veiculado de 28 de agosto a 1\u00ba de outubro. O primeiro turno de vota\u00e7\u00e3o est\u00e1 previsto para 4 de outubro; o segundo turno, para a elei\u00e7\u00e3o de prefeitos em munic\u00edpios com mais de 200 mil eleitores, ocorrer\u00e1 no dia 25 do mesmo m\u00eas.<\/p>\n<p>Hoje, as elei\u00e7\u00f5es n\u00e3o poderiam ser realizadas na maioria das capitais, sobretudo S\u00e3o Paulo, Rio de Janeiro, Fortaleza, Recife, Manaus e Florian\u00f3polis, e alguns grandes cidades. Na maioria dos munic\u00edpios, n\u00e3o haveria maiores dificuldades. Entretanto, n\u00e3o se sabe o que acontecer\u00e1 at\u00e9 outubro. Na epidemia da \u201cgripe espanhola\u201d, que matou milhares de pessoas no Rio de Janeiro em 1918, somente 5 mil dos 36 mil eleitores compareceram \u00e0s urnas em novembro daquele ano, na elei\u00e7\u00e3o para o Senado. Em mar\u00e7o, na elei\u00e7\u00e3o presidencial, 22 mil haviam votado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cA epidemia n\u00e3o impediu a montagem de chapas de vereadores nem as pr\u00e9-candidaturas a prefeito, mas muita gente torce pelo adiamento do pleito\u201d Se antecipando ao Tribunal Superior Eleitoral (TSE), o juiz federal Itagiba Catta Preta Neto, da 4\u00aa Vara C\u00edvel da Justi\u00e7a Federal em Bras\u00edlia, detonou, ontem, as elei\u00e7\u00f5es municipais deste ano, para escolha de prefeitos e de vereadores, [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[176,6,46,7,8,3],"tags":[705,645,459,528,342],"class_list":["post-4707","post","type-post","status-publish","format-standard","hentry","category-cidades","category-congresso","category-eleicoes","category-justica","category-partidos","category-politica","tag-candidatos","tag-coronavirus","tag-eleicoes2020","tag-fundos","tag-justica"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/4707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/comments?post=4707"}],"version-history":[{"count":2,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/4707\/revisions"}],"predecessor-version":[{"id":4713,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/4707\/revisions\/4713"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/media?parent=4707"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/categories?post=4707"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/tags?post=4707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}