{"id":4570,"date":"2020-02-20T08:44:14","date_gmt":"2020-02-20T11:44:14","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/?p=4570"},"modified":"2020-02-20T08:44:14","modified_gmt":"2020-02-20T11:44:14","slug":"nas-entrelinhas-como-comeca-a-bagunca","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/nas-entrelinhas-como-comeca-a-bagunca\/","title":{"rendered":"Nas entrelinhas: Como come\u00e7a a bagun\u00e7a"},"content":{"rendered":"<p><em><strong>\u201cAs declara\u00e7\u00f5es do general Heleno nos trazem \u00e0 mem\u00f3ria as \u201cquarteladas\u201d que caracterizaram a indisciplina nos quart\u00e9is e a presen\u00e7a dos militares na pol\u00edtica\u201c\u00a0<\/strong><\/em><\/p>\n<p>O que t\u00eam a ver as declara\u00e7\u00f5es contra o Congresso do general Augusto Heleno, ministro-chefe do Gabinete de Seguran\u00e7a Institucional, e o tiro disparado por policiais militares grevistas, encapuzados, contra o senador Cid Gomes (PDT-CE), em Sobral? Aparentemente, nada; em sua ess\u00eancia, por\u00e9m, tudo: a bagun\u00e7a. O ex-governador cearense tentou negociar e, depois, conduzindo uma retroescavadeira, enfrentou os grevistas de forma exaltada, imprudente e voluntarista, sendo baleado no peito e na clav\u00edcula. O epis\u00f3dio, no entanto, tamb\u00e9m \u00e9 uma demonstra\u00e7\u00e3o da anarquia que come\u00e7a a vicejar nas pol\u00edcias militares, pois as greves s\u00e3o ilegais e est\u00e3o sendo preparadas em outros estados.<\/p>\n<p>As declara\u00e7\u00f5es do general s\u00e3o incompat\u00edveis com o cargo que ocupa no governo e nos trazem \u00e0 mem\u00f3ria as \u201cquarteladas\u201d que caracterizaram a indisciplina nos quart\u00e9is e a presen\u00e7a dos militares na pol\u00edtica durante o s\u00e9culo passado, inclusive durante o regime militar, s\u00f3 encerradas no governo Ernesto Geisel, com a demiss\u00e3o do ent\u00e3o ministro do Ex\u00e9rcito, general S\u00edlvio Frota, do qual Augusto Heleno foi ajudante de ordens. Ainda que minimizadas pelo presidente Jair Bolsonaro \u2014 diga-se de passagem, o respons\u00e1vel pela sua divulga\u00e7\u00e3o \u2014, as declara\u00e7\u00f5es afrontam um poder constitu\u00eddo, que est\u00e1 no pleno exerc\u00edcio de suas prerrogativas.<\/p>\n<p>A fala do ministro foi transmitida ao vivo, via internet, pelo perfil do presidente Jair Bolsonaro em uma rede social, na ter\u00e7a-feira. No evento de hasteamento da bandeira em frente ao Pal\u00e1cio da Alvorada, Heleno conversava com o ministro da Economia, Paulo Guedes, e com o ministro da Secretaria de Governo, Luiz Eduardo Ramos. No di\u00e1logo, disse que o governo n\u00e3o pode \u201caceitar esses caras chantagearem a gente o tempo todo\u201d. Ontem, em uma rede social, Heleno tentou minimizar as declara\u00e7\u00f5es, mas a emenda foi pior do que o soneto: argumentou que, na conversa com os ministros, estava expondo sua vis\u00e3o pessoal sobre \u201cinsaci\u00e1veis reivindica\u00e7\u00f5es de alguns parlamentares por fatias do Or\u00e7amento Impositivo\u201d.<\/p>\n<p>As declara\u00e7\u00f5es provocaram rea\u00e7\u00f5es no Congresso, que discute os vetos do presidente Bolsonaro \u00e0s regras que d\u00e3o a deputados e senadores maior controle sobre o Or\u00e7amento da Uni\u00e3o. Manter ou derrubar os vetos presidenciais \u00e9 prerrogativa do parlamento. O que todos os governos democr\u00e1ticos procuram fazer \u00e9 articular uma base s\u00f3lida, que garanta a aprova\u00e7\u00e3o do que interessa ao Executivo. O Pal\u00e1cio do Planalto, por\u00e9m, n\u00e3o se empenha muito para garantir que isso aconte\u00e7a.<\/p>\n<p><strong>Rea\u00e7\u00f5es<\/strong><br \/>\nA rea\u00e7\u00e3o mais forte foi do presidente da C\u00e2mara, Rodrigo Maia (DEM-RJ), que fez duras cr\u00edticas ao general: \u201cGeralmente na vida, quando a gente vai ficando mais velho, a gente vai ganhando equil\u00edbrio, experi\u00eancia e paci\u00eancia. O ministro, pelo jeito, est\u00e1 ficando mais velho e est\u00e1 falando como um jovem estudante no auge da sua idade, da sua juventude\u201d, disse. Maia tamb\u00e9m ironizou: \u201cEu n\u00e3o ouvi da parte dele nenhum tipo de ataque ao parlamento quando a gente estava votando o aumento do sal\u00e1rio dele como militar da reserva (&#8230;) Talvez ele estivesse melhor em um gabinete de rede social, tuitando, agredindo, como muitos fazem, como ele tem feito ao parlamento nos \u00faltimos meses\u201d, concluiu o presidente da C\u00e2mara.<\/p>\n<p>O presidente do Senado, Davi Alcolumbre (DEM-AP), tamb\u00e9m se manifestou sobre a fala de Heleno. Em nota, disse que \u201cnenhum ataque \u00e0 democracia ser\u00e1 tolerado pelo parlamento\u201d e que \u201co momento, mais do que nunca, \u00e9 de defesa da democracia, independ\u00eancia e harmonia dos poderes para trabalhar pelo pa\u00eds\u201d. Contra todas as expectativas, \u00e0s v\u00e9speras do carnaval, o esgar\u00e7amento das rela\u00e7\u00f5es do Pal\u00e1cio do Planalto com o Congresso aumenta as incertezas em rela\u00e7\u00e3o \u00e0 economia.<\/p>\n<p>Um coment\u00e1rio do presidente da Rep\u00fablica, em cerim\u00f4nia oficial, sobre o ministro da Economia, Paulo Guedes, gerou ainda mais inseguran\u00e7a no mercado, pois deixou no ar que Guedes estaria demission\u00e1rio do cargo e sofre uma fritura interna. Seu prazo de validade estaria pr\u00f3ximo do fim. O que alimenta essas especula\u00e7\u00f5es \u00e9 o vai-n\u00e3o-vai da economia, cujo crescimento est\u00e1 sendo med\u00edocre, apesar dos juros baixos e da infla\u00e7\u00e3o controlada.<\/p>\n<p>O IBC-BR, \u00edndice do Banco Central, aponta alta de 0,5% no \u00faltimo trimestre do ano e de 0,9% no ano de 2019. Em 2018, quando o PIB teve alta de 1,3%, o IBC-BR tamb\u00e9m subiu 1,3%: se o padr\u00e3o se repetir, o que n\u00e3o \u00e9 garantido, o PIB em 2019 ter\u00e1 tido pior desempenho que no bi\u00eanio 2017-18. Nesse ritmo, s\u00f3 em 2022 voltaremos ao PIB de 2014. Levar oito anos para completar a recupera\u00e7\u00e3o de uma recess\u00e3o em qualquer \u00e9poca e em qualquer lugar \u00e9 um fracasso.<\/p>\n<p>Essa situa\u00e7\u00e3o tem ampliado os questionamentos \u00e0 pol\u00edtica de Guedes, um ultraliberal, por parte de setores do governo que t\u00eam forma\u00e7\u00e3o desenvolvimentista, entre os quais, os militares. O pr\u00f3prio Bolsonaro \u00e9 um rec\u00e9m-convertido ao liberalismo e vem adotando postura cada vez mais populista, como no caso dos combust\u00edveis e da reforma administrativa, e n\u00e3o perde oportunidade de abrir novas frentes de conflito, como a queda de bra\u00e7o com os governadores.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cAs declara\u00e7\u00f5es do general Heleno nos trazem \u00e0 mem\u00f3ria as \u201cquarteladas\u201d que caracterizaram a indisciplina nos quart\u00e9is e a presen\u00e7a dos militares na pol\u00edtica\u201c\u00a0 O que t\u00eam a ver as declara\u00e7\u00f5es contra o Congresso do general Augusto Heleno, ministro-chefe do Gabinete de Seguran\u00e7a Institucional, e o tiro disparado por policiais militares grevistas, encapuzados, contra o senador Cid Gomes (PDT-CE), em [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,36,4,113,3,9,80,68],"tags":[307,671,77,252,154,274,151,374],"class_list":["post-4570","post","type-post","status-publish","format-standard","hentry","category-congresso","category-economia","category-governo","category-militares","category-politica","category-politica-2","category-seguranca","category-violencia","tag-alcolumbre","tag-cid","tag-congresso","tag-governo","tag-greve","tag-heleno","tag-maia","tag-orcamento"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/4570","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/comments?post=4570"}],"version-history":[{"count":2,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/4570\/revisions"}],"predecessor-version":[{"id":4576,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/4570\/revisions\/4576"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/media?parent=4570"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/categories?post=4570"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/tags?post=4570"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}