{"id":4552,"date":"2020-02-14T07:22:09","date_gmt":"2020-02-14T10:22:09","guid":{"rendered":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/?p=4552"},"modified":"2020-02-14T07:22:09","modified_gmt":"2020-02-14T10:22:09","slug":"nas-entrelinhas-o-outro-lado-da-praca","status":"publish","type":"post","link":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/nas-entrelinhas-o-outro-lado-da-praca\/","title":{"rendered":"Nas entrelinhas: O outro lado da pra\u00e7a"},"content":{"rendered":"<p><em><strong>&#8220;Com o deslocamento da ala mais ideol\u00f3gica do centro do poder, o Pal\u00e1cio do Planalto deve ganhar mais coordena\u00e7\u00e3o e efici\u00eancia, por\u00e9m, refor\u00e7a seu distanciamento do campo pol\u00edtico\u201d<\/strong><\/em><\/p>\n<p>A confirma\u00e7\u00e3o da nomea\u00e7\u00e3o do general Braga Netto como novo ministro da Casa Civil, com o deslocamento do deputado Onyx Lorenzoni (DEM-RS) dessa pasta para o Minist\u00e9rio da Cidadania, refor\u00e7a o vi\u00e9s bonapartista do governo Bolsonaro, o que n\u00e3o significa que esse seja o car\u00e1ter do regime pol\u00edtico brasileiro. Como se sabe, o bonapartismo se caracteriza pela centraliza\u00e7\u00e3o do poder na figura de um l\u00edder populista que se coloca acima das classes sociais e procura se legitimar atrav\u00e9s da comunica\u00e7\u00e3o direta com as massas. Estamos longe, por\u00e9m, de um regime autorit\u00e1rio e militarista, porque o Brasil \u00e9 uma democracia de massas, na qual o Congresso e o Judici\u00e1rio t\u00eam grande protagonismo.<\/p>\n<p>A mudan\u00e7a no Pal\u00e1cio dos Planalto completa uma troca de guarda: saiu a tropa de assalto e entrou a de ocupa\u00e7\u00e3o. Os militares que dar\u00e3o as cartas no Pal\u00e1cio do Planalto \u2014 al\u00e9m do general Braga Netto, o ministro da Secretaria de Governo, Luiz Eduardo Ramos, e o ministro da Defesa, Fernando Azevedo e Silva \u2014 sempre trabalharam juntos e s\u00e3o mais novos e bem mais moderados do que o general Augusto Heleno, chefe do Gabinete de Seguran\u00e7a Institucional, que j\u00e1 n\u00e3o tem a mesma ascend\u00eancia sobre Bolsonaro do come\u00e7o do governo.<\/p>\n<p>Em termos de imagem, a ida de mais um general para o Planalto agrega ao governo valores identificados pela opini\u00e3o p\u00fablica como atributos positivos dos militares, como austeridade, compet\u00eancia e patriotismo. Com o deslocamento da ala mais ideol\u00f3gica do governo do centro do poder, o Pal\u00e1cio do Planalto deve ganhar mais coordena\u00e7\u00e3o e efici\u00eancia, por\u00e9m, refor\u00e7a seu distanciamento do campo pol\u00edtico propriamente dito.<\/p>\n<p>Entretanto, as pesquisas de opini\u00e3o est\u00e3o mostrando que a estrat\u00e9gia de Bolsonaro de manter a polariza\u00e7\u00e3o com a esquerda, ignorar a imprensa e manter dist\u00e2ncia dos pol\u00edticos est\u00e1 dando resultados positivos em termos eleitorais. O presidente da Rep\u00fablica mant\u00e9m grande vantagem em rela\u00e7\u00e3o aos seus principais advers\u00e1rios nas pesquisas, como candidato \u00e0 reelei\u00e7\u00e3o, enquanto o governo, que sofre desgastes por causa de suas crises, recupera pontos na aprova\u00e7\u00e3o. Manter-se como um pol\u00edtico antissistema n\u00e3o deixa de ser uma proeza de Bolsonaro, j\u00e1 que est\u00e1 no v\u00e9rtice do pr\u00f3prio sistema.<\/p>\n<p>O outro lado dessa moeda, por\u00e9m, \u00e9 o fortalecimento do Congresso como poder pol\u00edtico. A postura avessa \u00e0s articula\u00e7\u00f5es pol\u00edticas de Bolsonaro levou de volta ao Congresso a negocia\u00e7\u00e3o dos interesses da sociedade e a lideran\u00e7a das reformas. O presidente da Rep\u00fablica j\u00e1 deu demonstra\u00e7\u00f5es de que sua agenda priorit\u00e1ria \u00e9 a dos costumes e de combate aos movimentos identit\u00e1rios, n\u00e3o s\u00f3 com declara\u00e7\u00f5es, mas com atos administrativos. Mas essa pauta n\u00e3o prospera no Congresso, muito menos no Judici\u00e1rio.<\/p>\n<p><b>Disneyl\u00e2ndia<\/b><br \/>\nBolsonaro tamb\u00e9m n\u00e3o se entusiasma com as propostas de reformas que podem causar desgastes com os setores que o apoiam, como policiais, caminhoneiros e evang\u00e9licos. O ministro da Economia, Paulo Guedes, que lidera as reformas econ\u00f4micas no governo, tamb\u00e9m n\u00e3o ajuda muito, por causa de declara\u00e7\u00f5es bomb\u00e1sticas, como comparar os servidores p\u00fablicos a parasitas. A \u00faltima de Guedes foi um coment\u00e1rio desastroso sobre o c\u00e2mbio, que revelou grande preconceito em rela\u00e7\u00e3o aos mais pobres.<\/p>\n<p>\u201cN\u00e3o tem neg\u00f3cio de c\u00e2mbio a R$ 1,80. Vou exportar menos, substitui\u00e7\u00e3o de importa\u00e7\u00f5es, turismo, todo mundo indo para a Disneyl\u00e2ndia. Empregada dom\u00e9stica indo pra Disneyl\u00e2ndia, uma festa danada. Mas espera a\u00ed? Espera a\u00ed. Vai passear ali em Foz do Igua\u00e7u, vai ali passear nas praias do Nordeste, est\u00e1 cheio de praia bonita. Vai para Cachoeiro do Itapemirim, vai conhecer onde o Roberto Carlos nasceu. Vai passear no Brasil, vai conhecer o Brasil, que est\u00e1 cheio de coisa bonita para ver\u201d, disse.<\/p>\n<p>Com essas e outras, o fato \u00e9 que o Congresso ganha cada vez mais protagonismo, porque os pol\u00edticos sabem agarrar as oportunidades com as duas m\u00e3os e resolveram assumir como bandeiras as reformas da economia, principalmente o presidente da C\u00e2mara, Rodrigo Maia (DEM-RJ). V\u00e3o matar no peito a reforma tribut\u00e1ria e a reforma administrativa, das quais o governo j\u00e1 abriu m\u00e3o. A ironia, por\u00e9m, \u00e9 que o grande benefici\u00e1rio das reformas, em termos eleitorais, ser\u00e1 Bolsonaro. Enquanto o Congresso arcar\u00e1 com o desgaste das maldades, o presidente da Rep\u00fablica colher\u00e1 os louros dos seus benef\u00edcios para a economia. Mas \u00e9 do jogo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Com o deslocamento da ala mais ideol\u00f3gica do centro do poder, o Pal\u00e1cio do Planalto deve ganhar mais coordena\u00e7\u00e3o e efici\u00eancia, por\u00e9m, refor\u00e7a seu distanciamento do campo pol\u00edtico\u201d A confirma\u00e7\u00e3o da nomea\u00e7\u00e3o do general Braga Netto como novo ministro da Casa Civil, com o deslocamento do deputado Onyx Lorenzoni (DEM-RS) dessa pasta para o Minist\u00e9rio da Cidadania, refor\u00e7a o vi\u00e9s [&hellip;]<\/p>\n","protected":false},"author":39,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,36,46,4,113,3],"tags":[130,77,243,151,114,90],"class_list":["post-4552","post","type-post","status-publish","format-standard","hentry","category-congresso","category-economia","category-eleicoes","category-governo","category-militares","category-politica","tag-bolsonaro","tag-congresso","tag-guedes","tag-maia","tag-militares","tag-reformas"],"_links":{"self":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/4552","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/comments?post=4552"}],"version-history":[{"count":2,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/4552\/revisions"}],"predecessor-version":[{"id":4558,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/posts\/4552\/revisions\/4558"}],"wp:attachment":[{"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/media?parent=4552"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/categories?post=4552"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correiobraziliense.com.br\/azedo\/wp-json\/wp\/v2\/tags?post=4552"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}